{"id":112187,"date":"2013-10-18T08:48:20","date_gmt":"2013-10-18T08:48:20","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/10\/fw-sl-kommunalseminar-kreisfeuerwehrverband-schleswig-flensburg-474\/"},"modified":"2013-10-18T08:48:20","modified_gmt":"2013-10-18T08:48:20","slug":"fw-sl-kommunalseminar-kreisfeuerwehrverband-schleswig-flensburg-474","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-sl-kommunalseminar-kreisfeuerwehrverband-schleswig-flensburg-474\/","title":{"rendered":"FW-SL: Kommunalseminar Kreisfeuerwehrverband Schleswig-Flensburg"},"content":{"rendered":"<p>Schleswig (ots) &#8211; Kommunale Politik und Feuerwehr &#8211; Gemeinsam f\u00fcr  die Sicherheit der B\u00fcrgerund B\u00fcrgerinnen Am Samstag, dem 26.Oktober  2013 von 09:00 Uhr &#8211; 15:00 Uhr, findet ein Seminar des  Kreisfeuerwehrbandes Schleswig-Flensburg in der St. J\u00fcrgener Stra\u00dfe  61, 24837 Schleswig mit dem Themenkomplex Feuerwehr und  Kommunalpolitik statt.<!--more--> Die Zukunft der Freiwilligen Feuerwehren im  Wandel der Zeit, mit allen Herausforderungen der heutigen Zeit und  der Zukunft, im Zusammenspiel mit den kommunalen politischen  Entscheidungstr\u00e4gern und Entscheidungstr\u00e4gerinnen und F\u00fchrungskr\u00e4ften der Feuerwehren, steht im Focus dieses Seminars Die Organisation,  Aufgaben und die Struktur von Feuerwehren, die organisatorische  Begleitung durch den Kreisfeuerwehrverband, Besonderheiten im  Feuerwehrwesen und die Verbindung zur Kommunalpolitik sind Eckpunkte  des Seminars, vorgestellt durch verschiede Referenten. Eine aktive  Diskussionsrunde der Seminarteilnehmer und Seminarteilnehmerinnen mit Referenten und Referentinnen aus verschiedenen Bereichen des  Feuerwehrlebens und Kommunalpolitikern, die selber aktiv in der  Feuerwehr mitwirken, sind ein weiter Kernpunkt des Seminars.  Abgerundet wird das Seminar durch einsatznahe, praktische  Demonstrationen der t\u00e4glichen Feuerwehrarbeit. Sie sind herzlich  eingeladen, sich bei dem Seminar ein Bild \u00fcber die Arbeit, die Ideen  und die Zukunft der Freiwilligen Feuerweheren im Kreis  Schleswig-Flensburg zu machen.     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Schleswig-Flensburg Klaus Uck Telefon: 04621 24601<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/68035\/2578645\/fw-sl-kommunalseminar-kreisfeuerwehrverband-schleswig-flensburg\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schleswig (ots) &#8211; Kommunale Politik und Feuerwehr &#8211; Gemeinsam f\u00fcr die Sicherheit der B\u00fcrgerund B\u00fcrgerinnen Am Samstag, dem 26.Oktober 2013<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-112187","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/112187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=112187"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/112187\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=112187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=112187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=112187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}