{"id":112504,"date":"2013-10-04T13:23:46","date_gmt":"2013-10-04T13:23:46","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/10\/fw-oh-oh-riepsdorf-ortsteil-thomsdorfreetdachhaus-niedergebrannt-557\/"},"modified":"2013-10-04T13:23:46","modified_gmt":"2013-10-04T13:23:46","slug":"fw-oh-oh-riepsdorf-ortsteil-thomsdorfreetdachhaus-niedergebrannt-557","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-oh-riepsdorf-ortsteil-thomsdorfreetdachhaus-niedergebrannt-557\/","title":{"rendered":"FW-OH: OH- Riepsdorf- Ortsteil Thomsdorf\nReetdachhaus niedergebrannt"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Foto: Hartmut Junge\" src=\"http:\/\/www.presseportal.de\/bild\/262188-preview-pressemitteilung-dsc09685.jpg\" \/><\/p>\n<p>Lensahn (ots) &#8211; Am Mittwochabend (02.10.) entdeckten Passanten um  kurz vor 20.00 Uhr  ein Feuer auf dem Dach einer Reetkate. Als die  Feuerwehr wenige Minuten sp\u00e4ter an der Einsatzstelle eintraf brannte  das Reetdach schon in voller Ausdehnung. Da sich um das Brandobjekt  herum weitere Reetdachh\u00e4user befinden, hat die Einsatzleitung sofort  weitere Wehren nachalarmieren lassen.<!--more--> Insgesamt waren elf Feuerwehren mit insgesamt 174 Einsatzkr\u00e4ften vor Ort. Durch einen massiven  L\u00f6schangriff, unter anderem mittels zweier Drehleitern, gelang es das Feuer trotz des stark b\u00f6igen Windes einzud\u00e4mmen. Nach zwei Stunden  war das Feuer unter Kontrolle. Weitere Geb\u00e4ude wurden nicht in  Mitleidenschaft gezogen. Der Bewohner des Hauses befand sich zum  Zeitpunkt des Brandausbruches nicht im Haus. Er traf erst im Verlauf  der L\u00f6scharbeiten an der Einsatzstelle ein.     F\u00fcr die L\u00f6scharbeiten wurden die freiwilligen Feuerwehren  Altratjensdorf, Ripsdorf, Koselau, Lensahn, Damlos, Guttau, Grube,  Dahme, Kellenhusen, Gr\u00f6mitz und Oldenburg alarmiert. Ausserdem war  die Technische Einsatzleitung des Kreises Ostholstein mit einem  Einsatzleitfahrzeug zur Unterst\u00fctzung der \u00f6rtlichen Einsatzleitung  vor Ort. Gegen Mitternacht meldete die Einsatzleitung &#8222;Feuer aus&#8220;.  Personen kamen bei dem Brand nicht zu Schaden.     Die Brandursache ist zurzeit noch unklar; die Kriminalpolizei hat  die Ermittlungen aufgenommen.     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Ostholstein Kreisgesch\u00e4ftsstelle B\u00e4derstrasse 47 23738 Lensahn Pressedienst HBM Hartmut Junge Telefon: 0172 413 73 24 E-Mail: hartmut.junge@kfv-oh.org www.kfv-oh.org<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/56143\/2569602\/fw-oh-oh-riepsdorf-ortsteil-thomsdorf-reetdachhaus-niedergebrannt\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Am Mittwochabend (02.10.) entdeckten Passanten um kurz vor 20.00 Uhr ein Feuer auf dem Dach einer Reetkate.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-112504","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/112504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=112504"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/112504\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=112504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=112504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=112504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}