{"id":117953,"date":"2013-11-30T14:22:44","date_gmt":"2013-11-30T14:22:44","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/11\/fw-rz-starke-rauchentwicklung-gemeldet-486\/"},"modified":"2013-11-30T14:22:44","modified_gmt":"2013-11-30T14:22:44","slug":"fw-rz-starke-rauchentwicklung-gemeldet-486","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-starke-rauchentwicklung-gemeldet-486\/","title":{"rendered":"FW-RZ: Starke Rauchentwicklung gemeldet"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Rauchschwaden kamen an allen Seiten des Daches heraus.\" src=\"http:\/\/www.presseportal.de\/bild\/267773-preview-pressemitteilung-2013-11-30-klinkrade-1.jpg\" \/><\/p>\n<p>Ratzeburg (ots) &#8211; Klinkrade: Am Vormittag des 30.11.2013, kurz vor 11:00 Uhr meldeten zuf\u00e4llig vorbei kommende Passanten  Rauch, der  unter dem Dach eines Resthofes im Ortsteil Klein Klinkrade hervorkam. In Folge der sofort ausgel\u00f6sten Alarmierung erreichten die Wehren  Labenz und Klinkrade als Erste den Einsatzort.<!--more--> Bis auf den Hund war  jedoch niemand zuhause, so dass sich die Einsatzkr\u00e4fte gewaltsam  Zutritt verschaffen mussten. Eine fr\u00fche Lokalisierung des Brandherdes und der schnelle und gezielte L\u00f6schangriff verhinderten schlimmeres.  Zus\u00e4tzlich wurden die Wehren L\u00fcchow, Wentorf AS, Duvensee,  Siebenb\u00e4umen, Sch\u00f6nberg, Sandesneben, Schiphorst, Kastorf und  Bliestorf alarmiert. Unterst\u00fctzt durch eine Drehleiter aus Ratzeburg  und die Technische Einsatzleitung des Kreises kamen so insgesamt rund 150 Helfer zum Einsatz. Da das Geb\u00e4ude nie komplett im Vollbrand  stand, mag das manchem sehr viel erscheinen. Durch die  un\u00fcbersichtliche Geb\u00e4udestruktur und schwer zug\u00e4ngige Brandnester war jedoch lange Zeit nicht sicher ob die L\u00f6schma\u00dfnahmen den gew\u00fcnschten  Erfolg bringen w\u00fcrden. W\u00e4re das nicht der Fall gewesen, wollte die  Einsatzleitung vorbereitet sein. Am Ende konnte der Hund gerettet  werden und Menschen kamen auch nicht zu Schaden. Abgesehen von den   Nachl\u00f6scharbeiten endete der Einsatz gegen 13:00 Uhr.     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Hzgt. Lauenburg Thomas Grimm Telefon: 0160\/1188910 E-Mail: tel@kfv-herzogtum-lauenburg.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/68033\/2610782\/fw-rz-starke-rauchentwicklung-gemeldet\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Klinkrade: Am Vormittag des 30.11.2013, kurz vor 11:00 Uhr meldeten zuf\u00e4llig vorbei kommende Passanten Rauch, der unter<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-117953","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/117953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=117953"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/117953\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=117953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=117953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=117953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}