{"id":122844,"date":"2013-10-11T21:34:04","date_gmt":"2013-10-11T21:34:04","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/10\/bpoli-see-bundespolizei-see-rettet-surfer-aus-seenot-1036\/"},"modified":"2013-10-11T21:34:04","modified_gmt":"2013-10-11T21:34:04","slug":"bpoli-see-bundespolizei-see-rettet-surfer-aus-seenot-1036","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-bundespolizei-see-rettet-surfer-aus-seenot-1036\/","title":{"rendered":"BPOLI-See: Bundespolizei See rettet Surfer aus Seenot"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"BP 23 \"Bad D\u00fcben\" (Archivbild Bundespolizei See)\" src=\"http:\/\/www.presseportal.de\/bild\/262836-preview-pressemitteilung-bp23.jpg\" \/><\/p>\n<p>Neustadt (ots) &#8211; Ein aufmerksamer B\u00fcrger beobachtete am  Freitagabend vom Ufer Gold\/ Fehmarn einen Surfer, der sich aus  eigenen Kr\u00e4ften nicht mehr aufrichten konnte. Es herrschten starke  ablandige Winde, die den Surfer immer weiter in das Meer  hinauszutreiben drohten.<!--more--> Die beobachtende Person erkannte die  gef\u00e4hrliche Situation und informierte telefonisch die  Seenotrettungsleitstelle in Bremen. \u00dcber Seefunk wurde daraufhin das  in der N\u00e4he eingesetzte Einsatzschiff der Bundespolizeiinspektion See Neustadt in Holstein BP 23 &#8222;Bad D\u00fcben&#8220; \u00fcber den Sachverhalt in  Kenntnis gesetzt. Die &#8222;Bad D\u00fcben&#8220; nahm sofort Kurs auf und lief mit  H\u00f6chstfahrt zur angegebenen Position. Das mit einem gemischtem  Einsatzteam besetzte Kontrollboot (3 Bundespolizeibeamte, 1  Zollbeamter) konnte den unterk\u00fchlten und stark ersch\u00f6pften Mann aus  dem Wasser retten. Ein eintreffendes Fahrzeug der Deutschen  Gesellschaft zur Rettung Schiffbr\u00fcchiger brachte diesen zwecks  weiterer medizinischer Untersuchung nach Heiligenhafen. Die Schiffe  der Bundespolizei befinden sich das gesamte Jahr rund um die Uhr in  See und nehmen au\u00dferhalb des K\u00fcstenmeeres alle polizeilichen Aufgaben wahr. Innerhalb des K\u00fcstenmeeres ist die Bundespolizei f\u00fcr den  Grenzschutz zust\u00e4ndig. Durch den hohen Pr\u00e4senzgrad ist gew\u00e4hrleistet, dass die Einsatzmittel, zu denen Schiffe, Streifenboote und  Hubschrauber geh\u00f6ren, schnell jeden Einsatzort erreichen k\u00f6nnen.     R\u00fcckfragen bitte an:  Bundespolizeiinspektion See Neustadt \/ Holstein Carsten Thielhorn Telefon: 04561 \/ 4071-514 Fax: 04561 \/ 4071-510 E-Mail: carsten.thielhorn@polizei.bund.de www.bundespolizei.de  Die Bundespolizeidirektion Bad Bramstedt nimmt als Bundesbeh\u00f6rde ihre Aufgaben in Schleswig-Holstein, Mecklenburg-Vorpommern sowie in Nord- und Ostsee und anlassbezogen dar\u00fcber hinaus wahr.    Dazu sind ihr als operative Dienststellen die  Bundespolizeiinspektionen in Flensburg, Kiel, Rostock, Stralsund und  Pasewalk sowie die Bundespolizeiinspektion Kriminalit\u00e4tsbek\u00e4mpfung  Rostock und eine Mobile Kontroll- und \u00dcberwachungseinheit  unterstellt. Mit den Bundespolizeiinspektionen See in Neustadt in  Holstein, Warnem\u00fcnde und Cuxhaven verf\u00fcgt sie als einzige  Bundespolizeidirektion \u00fcber eine maritime Einsatzkomponente  &#8222;Bundespolizei See&#8220;, um die Seegrenze in der Nord- und Ostsee  (Schengen-Au\u00dfengrenze) zu \u00fcberwachen.   Die Bundespolizeidirektion Bad Bramstedt besch\u00e4ftigt insgesamt ca.  2600 Mitarbeiterinnen und Mitarbeiter, darunter Polizeibeamte,  Verwaltungsbeamte und Tarifbesch\u00e4ftigte. Auf Grundlage des Bundespolizeigesetzes und anderer Gesetze nimmt sie umfangreiche und vielf\u00e4ltige Aufgaben wahr.   Dazu geh\u00f6ren insbesondere: &#8211;  der grenzpolizeiliche Schutz des Bundesgebietes, &#8211; die bahnpolizeilichen Aufgaben &#8211; die grenzpolizeilichen, schifffahrtspolizeilichen und  umweltpolizeilichen Aufgaben in Nord- und Ostsee.   Weitere Informationen zur Bundespolizei und zur  Bundespolizeidirektion Bad Bramstedt erhalten Sie unter  www.bundespolizei.de.<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/70262\/2574744\/bpoli-see-bundespolizei-see-rettet-surfer-aus-seenot\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Ein aufmerksamer B\u00fcrger beobachtete am Freitagabend vom Ufer Gold\/ Fehmarn einen Surfer, der sich aus eigenen Kr\u00e4ften<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-122844","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/122844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=122844"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/122844\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=122844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=122844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=122844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}