{"id":125666,"date":"2013-10-28T11:24:04","date_gmt":"2013-10-28T11:24:04","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/10\/pol-sh-afb-einladung-zum-festakt-anlasslich-der-20-jahrigen-namensgebung-der-polizeischule-wilhelm-krutzfeld-in-der-fachinspektion-fortbildung-der-pd-afb-in-malente-kiebitzhorn-1086\/"},"modified":"2013-10-28T11:24:04","modified_gmt":"2013-10-28T11:24:04","slug":"pol-sh-afb-einladung-zum-festakt-anlasslich-der-20-jahrigen-namensgebung-der-polizeischule-wilhelm-krutzfeld-in-der-fachinspektion-fortbildung-der-pd-afb-in-malente-kiebitzhorn-1086","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-einladung-zum-festakt-anlasslich-der-20-jahrigen-namensgebung-der-polizeischule-wilhelm-krutzfeld-in-der-fachinspektion-fortbildung-der-pd-afb-in-malente-kiebitzhorn-1086\/","title":{"rendered":"POL-SH-AFB: Einladung zum Festakt anl\u00e4sslich der 20-j\u00e4hrigen Namensgebung der Polizeischule &#8218;Wilhelm Kr\u00fctzfeld&#8216; in der Fachinspektion Fortbildung der PD AFB in Malente &#8211; Kiebitzh\u00f6rn"},"content":{"rendered":"<p>Eutin (ots) &#8211; Im November 2013 j\u00e4hrt sich die Namensgebung der  Polizeischule &#8218;Wilhelm Kr\u00fctzfeld&#8216; zum 20. Mal. Wilhelm Kr\u00fctzfeld ist  geb\u00fcrtiger Schleswig-Holsteiner. Er wurde am 9. Dezember 1880 in  Hornsdorf, Gemeinde Seedorf, im Kreis Bad Segeberg geboren.<!--more--> Er  leitete als Polizeioberleutnant 1938 das Berliner Polizeirevier 16.  Wilhelm Kr\u00fctzfeld  bewahrte in der Reichspogromnacht vom 9. auf den  10. November 1938 die Neue Synagoge in der Oranienburger Stra\u00dfe in  Berlin vor der Zerst\u00f6rung und bewies dabei lebensgef\u00e4hrliche  Zivilcourage. Beamte seines Reviers stellten sich einer Gruppe von  SA-Leuten entgegen, die bereits Feuer gelegt hatten und zwangen sie  zum &#8222;R\u00fcckzug&#8220;. Die Beamten ordneten sofortige L\u00f6scharbeiten an,  obwohl die Feuerwehr den Befehl hatte, keine brennenden Synagogen  zu l\u00f6schen. Man berief sich dabei auf die bestehenden Gesetze zum  Denkmalschutz. Am 10.11.1938 musste sich Wilhelm Kr\u00fctzfeld f\u00fcr diese  Vorkommnisse beim damaligen Polizeipr\u00e4sidenten Graf von Helldorf  verantworten und wurde ger\u00fcgt. Weitergehende &#8222;Strafen&#8220; w\u00e4ren bei  solchen Sachverhalten durchaus wahrscheinlich gewesen. Dieses f\u00fcr die Landespolizei Schleswig-Holstein und die PD AFB Eutin besondere  Jubil\u00e4um der Namensgebung wird am     Donnerstag, den 7. November 2013     im Rahmen eines Festaktes begangen. Im Zusammenhang mit diesem  Jubil\u00e4um wird auch die ehemalige Ausstellung zur Person und dem  Schaffen Wilhelm Kr\u00fctzfelds in neuer Form und als fest installierte  Dauerausstellung in den R\u00e4umlichkeiten der Polizeischule wieder  er\u00f6ffnet.     Herr Innenminister Andreas Breitner wird beim Festakt die  Er\u00f6ffnungsrede, der Pr\u00e4sident des Bundeskriminalamtes, J\u00f6rg Ziercke,  wird die Festansprache halten.     Die Veranstaltung beginnt um 15:00 Uhr in den R\u00e4umlichkeiten der  Polizeischule &#8218;Wilhelm Kr\u00fctzfeld&#8216; in Kiebitzh\u00f6rn. Der Abschluss des  offiziellen Aktes ist gegen 16:30 Uhr geplant.     Vertreter der Medien sind herzlich eingeladen, die Veranstaltung  f\u00fcr eine Berichterstattung zu begleiten. F\u00fcr die Disposition bitte  ich um Zusagen bis zum 6. November um 16 Uhr.     R\u00fcckfragen bitte an:  Polizeidirektion f\u00fcr Aus- und Fortbildung und f\u00fcr die  Bereitschaftspolizei Schleswig-Holstein R\u00fcdiger Schwarz Telefon: 04521 81 209 E-Mail: ruediger.schwarz1@polizei.landsh.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/43685\/2585241\/pol-sh-afb-einladung-zum-festakt-anlaesslich-der-20-jaehrigen-namensgebung-der-polizeischule\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; Im November 2013 j\u00e4hrt sich die Namensgebung der Polizeischule &#8218;Wilhelm Kr\u00fctzfeld&#8216; zum 20. Mal. Wilhelm Kr\u00fctzfeld ist<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-125666","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/125666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=125666"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/125666\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=125666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=125666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=125666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}