{"id":153546,"date":"2014-09-07T09:58:06","date_gmt":"2014-09-07T09:58:06","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/09\/fw-rz-feuer-durch-blitzschlag-bilder-190\/"},"modified":"2014-09-07T09:58:06","modified_gmt":"2014-09-07T09:58:06","slug":"fw-rz-feuer-durch-blitzschlag-bilder-190","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-feuer-durch-blitzschlag-bilder-190\/","title":{"rendered":"FW-RZ: Feuer durch Blitzschlag (Bilder)"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Nebengeb\u00e4ude\" src=\"http:\/\/www.presseportal.de\/bild\/295534-preview-pressemitteilung-sahms-3.jpg\" \/><\/p>\n<p>Ratzeburg (ots) &#8211;      Erg\u00e4nzende Bilder zum Feuer vom 06. auf den 07.09.2014 in Sahms.     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Hzgt. Lauenburg Thomas Grimm Telefon: 0160\/1188910 E-Mail: tel@kfv-herzogtum-lauenburg.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/68033\/2824744\/fw-rz-feuer-durch-blitzschlag-bilder\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Erg\u00e4nzende Bilder zum Feuer vom 06. auf den 07.09.2014 in Sahms. R\u00fcckfragen bitte an: Kreisfeuerwehrverband Hzgt. Lauenburg<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-153546","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/153546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=153546"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/153546\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=153546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=153546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=153546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}