{"id":153939,"date":"2014-04-10T13:43:38","date_gmt":"2014-04-10T13:43:38","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/04\/bpoli-see-pressetermin-bei-der-bundespolizeiinspektion-see-neustadt-zur-zentralen-jubilaeumsveranstaltung-50-jahre-bundespolizei-see-tag-der-kuestenwache-am-09-und-10-august-2014-867\/"},"modified":"2014-04-10T13:43:38","modified_gmt":"2014-04-10T13:43:38","slug":"bpoli-see-pressetermin-bei-der-bundespolizeiinspektion-see-neustadt-zur-zentralen-jubilaeumsveranstaltung-50-jahre-bundespolizei-see-tag-der-kuestenwache-am-09-und-10-august-2014-867","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-pressetermin-bei-der-bundespolizeiinspektion-see-neustadt-zur-zentralen-jubilaeumsveranstaltung-50-jahre-bundespolizei-see-tag-der-kuestenwache-am-09-und-10-august-2014-867\/","title":{"rendered":"BPOLI-See: Pressetermin bei der Bundespolizeiinspektion See Neustadt zur zentralen Jubil\u00e4umsveranstaltung 50 Jahre Bundespolizei See\/ Tag der K\u00fcstenwache am 09. und 10. August 2014"},"content":{"rendered":"<p>Neustadt (ots) &#8211;      PRESSEMITTEILUNG April 2014: Willkommen an Bord in Neustadt in  Holstein: Das 50-j\u00e4hrige Dienstjubil\u00e4um der Bundespolizei See wird in der Hafenstadt Neustadt in Holstein gefeiert.<!--more--> Das ist der Anlass f\u00fcr  eine gemeinsame zweit\u00e4gige Veranstaltung der Bundespolizei See und  der Stadt Neustadt in Holstein am 09. und 10. August 2014.     Jubil\u00e4um: 50 Jahre Bundespolizei See am 09. und 10. August 2014 Am 20.08.1964  wurde  in  Neustadt  in  Holstein  der  damalige   Bundesgrenzschutz  See  mit  zwei Flottillen  aufgestellt  und  die   ersten  &#8222;Grenzj\u00e4ger  zur  See&#8220;  bezogen  ihre  Unterk\u00fcnfte  in  der  Marinekaserne auf dem Wieksberg. Bis zum heutigen Tage sind Teile der maritimen Komponente der  Bundespolizeidirektion  Bad  Bramstedt  im  Standort  Neustadt  pr\u00e4sent;  dieses  sind  die  Bundespolizeiinspektion  See  Neustadt  in  Holstein  mit  ihren   Seefahrzeugen  sowie  der Direktionsbereich  Bundespolizei  See,   letzterer  ist  der  maritime  Fachstab  der Bundespolizeiinspektion  See. Das Jahr 2014 ist daher sowohl f\u00fcr die Bundespolizeidirektion  Bad Bramstedt  als  auch  f\u00fcr  die  Stadt  Neustadt  in  Holstein  in maritimer  Hinsicht  von  besonderer Bedeutung. In diesem Jahr j\u00e4hrt  sich der &#8222;5. Tag der K\u00dcSTENWACHE&#8220;, der allj\u00e4hrlich mit gro\u00dfer  Resonanz  und  wachsender  Beliebtheit  bei  der  Fangemeinde  der   Vorabendserie &#8222;K\u00dcSTENWACHE&#8220;  rund  um  den  Kommunalhafen  gefeiert   wird.  Damit  r\u00fcckt  sowohl  die  Stadt Neustadt mit ihren  zahlreichen Drehorten und Schaupl\u00e4tzen als auch die Bundespolizei See mit ihrer  Liegenschaft  auf  dem  Wieksberg  und  den   Einsatzschiffen  &#8222;Neustrelitz&#8220;  und  &#8222;Bad  D\u00fcben&#8220;, besser  bekannt  unter  dem  Namen  &#8222;Albatros  2&#8220;,  in  den  Fokus  vieler  maritim   interessierter Fernsehzuschauer.  Die  Bundespolizei  See  blickt  im Jahr  2014  auf  eine  50-j\u00e4hrige  Geschichte zur\u00fcck; dieses  besondere Jubil\u00e4um wird miteiner &#8222;Zentralen Jubil\u00e4umsveranstaltung &#8211;  50 Jahre Bundespolizei  See&#8220;  gefeiert.  Aufgrund  der  engen   Verbundenheit  zur  Stadt  Neustadt  werden  an zwei Tagen der &#8222;Tag  der K\u00fcstenwache&#8220; und das Dienststellenjubil\u00e4um mit einem &#8222;Tag der  offenen T\u00fcr&#8220;  gemeinsam  gefeiert.  Dazu  wird  sowohl  der Bereich   des  Kommunalhafens  als  auch  die Liegenschaft  auf  dem  Wieksberg einschlie\u00dflich  des  Bundespolizeihafens  in  eine  maritime  Eventfl\u00e4che umgestaltet.     Tag der K\u00fcstenwache am 09. und 10. August 2014 Neustadt  in   Holstein  ist  seit  1996  Produktionsort  der  ZDF-Serie   &#8222;K\u00fcstenwache&#8220;.  Jede  Woche sehen  Millionen  von  Zuschauerinnen   und  Zuschauern  die  Serie  und  verfolgen  die  spannenden Folgen  dieses maritimen Krimis. Somit hat die Fernsehserie &#8222;K\u00fcstenwache&#8220;  Neustadt in Holstein und die angrenzende Region in ganz Deutschland  bekannt gemacht. Die ganze Stadt versteht sich mittlerweile als  &#8222;Stadt der K\u00fcstenwache&#8220;, denn Neustadt in Holstein ist nicht nur  Drehort, sondern auch  Sitz  der  Bundespolizei  See.  Dieses  Alleinstellungsmerkmal  ist  zentrales  Thema  des Neust\u00e4dter  Stadtmarketings.     In diesem Jahr freut sich die Stadt Neustadt in Holstein ganz  besonders, dass nicht nur auf das  50j\u00e4hrige  Jubil\u00e4um  der   Bundespolizei  See  angesto\u00dfen  werden  kann,  sondern  dass  das  Thema  &#8222;K\u00fcstenwache&#8220;  im  Rahmen  der  gemeinsamen  zweit\u00e4gigen   Veranstaltung  in  den  Fokus gestellt wird. Bereits am 08. August  wird f\u00fcr geladene G\u00e4ste ein Empfang der Stadt veranstaltet.     Zwei Tage voller Erlebnisse und maritimen Flair Die Veranstaltung  markiert f\u00fcr die K\u00fcste einen echten Veranstaltungsh\u00f6hepunkt, denn  hier k\u00f6nnen die Besucher Realit\u00e4t und Fiktion hautnah miterleben. Die Arbeit der Bundespolizei See kann im Rahmen  von   Schiffsbesichtigungen  und  vielen  Vorf\u00fchrungen kennen gelernt   werden.  An  beiden Veranstaltungstagen bleibt sicher keine Frage zur Arbeit der Bundespolizei offen. F\u00fcr die Fans der Serie &#8222;K\u00fcstenwache&#8220;  geht ganz bestimmt ein Traum in Erf\u00fcllung, denn an beiden Tagen  werden die Hauptdarsteller zur Autogrammstunde erwartet. F\u00fcr k\u00fcnftige Schauspieler findet am Samstag ein  Komparsen-Casting  statt.  Am   gesamten  Wochenende  gibt  es  ein  abwechslungsreiches  Familienprogramm  mit  Live-Musik,  Mitmach-Angeboten,   Schiffsbesichtigungen,  F\u00fchrungen  und vielem mehr. So k\u00f6nnen sich  alle schon einmal auf ein zweit\u00e4giges buntes Treiben rund um den  Bundespolizei- und Stadthafen freuen.     Druckfrischer Flyer macht Lust auf einen Besuch Die Veranstalter  Bundespolizei See und Neust\u00e4dter Stadtmarketing haben einen Flyer  entwickelt, der  die  wichtigsten  und  bereits  fest  stehenden   Programmpunkte  in  einem  handlichen  Format zusammenfasst.  Auf  8  Seiten  wird  die  Veranstaltung  vorgestellt  und  Lust  gemacht   auf  diesen maritimen  Veranstaltungsh\u00f6hepunkt.  Der  Flyer  ist  in  einer  Auflage  von  10.000  St\u00fcck  gedruckt worden und wird \u00fcber das Stadtmarketing und die Tourismus-Agentur L\u00fcbecker Bucht verteilt.     Verbindung beider Veranstaltungsfl\u00e4chen durch Shuttle mit Bus,  Bimmel-Bahn und Booten Die  beiden  Veranstaltungsfl\u00e4chen  am   Wieksberg  und  Kommunalhafen  werden  durch  einen  Bimmelbahn-Shuttle verbunden. F\u00fcr die Besucher ohne PKW wird ein  Bus-Shuttle aus Rettin und Pelzerhaken  eingerichtet.  Die  beiden   Hafenseiten  im  Bereich  des  Kommunalhafens  werden  am Tag  der   K\u00fcstenwache  durch  einen  Wasser-Shuttle  miteinander  verbunden   und  f\u00fcr  PKW-Fahrer werden  die  Parkfl\u00e4chen  rechtzeitig   ausgeschildert.  Das  Parken  soll  an  beiden  Tagen  au\u00dferhalb der  Veranstaltungsfl\u00e4chen stattfinden.     Weitere Informationen zur Veranstaltung erteilen EPHK Marco Antler unter 04561\/ 4071-502 und marco.Antler@polizei.bund.de oder  Stadtmarketingkoordinatorin Andrea Brunh\u00f6ber unter: 04561\/ 61920 oder unter: marketing@stadt-neustadt.de     Ort der Veranstaltung: 50 Jahre Bundespolizei See, Wieksberg,  23730 Neustadt in Holstein Ansprechpartner: Marco Antler Ort der  Veranstaltung: Tag der K\u00fcstenwache, Hafen Neustadt in Holstein:  Ansprechpartner: Andrea Brunh\u00f6ber     Programmh\u00f6hepunkte am 09. und 10. August 2014     Maritime  Einsatzvorf\u00fchrungen:  am  09.  und  10.  gibt  es  die   einmalige  Gelegenheit,  sich  einen hautnahen  Einblick  in  die   Aufgaben  und  die  Leistungsf\u00e4higkeit  der  maritimen  Komponente   der Bundespolizei See zu verschaffen.     Autogrammstunde  mit  den  Hauptdarstellern.  Die  Autogrammstunde findet  am  Samstag  in einem Zelt von 14-17 Uhr vor dem Studio 1  (Werftstra\u00dfe) statt. Autogrammstunde auf dem Wieksberg: diese findet  am Sonntag statt     Studiobesuch und Komparsen-Casting: Auch die Filmwelt  &#8222;K\u00fcstenwache&#8220; ist hautnah erlebbar. Im  Studio  1  werden   Originalrequisiten,  unver\u00f6ffentlichte  Filmsequenzen  und  begehbare Filmkulissen gezeigt und f\u00fcr diejenigen, die schon immer mal Filmluft schnuppern wollten, besteht die M\u00f6glichkeit, sich als Komparsin oder  Komparse am Samstag casten zu lassen.     ZDF  Torwandschie\u00dfen:  Das  ZDF  wird  anl\u00e4sslich  des  &#8222;Tags  der K\u00fcstenwache&#8220;  seine  Original-Torwand mit nach Neustadt in Holstein  bringen. Am Samstag findet ein Promi-Torwandschie\u00dfen statt  und   anschlie\u00dfend  kann  sich  jeder,  der  mag,  beim  &#8222;Torwandschie\u00dfen   f\u00fcr jedermann&#8220; versuchen.     Open  ship  auf  Einsatzschiffen  der  Bundespolizei  See:  Die   beiden  Einsatzschiffe  der Bundespolizeiinspektion  See  Neustadt   in  Holstein  &#8222;Bad  D\u00fcben&#8220;  und  &#8222;Neustrelitz&#8220;  werden  f\u00fcr  die  Dreharbeiten der Serie &#8222;K\u00fcstenwache&#8220; der Filmproduktionsgesellschaft  zur Verf\u00fcgung gestellt; f\u00fcr diese  Zwecke  tr\u00e4gt  das  eingesetzte   Schiff  den  Namen  &#8222;Albatros  II&#8220;.  Der  Name  des  jeweiligen  Einsatzschiffes (&#8222;Bad D\u00fcben&#8220; oder &#8222;Neustrelitz&#8220;) ist an den  Br\u00fcckenaufbauten angebracht. Weitere Einsatzschiffe sind w\u00e4hrend der  Gesamtveranstaltung zu besichtigen.     Beteiligung  des  Einsatzausbildungszentrum  Schadensabwehr:   Bereits  zum  vierten  Mal beteiligt  sich  das  Einsatzausbildungszentrum  Schadensabwehr  der  Marine  (EAZS)  am   Tag  der K\u00fcstenwache.     Open ship: Am Samstagmorgen wird ein Taucherschulboot seinen  Liegeplatz am Kai im Hafen einnehmen und kann w\u00e4hrend der beiden  Veranstaltungstage besichtigt werden. Auf dem Taucherschulboot  erfahren die Besucherinnen und Besucher nicht nur, wie die Taucher in der Marine  ausgebildet  werden,  sondern  werden  anhand  von   Bildmaterial  \u00fcber  die  Vielf\u00e4ltigkeit  der Ausbildung  beim   Einsatzausbildungszentrum  in  Neustadt  in  Holstein  informiert.   Als  besonderes Highlight wird eine Fotoaktion angeboten.     Live-Musik: Gro\u00df  und  Klein  k\u00f6nnen  am  09.  und  10.  August   ganz  viel  Live-Musik  erleben:  so freuen sich die Veranstalter auf die Big Band des Polizeiorchesters, die erstmals in Neustadt in  Holstein  spielen.  Ebenfalls  mit  dabei  sind  u.a.  der   Shanty-Chor  Neustadt,  L\u00fcbecks Freibeutermuuke und das Lensahner  Blasorchester.     \u00dcber die Partner     OPAL Filmproduktion: Die OPAL-Gruppe produziert seit vielen Jahren erfolgreich fiktionales Programm f\u00fcr den  deutschen  und   internationalen  Fernsehmarkt.  Produzent  und  Gesch\u00e4ftsf\u00fchrer  ist  Alexander  von Hohenthal.  Die  Serie  K\u00fcstenwache  wird  im  Auftrag des  ZDF  produziert.  Mittlerweile  wird  im  Studio  in Neustadt in Holstein, auf der Ostsee und in der Umgebung die 17. Staffel  produziert.     Einsatz  Ausbildungszentrum  Schadensabwehr  Marine:  Das   Einsatzausbildungszentrum Schadensabwehr Marine (EAZS) ist eine  Schule der Marine mit Sitz in Neustadt in Holstein. Im EAZS der  Marine stehen die Schadensabwehr und die Ausbildung von Tauchern und  U-Boot-Besatzungen im Fokus. Leckabwehr und Brandbek\u00e4mpfung k\u00f6nnen  vor Ort im realistischen Umfeld stattfinden. Mit Arbeitstauchtopf,  Tieftauchtopf  und  Rettungsmittel-  und  Taucher\u00fcbungshalle  stehen  f\u00fcr  diese  Ausbildungsg\u00e4nge  an  Land ausreichende  Wassertiefen   zur  Verf\u00fcgung.  Auf  See  wird  die  praktische  Taucherausbildung   im Taucher\u00fcbungsbecken oder an Bord der beiden Taucherschulboote  BALTRUM und JUIST durchgef\u00fchrt.     Studio  1  des  Fanclubs  K\u00fcstenwache  e.V.:  direkt am Neust\u00e4dter Hafen befindet sich das  K\u00fcstenwache Studio 1. Hier gibt es echte  Studioluft zu schnuppern und den Blick hinter die Kulissen. Die  Originalkulissen der  Albatros  I,  Filmausstattung,  Drehb\u00fccher,   Fotos  vom  Set  und  Geschichten  rund  um  die  Produktion werden   hier  zu  einem  spannenden  Erlebnis.  Dabei  sind  die  Kulissen   begehbar,  sowie  Fotografieren  und Anfassen erlaubt. Mit etwas  Gl\u00fcck treffen die Besucher hier auch mal den einen oder anderen  Schauspieler bei  einer  Autogrammstunde.  F\u00fcr  Gruppen  k\u00f6nnen   Sonderbesichtigungen  ganzj\u00e4hrig  an  drehfreien  Tagen angemeldet  werden unter Tel: 04561 &#8211; 10 88. Das Studio 1 des Fanclubs wird vom  Fanclub K\u00fcstenwache e.V.  betrieben  und  hat  folgende   \u00d6ffnungszeiten:  Von  Juni  bis  August  jeweils  donnerstags,   freitags  und samstags von 14-18.00 Uhr. Der Eintritt betr\u00e4gt f\u00fcr  Erwachsene 6,00 EUR, Kinder 3,00 EUR (Kinder mit eigener ostseecard*  haben freien Eintritt f\u00fcr Kinder), Familienkarte: 15,00 EUR.     R\u00fcckfragen bitte an:  Bundespolizeiinspektion See Neustadt \/ Holstein Pressestelle Bianca Diekert Telefon: 04561 \/ 4071-514 Fax: 04561 \/ 40715 &#8211; 10 E-Mail: bianca.diekert@polizei.bund.de www.bundespolizei.de  Die Bundespolizeidirektion Bad Bramstedt nimmt als Bundesbeh\u00f6rde ihre Aufgaben in Schleswig-Holstein, Mecklenburg-Vorpommern sowie in Nord- und Ostsee und anlassbezogen dar\u00fcber hinaus wahr.    Dazu sind ihr als operative Dienststellen die  Bundespolizeiinspektionen in Flensburg, Kiel, Rostock, Stralsund und  Pasewalk sowie die Bundespolizeiinspektion Kriminalit\u00e4tsbek\u00e4mpfung  Rostock und eine Mobile Kontroll- und \u00dcberwachungseinheit  unterstellt. Mit den Bundespolizeiinspektionen See in Neustadt in  Holstein, Warnem\u00fcnde und Cuxhaven verf\u00fcgt sie als einzige  Bundespolizeidirektion \u00fcber eine maritime Einsatzkomponente  &#8222;Bundespolizei See&#8220;, um die Seegrenze in der Nord- und Ostsee  (Schengen-Au\u00dfengrenze) zu \u00fcberwachen.   Die Bundespolizeidirektion Bad Bramstedt besch\u00e4ftigt insgesamt ca.  2600 Mitarbeiterinnen und Mitarbeiter, darunter Polizeibeamte,  Verwaltungsbeamte und Tarifbesch\u00e4ftigte. Auf Grundlage des Bundespolizeigesetzes und anderer Gesetze nimmt sie umfangreiche und vielf\u00e4ltige Aufgaben wahr.   Dazu geh\u00f6ren insbesondere: &#8211;  der grenzpolizeiliche Schutz des Bundesgebietes, &#8211; die bahnpolizeilichen Aufgaben &#8211; die grenzpolizeilichen, schifffahrtspolizeilichen und  umweltpolizeilichen Aufgaben in Nord- und Ostsee.   Weitere Informationen zur Bundespolizei und zur  Bundespolizeidirektion Bad Bramstedt erhalten Sie unter  www.bundespolizei.de.<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/70262\/2710693\/bpoli-see-pressetermin-bei-der-bundespolizeiinspektion-see-neustadt-zur-zentralen\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; PRESSEMITTEILUNG April 2014: Willkommen an Bord in Neustadt in Holstein: Das 50-j\u00e4hrige Dienstjubil\u00e4um der Bundespolizei See wird<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-153939","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/153939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=153939"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/153939\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=153939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=153939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=153939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}