{"id":157008,"date":"2014-05-29T17:03:34","date_gmt":"2014-05-29T17:03:34","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/05\/bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot-913\/"},"modified":"2014-05-29T17:03:34","modified_gmt":"2014-05-29T17:03:34","slug":"bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot-913","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot-913\/","title":{"rendered":"BPOLI-See: Bundespolizei See rettet Angler vor Pelzerhaken aus Seenot"},"content":{"rendered":"<p>Neustadt (ots) &#8211; Am Morgen des 29. Mai 2014 sichtete die Besatzung des Einsatzschiffes BP 22 &#8222;Neustrelitz&#8220; der Bundespolizeiinspektion  See aus Neustadt w\u00e4hrend der Streifenfahrt ein gekentertes Angelboot  vor Pelzerhaken. Die Crew bestand aus drei m\u00e4nnlichen Personen, die  neben dem Boot im Wasser trieben.<!--more--> Das sofort zu Wasser gelassene  Bereitschaftsboot von BP 22 konnte die Angler nach kurzer Zeit an  Bord nehmen, keiner von ihnen trug eine Rettungsweste. Nach einer  Verbindungsaufnahme mit der DGzRS wurde das SRB &#8222;Crempe&#8220; gebeten, das in der Zwischenzeit gesunkene Angelboot zu bergen. Das Boot lag am  Grund im Flachwasser vor Pelzerhaken, wo an diesem Wochenende das  Surf Festival veranstaltet wird, somit stellte es eine Gefahr f\u00fcr die dort startenden Surfer und Kiter dar. Auf dem Einsatzschiff BP 22  wurden unterdessen die geretteten Angler im Rahmen der Ersten Hilfe  versorgt. Da zwei Personen an Unterk\u00fchlung litten, wurde ihnen  trockene Kleidung von der Besatzung zur Verf\u00fcgung gestellt. Nach dem  Einlaufen im Neust\u00e4dter Hafen konnten die drei Personen von einem  durch das Gemeinsame Lagezentrum bereits alarmierten Rettungswagen  \u00fcbernommen und weiter versorgt werden.     R\u00fcckfragen bitte an:  Bundespolizeiinspektion See Neustadt in Holstein \u00d6ffentlichkeitsarbeit\/Pressestelle Bianca Diekert Telefon: 04561 \/ 4071 &#8211; 514 Fax: 04561 \/ 4071 &#8211; 510 E-Mail: bianca.diekert@polizei.bund.de www.bundespolizei.de  Die Bundespolizeidirektion Bad Bramstedt nimmt als Bundesbeh\u00f6rde ihre Aufgaben in Schleswig-Holstein, Mecklenburg-Vorpommern sowie in Nord- und Ostsee und anlassbezogen dar\u00fcber hinaus wahr.    Dazu sind ihr als operative Dienststellen die  Bundespolizeiinspektionen in Flensburg, Kiel, Rostock, Stralsund und  Pasewalk sowie die Bundespolizeiinspektion Kriminalit\u00e4tsbek\u00e4mpfung  Rostock und eine Mobile Kontroll- und \u00dcberwachungseinheit  unterstellt. Mit den Bundespolizeiinspektionen See in Neustadt in  Holstein, Warnem\u00fcnde und Cuxhaven verf\u00fcgt sie als einzige  Bundespolizeidirektion \u00fcber eine maritime Einsatzkomponente  &#8222;Bundespolizei See&#8220;, um die Seegrenze in der Nord- und Ostsee  (Schengen-Au\u00dfengrenze) zu \u00fcberwachen.   Die Bundespolizeidirektion Bad Bramstedt besch\u00e4ftigt insgesamt ca.  2600 Mitarbeiterinnen und Mitarbeiter, darunter Polizeibeamte,  Verwaltungsbeamte und Tarifbesch\u00e4ftigte. Auf Grundlage des Bundespolizeigesetzes und anderer Gesetze nimmt sie umfangreiche und vielf\u00e4ltige Aufgaben wahr.   Dazu geh\u00f6ren insbesondere: &#8211;  der grenzpolizeiliche Schutz des Bundesgebietes, &#8211; die bahnpolizeilichen Aufgaben &#8211; die grenzpolizeilichen, schifffahrtspolizeilichen und  umweltpolizeilichen Aufgaben in Nord- und Ostsee.   Weitere Informationen zur Bundespolizei und zur  Bundespolizeidirektion Bad Bramstedt erhalten Sie unter  www.bundespolizei.de.<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/70262\/2749298\/bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Am Morgen des 29. Mai 2014 sichtete die Besatzung des Einsatzschiffes BP 22 &#8222;Neustrelitz&#8220; der Bundespolizeiinspektion See<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-157008","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/157008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=157008"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/157008\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=157008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=157008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=157008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}