{"id":162732,"date":"2014-09-30T17:29:38","date_gmt":"2014-09-30T17:29:38","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/09\/fw-oh-traditionssegler-im-neustaedter-hafen-gesunken-feuerwehr-verhindert-groessen-umweltschaden-480\/"},"modified":"2014-09-30T17:29:38","modified_gmt":"2014-09-30T17:29:38","slug":"fw-oh-traditionssegler-im-neustaedter-hafen-gesunken-feuerwehr-verhindert-groessen-umweltschaden-480","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-traditionssegler-im-neustaedter-hafen-gesunken-feuerwehr-verhindert-groessen-umweltschaden-480\/","title":{"rendered":"FW-OH: Traditionssegler im Neust\u00e4dter Hafen gesunken. Feuerwehr verhindert gr\u00f6\u00dfen Umweltschaden"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Foto: Hartmut Junge\nF\u00fcr redaktionelle Zwecke honorarfrei gegen Nennung des Fotografen\" src=\"http:\/\/www.presseportal.de\/bild\/298373-preview-pressemitteilung-dsc00412.jpg\" \/><\/p>\n<p>Lensahn (ots) &#8211;      Am Dienstagnachmittag gegen 15.30 Uhr wurde die Feuerwehr Neustadt in Holstein alarmiert, weil ein altes Segelschiff im Stadthafen  deutlich Schlagseite hatte. Die ersten eintreffenden Kr\u00e4fte  versuchten zun\u00e4chst eingedrungenes Wasser aus dem Schiff abzupumpen.<!--more-->  Noch bevor der Lenzeinsatz erfolgreich begonnen werden konnte, legte  sich das Schiff auf die Seite und sank innerhalb weniger Minuten.  Dadurch lief eine gr\u00f6\u00dfere Menge Dieselkaftstoff in das Hafenbecken.  Die Feuerwehr legte mit Hilfe ihres Arbeitsbootes &#8222;Grisu&#8220; eine  \u00d6lsperre um den Havaristen. Das THW Neustadt wurde zus\u00e4tzlich  angefordert, um mit weiteren \u00d6lsperren ein Abtreiben des Kraftstoffes in das Binnenwasser zu verhindern. Anschlie\u00dfend sicherte die  Feuerwehr den Havaristen mit Seilen, damit der Segler nicht  aufschwimmen und in das Hafenbecken treiben kann.     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Ostholstein Kreisgesch\u00e4ftsstelle B\u00e4derstrasse 47 23738 Lensahn Pressedienst HBM Hartmut Junge Telefon: 0172 413 73 24 E-Mail: hartmut.junge@kfv-oh.org www.kfv-oh.org<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/56143\/2844018\/fw-oh-traditionssegler-im-neustaedter-hafen-gesunken-feuerwehr-verhindert-groessen-umweltschaden\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Am Dienstagnachmittag gegen 15.30 Uhr wurde die Feuerwehr Neustadt in Holstein alarmiert, weil ein altes Segelschiff im<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-162732","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/162732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=162732"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/162732\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=162732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=162732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=162732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}