{"id":162995,"date":"2014-09-13T13:20:30","date_gmt":"2014-09-13T13:20:30","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/09\/fw-rz-grossuebung-von-feuerwehren-und-drk-in-alt-moelln-576\/"},"modified":"2014-09-13T13:20:30","modified_gmt":"2014-09-13T13:20:30","slug":"fw-rz-grossuebung-von-feuerwehren-und-drk-in-alt-moelln-576","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-grossuebung-von-feuerwehren-und-drk-in-alt-moelln-576\/","title":{"rendered":"FW-RZ: Gro\u00df\u00fcbung von Feuerwehren und DRK in Alt M\u00f6lln"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Sammelpunkt\" src=\"http:\/\/www.presseportal.de\/bild\/296332-preview-pressemitteilung-sammelpunkt.jpg\" \/><\/p>\n<p>Ratzeburg (ots) &#8211;      Alt M\u00f6lln (ots)- Kreis Herzogtum Lauenburg 13.09.2014 \/ 8:50 Uhr  Unheimlich lag der k\u00fcnstliche Rauch \u00fcber dem \u00dcbungsobjekt, dem  Seniorenruhesitz &#8222;Zu den Ziegelwiesen&#8220;. Am Samstag den 13.09.2014  fand in Alt M\u00f6lln eine gro\u00df angelegte Einsatz\u00fcbung statt.<!--more-->     Kurz vor 09:00 Uhr wurden rund 60 Einsatzkr\u00e4fte, bestehend aus  neun Feuerwehren, der TEL und Helfern des DRK alarmiert. Sie  erprobten einen umfangreichen Innenangriff und eine m\u00f6glichst  schnelle R\u00e4umung des Geb\u00e4udes. Im weiteren Verlauf der \u00dcbung galt es  insgesamt acht Personen zu finden, zu retten und anschlie\u00dfend zu  versorgen.     Um das Szenario m\u00f6glichst realit\u00e4tsnah erscheinen zu lassen wurde  nicht mit Kunstblut gespart. F\u00fcnf Statisten der DRK-Jugendgruppe  standen daf\u00fcr zur Verf\u00fcgung und lieferten eine b\u00fchnenreife Show ab.     Abgesehen von dem Spa\u00df, den alle Beteiligten dabei hatten, sind  solche \u00dcbungen f\u00fcr Einsatzkr\u00e4fte immens wichtig um auch auf  schwierige Einsatzlagen richtig reagieren zu k\u00f6nnen.     Unser Dank gilt an dieser Stelle der Leitung des  Seniorenruhesitzes, die allen Einsatzkr\u00e4ften damit eine M\u00f6glichkeit  gegeben hat, eine nicht allt\u00e4gliche Situation zu trainieren.     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Hzgt. Lauenburg Thomas Grimm Telefon: 0160\/1188910 E-Mail: tel@kfv-herzogtum-lauenburg.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/68033\/2829983\/fw-rz-grossuebung-von-feuerwehren-und-drk-in-alt-moelln\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Alt M\u00f6lln (ots)- Kreis Herzogtum Lauenburg 13.09.2014 \/ 8:50 Uhr Unheimlich lag der k\u00fcnstliche Rauch \u00fcber dem<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-162995","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/162995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=162995"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/162995\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=162995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=162995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=162995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}