{"id":163545,"date":"2014-02-17T08:00:05","date_gmt":"2014-02-17T08:00:05","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/02\/fw-oh-lensahn-carport-und-ferienwohnung-brennen-1319\/"},"modified":"2014-02-17T08:00:05","modified_gmt":"2014-02-17T08:00:05","slug":"fw-oh-lensahn-carport-und-ferienwohnung-brennen-1319","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-lensahn-carport-und-ferienwohnung-brennen-1319\/","title":{"rendered":"FW-OH: Lensahn: Carport und Ferienwohnung brennen"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Als die Feuerwehr eintraf standen PKW und Carport bereits in Vollbrand.\nFoto: Hartmut Junge\" src=\"http:\/\/www.presseportal.de\/bild\/274460-preview-pressemitteilung-dsc01781.jpg\" \/><\/p>\n<p>Lensahn (ots) &#8211;      Ein Feuer hielt am Sonntagnachmittag die Feuerwehren der Gemeinde  Lensahn in Atem. Gegen  13.20 Uhr wurde der Rettungsleitstelle S\u00fcd  der Brand eines Carports in der L\u00fcbecker Stra\u00dfe in Lensahn gemeldet.  Als die Feuerwehr wenige Minuten sp\u00e4ter an der Einsatzstelle eintraf  standen der Carport und der darin untergestellte PKW bereits in  Vollbrand.<!--more--> Durch den starken Wind mit Sturmb\u00f6en hatte das Feuer  auch schon auf den Dachstuhl eines in unmittelbarer baulicher  Nachbarschaft stehenden Einfamilienhauses mit angebauter  Ferienwohnung auf einem Nachbargrundst\u00fcck \u00fcbergegriffen. Nur durch  einen massiven L\u00f6scheinsatz unter Atemschutz konnte das Feuer auf den Carport und den Dachstuhl der benachbarten Ferienwohnung begrenzt   werden. Das gef\u00e4hrdete Einfamilienhaus konnte nahezu unbeschadet  gerettet werden und ist weiterhin bewohnbar. Die Bewohner beider  Einfamilienh\u00e4user kamen mit einem geh\u00f6rigen Schrecken, aber  unverletzt davon. Im Einsatz waren die Feuerwehren Lensahn,  Lensahnerhof, Sipsdorf und Wahrendorf. Wegen der gr\u00f6\u00dferen Ausdehnung  der Einsatzstelle auf zwei verschiedenen Grundst\u00fccken wurden  vorsichtshalber eine zweite Drehleiter und weitere  Atemschutzger\u00e4tetr\u00e4ger der Feuerwehr Oldenburg angefordert. Au\u00dferdem  waren zwei Rettungswagen, zwei Not\u00e4rzte und die Polizei an der  Einsatzstelle. F\u00fcr die Dauer des Feuerwehreinsatzes musste die  Kreisstra\u00dfe im Zuge der Ortsdurchfahrt Lensahn voll gesperrt werden.     Im Anhang finden Sie zwei Fotos von der Einsatzstelle. Honorarfrei f\u00fcr redaktionelle Zwecke, gegen Nennung des Autoren. Fotos: Hartmut  Junge     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Ostholstein Kreisgesch\u00e4ftsstelle B\u00e4derstrasse 47 23738 Lensahn Pressedienst HBM Hartmut Junge Telefon: 0172 413 73 24 E-Mail: hartmut.junge@kfv-oh.org www.kfv-oh.org<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/56143\/2665949\/fw-oh-lensahn-carport-und-ferienwohnung-brennen\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Ein Feuer hielt am Sonntagnachmittag die Feuerwehren der Gemeinde Lensahn in Atem. Gegen 13.20 Uhr wurde der<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-163545","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/163545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=163545"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/163545\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=163545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=163545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=163545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}