{"id":167474,"date":"2014-09-03T07:37:20","date_gmt":"2014-09-03T07:37:20","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/09\/fw-hl-presseeinladung-wehrfuehrervereidigung-817\/"},"modified":"2014-09-03T07:37:20","modified_gmt":"2014-09-03T07:37:20","slug":"fw-hl-presseeinladung-wehrfuehrervereidigung-817","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-hl-presseeinladung-wehrfuehrervereidigung-817\/","title":{"rendered":"FW-HL: Presseeinladung: Wehrf\u00fchrervereidigung"},"content":{"rendered":"<p>L\u00fcbeck (ots) &#8211; Sehr geehrte Damen und Herren,     hiermit laden wir Sie herzlich zur diesj\u00e4hrigen Vereidigung der  Wehrf\u00fchrer ein.     Die Vereidigung der sechs Funktionstr\u00e4ger findet statt am Termin:  Montag, den 08.09.2014, um 17 Uhr im Ort: Rathaus, Audienzsaal  Treffpunkt: 16:45 Uhr Treffen am Haupteingang zum Rathaus.<!--more-->     F\u00fcr eine kurze R\u00fcckmeldung per Mail, wenn Sie kommen, w\u00fcrde ich  mich freuen.     Folgende Funktionstr\u00e4ger werden vereidigt:     1. Stellv. Stadtwehrf\u00fchrer: FF-Israelsdorf   Walter Gaul        (Wiederwahl)     2. Wehrf\u00fchrer: FF-Kronsforde  Torsten Frobel (Neuwahl) FF-B\u00fcssau         Axel L\u00fcth (Wiederwahl)     3. Stellvertretende Wehrf\u00fchrer: FF-Sch\u00f6nb\u00f6cken        Jens Gerwien       (Wiederwahl) FF-Schlutup                 Thorsten Persohn        (Wiederwahl) FF-Siems                      Florian Schuster        (Neuwahl)     Mit freundlichen Gr\u00fc\u00dfen     LM Bj\u00f6rn von Mateffy     Fachwart \u00d6ffentlichkeitsarbeit     R\u00fcckfragen bitte an:  Feuerwehr L\u00fcbeck Team Pressebetreuer 23554 L\u00fcbeck &#8211; Pressebetreuer &#8211; Bj\u00f6rn von Mateffy Telefon: 0151 \/ 161 33333 E-Mail: b.mateffy@stfv-hl.de http:\/\/www.stfv-hl.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/52865\/2821669\/fw-hl-presseeinladung-wehrfuehrervereidigung\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00fcbeck (ots) &#8211; Sehr geehrte Damen und Herren, hiermit laden wir Sie herzlich zur diesj\u00e4hrigen Vereidigung der Wehrf\u00fchrer ein. Die<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-167474","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/167474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=167474"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/167474\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=167474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=167474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=167474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}