{"id":168192,"date":"2014-09-26T12:00:14","date_gmt":"2014-09-26T12:00:14","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2014\/09\/pol-sh-afb-vereidigung-von-dienstanfaengern-bei-der-pd-afb-in-eutin-am-28-09-2014-730\/"},"modified":"2014-09-26T12:00:14","modified_gmt":"2014-09-26T12:00:14","slug":"pol-sh-afb-vereidigung-von-dienstanfaengern-bei-der-pd-afb-in-eutin-am-28-09-2014-730","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-vereidigung-von-dienstanfaengern-bei-der-pd-afb-in-eutin-am-28-09-2014-730\/","title":{"rendered":"POL-SH-AFB: Vereidigung von Dienstanf\u00e4ngern bei der PD AFB in Eutin am 28.09.2014"},"content":{"rendered":"<p>Eutin (ots) &#8211; Am Sonntag, 28.09.2014, findet in Eutin bei der  Polizeidirektion f\u00fcr Aus- und Fortbildung und Bereitschaftspolizei  (PD AFB) die feierliche Vereidigung von 273 Dienstanf\u00e4ngerinnen und  Dienstanf\u00e4ngern statt. Ab 10:00 Uhr findet in den Kraftfahrzeughallen ein Gottesdienst, den Auszubildende ma\u00dfgeblich mitgestalten, statt.<!--more-->  Der eigentliche Festakt der Vereidigung beginnt um 11:30 Uhr. Begr\u00fc\u00dft werden die Anwesenden durch den Leitenden Polizeidirektor J\u00fcrgen  Funk, Leiter der PD AFB. Der Landespolizeidirektor Ralf H\u00f6hs wird ein Gru\u00dfwort sprechen. Anschlie\u00dfend h\u00e4lt der Staatssekret\u00e4r im  Innenministerium SH Bernd K\u00fcpperbusch die Vereidigungsansprache.  Musikalisch begleitet die Polizei-Big-Band die Veranstaltung.     Ich lade Sie als Medienvertreter zu dieser nicht-\u00f6ffentlichen  Veranstaltung ein.     R\u00fcckfragen bitte an:  Polizeidirektion f\u00fcr Aus- und Fortbildung und f\u00fcr die  Bereitschaftspolizei Schleswig-Holstein R\u00fcdiger Schwarz Telefon: 04521 81 209 E-Mail: ruediger.schwarz1@polizei.landsh.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/43685\/2840570\/pol-sh-afb-vereidigung-von-dienstanfaengern-bei-der-pd-afb-in-eutin-am-28-09-2014\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; Am Sonntag, 28.09.2014, findet in Eutin bei der Polizeidirektion f\u00fcr Aus- und Fortbildung und Bereitschaftspolizei (PD AFB)<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-168192","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/168192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=168192"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/168192\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=168192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=168192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=168192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}