{"id":184002,"date":"2015-02-27T17:35:14","date_gmt":"2015-02-27T17:35:14","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/index.php\/fw-oh-ein-schwerverletzter-und-zwei-tote-bei-schwerem-verkehrsunfall-527\/"},"modified":"2015-02-27T17:35:14","modified_gmt":"2015-02-27T17:35:14","slug":"fw-oh-ein-schwerverletzter-und-zwei-tote-bei-schwerem-verkehrsunfall-527","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-ein-schwerverletzter-und-zwei-tote-bei-schwerem-verkehrsunfall-527\/","title":{"rendered":"FW-OH: Ein Schwerverletzter und zwei Tote bei schwerem Verkehrsunfall"},"content":{"rendered":"<p>Lensahn (ots) &#8211; Auf der L176 zwischen Hassendorfer Kreuz und  Hutzfeld kam es heute Nachmittag (27.02.2015)zum Frantalzusammensto\u00df  zwischen einem Kleinbus und einem PKW. Dabei wurden alle drei  Insassen in beiden Fahrzeugen eingeklemmt und mussten von der  Feuerwehr aus ihren Fahrzeugen befreit werden. Die beiden Insassen  des PKW konnten nur tot aus dem Fahrzeug geborgen werden.<!--more--> Der Fahrer  des Kleinbusses kam mit schweren Verletzung in ein Krankenhaus. Neben den Freiwilligen Feuerwehren der Gemeinde Bosau war die Freiwillige  Feuerwehr Eutin zur Unterst\u00fctzung eingesetzt.     siehe auch Pressemitteilung der Polizeidirektion L\u00fcbeck:  27.02.2015 OH-L176, Eutin, Hutzfeld Schwerer Verkehrsunfall endet f\u00fcr zwei Personen t\u00f6dlich     Bei einem schweren Verkehrsunfall auf der L176 in H\u00f6he  Hassendorfer Kreuz am Freitag (27.02.2015) kam es zu einem  Frontalzusammensto\u00df zwischen zwei Fahrzeugen. Dabei starben zwei  Personen, eine weitere wurde schwer verletzt.     Nach derzeitigem Sachstand lenkte ein Fahrzeugf\u00fchrer seinem VW Bus die L176 von Eutin in Richtung Hutzfeld. Aus bisher nicht bekannten  Gr\u00fcnden geriet der Fahrer in den Gegenverkehr und kollidierte mit  einem entgegenkommenden VW Golf. In dem Fahrzeug befanden sich zwei  Personen. Die Fahrzeuginsassen wurden im Wagen eingeklemmt und  konnten erst durch die Rettungskr\u00e4fte befreit werden. Die Personen,  \u00fcber deren Identit\u00e4t noch keine gesicherten Erkenntnisse vorliegen,  erlagen noch am Unfallort ihren Verletzungen.     Der Fahrer des VW Busses wurde durch den Unfall ebenfalls schwer  verletzt und musste mit dem Rettungshubschrauber ins Krankenhaus  gebracht werden.     Staatsanwaltschaft L\u00fcbeck und Polizei nahmen die Ermittlungen auf. Ein Sachverst\u00e4ndiger wurde mit der Fertigung eines Gutachtens  beauftragt.     Zwischenzeitlich kam es zu einer Vollsperrung der Landesstra\u00dfe  176.     Julia Engewald     R\u00fcckfragen bitte an:  Kreisfeuerwehrverband Ostholstein Kreisgesch\u00e4ftsstelle B\u00e4derstrasse 47 23738 Lensahn Pressedienst HBM Hartmut Junge Telefon: 0172 413 73 24 E-Mail: hartmut.junge@kfv-oh.org www.kfv-oh.org<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/2961027\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Auf der L176 zwischen Hassendorfer Kreuz und Hutzfeld kam es heute Nachmittag (27.02.2015)zum Frantalzusammensto\u00df zwischen einem Kleinbus<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-184002","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/184002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=184002"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/184002\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=184002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=184002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=184002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}