{"id":188754,"date":"2009-10-23T10:55:22","date_gmt":"2009-10-23T10:55:22","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-sl-erste-feuerwehr-partnerschaft-deutschland-daenemark-477\/"},"modified":"2009-10-23T10:55:22","modified_gmt":"2009-10-23T10:55:22","slug":"fw-sl-erste-feuerwehr-partnerschaft-deutschland-daenemark-477","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-sl-erste-feuerwehr-partnerschaft-deutschland-daenemark-477\/","title":{"rendered":"FW-SL: Erste Feuerwehr-Partnerschaft Deutschland \/ D\u00e4nemark"},"content":{"rendered":"<p>Schleswig (ots) &#8211; Sperrfrist 02.11.2009 17:00 Uhr     Nach fast 25j\u00e4hriger praktischer Aus\u00fcbung wird die Partnerschaft  der Freiwilligen Feuerwehren Ellund (Bundesrepublik Deutschland) und  Fr\u00f6slee (D\u00e4nemark) am 02.November 2009 im Rahmen eines Festaktes mit  der Unterzeichnung einer Partnerschaftsurkunde offiziell besiegelt.<!--more-->     Die Unterzeichnung der Urkunde findet um 17.00 Uhr auf dem  Festplatz in Fr\u00f6slee (Vestergade 17b, DK 6330 Padborg) statt.     An diesem &#8222;historischen Moment&#8220;, an dem erstmals zwei Feuerwehren  aus Deutschland und D\u00e4nemark ihre langj\u00e4hrigen Zusammenarbeit offiziell  besiegeln werden, werden neben den beiden Wehrf\u00fchrern Oluf  Feddersen-Jessen (Fr\u00f6slee)und Richard Andersen (Ellund) auch die  betroffenen B\u00fcrgermeister Tove Larsen (Kommune Apenrade) und Dr.  Arthur Christiansen (Gemeinde Handewitt) sowie zahlreiche  Repr\u00e4sentanten von Politik, Verwaltung und den Feuerwehren aus beiden L\u00e4ndern anwesend sein. Beide Wehren verbinden nicht nur die aktuelle Partnerschaft sondern  auch gemeinsame geschichtliche Wurzeln: Die Freiwillige Feuerwehr  Fr\u00f6slee wurde im Jahre 1881 gegr\u00fcndet. Zu ihrem L\u00f6schbezirk geh\u00f6rte  von Anfang an die benachbarte Gemeinde Ellund. Dort kam es erst 1890  zur Gr\u00fcndung einer Freiwilligen Feuerwehr. Beide Wehren waren eng miteinander verbunden, da ihre Mitglieder auch beide dem gemeinsamen  Kirchspiel Handewitt zugeh\u00f6rten. Aus dieser Zeit sind viele  gemeinsame \u00dcbungen und Eins\u00e4tze dokumentiert. Mit der Grenz\u00e4nderung im Jahre 1920 endete das freundschaftliche  Miteinander abrupt. Erst Ende der 80-Jahre begannen sich die beiden  Wehren unter ihren damaligen Wehrf\u00fchrern Ewald Petersen (Ellund) und  Christian Nissen (Fr\u00f6slee)wieder vorsichtig aufeinander zu zugehen.  Gemeinsame \u00dcbungen waren zu dieser Zeit nur unter erschwerten  Bedingungen m\u00f6glich. Sie wurden beispielsweise eine \u00dcbung auf dem Anwesen Vilmkj\u00e6r so geplant, da\u00df Fr\u00f6slee im d\u00e4nischen  und Ellund im deutschen Teil des Anwesens \u00fcbte. Das anschlie\u00dfende kameradschaftliche Beisammensein fand auf der  Grenzstra\u00dfe statt, so da\u00df keiner der Kameraden die Grenze  \u00fcberschritt. Das Ganze wurde vom Zoll und dem Grenzschutz aufmerksam  beobachtet. In der Folgezeit wurden die Beziehungen kontinuierlich  vertieft und ausgebaut. Nach der \u00d6ffnung der Grenze im Jahre 2001 kam es unter den jetzigen Wehrf\u00fchrern zu den ersten grenz\u00fcberschreitenden \u00dcbungen in den Kerngebieten der beiden Orte. Heute sind diese j\u00e4hrlichen \u00dcbungen sowie die gemeinsame Ausbildung  auf dem \u00dcbungsgel\u00e4nde der d\u00e4nischen Katastrophenschutzschule in  Tingleff ein fester Bestandteil der Ausbildung beider Wehren. Ziel der Partnerschaftserkl\u00e4rung ist u.a. die gegenseitige  Unterst\u00fctzung in Einsatz und Katastrophenf\u00e4llen als Aufgabe beider  Wehren festzulegen. Zur Zeit fehlen leider noch die rechtlichen  Grundlagen auf beiden Seiten der Grenze um dieses Ziel auch als festen Bestandteil der t\u00e4glichen Feuerwehrarbeit zu sehen.  Noch sind Brandschutz und Unfallversicherung nur national  ausgerichtet und machen an den nicht mehr vorhandenen Grenzen halt.  Es ist f\u00fcr die betroffenen B\u00fcrger dieser Grenzregion jedoch  unverst\u00e4ndlich, dass es in einem zusammenwachsenden Europa ohne Grenzen den Feuerwehrleuten des Nachbarortes offiziell nicht  gestattet ist sofort zur Hilfe eilen zu d\u00fcrfen, nur weil eine  Staatsgrenze auf dem Anmarschweg liegt.     Mit der feierlichen Partnerschaftserkl\u00e4rung m\u00f6chten wir ein Signal setzen f\u00fcr ein gemeinsames Miteinander in einem vereinten Europa.     Kontakt: Oberbrandmeister Richard Andersen, Ellunder Stra\u00dfe 28a, 24983  Handewitt Tel: 04608-1565 oder 0175-5151505 email: richardandersen@t-online.de     R\u00fcckfragen bitte an:  Oberbrandmeister Richard Andersen, Ellunder Stra\u00dfe 28a, 24983 Handewitt Tel: 04608-1565 oder 0175-5151505 email: richardandersen@t-online.deKreisfeuerwehrverband Schleswig-Flensburg<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/68035\/1498470\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schleswig (ots) &#8211; Sperrfrist 02.11.2009 17:00 Uhr Nach fast 25j\u00e4hriger praktischer Aus\u00fcbung wird die Partnerschaft der Freiwilligen Feuerwehren Ellund (Bundesrepublik<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-188754","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/188754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=188754"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/188754\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=188754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=188754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=188754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}