{"id":190702,"date":"2015-04-20T11:10:00","date_gmt":"2015-04-20T11:10:00","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/wsp-sh-seemann-bei-anlegemanoever-in-der-schleuse-brunsbuettel-schwer-verletzt-484\/"},"modified":"2015-04-20T11:10:00","modified_gmt":"2015-04-20T11:10:00","slug":"wsp-sh-seemann-bei-anlegemanoever-in-der-schleuse-brunsbuettel-schwer-verletzt-484","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/wsp-sh-seemann-bei-anlegemanoever-in-der-schleuse-brunsbuettel-schwer-verletzt-484\/","title":{"rendered":"WSP-SH: Seemann bei Anlegeman\u00f6ver in der Schleuse Brunsb\u00fcttel schwer verletzt"},"content":{"rendered":"<p>Brunsb\u00fcttel (ots) &#8211; Schwere Gesichtsverletzungen hatte sich ein  44j\u00e4hriger philippinischer Seemann des MS &#8222;ABIS CUXHAVEN&#8220; beim  Anlegeman\u00f6ver in der Gro\u00dfen S\u00fcdschleuse durch eine rei\u00dfende  Festmacherleine zugezogen.<!--more--> Der 144 Meter lange unter der Flagge der  Niederlande fahrende Frachter war in der Nacht zu Sonntag gegen 01.30 Uhr auf der Reise von Stralsund nach Immingham \/UK als letztes Schiff in die Gro\u00dfe S\u00fcdschleuse Brunsb\u00fcttel eingelaufen und wollte an der  Mittelmauer festmachen. Die Vorspring war bereits an die Festmacher  \u00fcbergeben und sollte lose mitgefiert werden. Dabei verhakte sich die  Leine an einer der Winden und kam stramm. Als das Tau schlie\u00dflich  riss, wurde der Decksmann von dem einen Ende am Kopf getroffen und  erheblich im Gesicht verletzt. Die Erstversorgung des Verletzten  erfolgte durch einen Brunsb\u00fctteler Notarzt in der Schiffsambulanz.  Danach wurde der Seemann in das Universit\u00e4tskrankenhaus Eppendorf  verbracht. Lebensgefahr bestand nicht. Die Wasserschutzpolizei hat  die Ermittlungen aufgenommen. Das Schiff konnte die Reise  anschlie\u00dfend in Richtung Bestimmungshafen fortsetzen.   ots Originaltext: Landespolizeiamt Schleswig-Holstein &#8211; Abt. 4 &#8211; Wasserschutzpolizei  Digitale Pressemappe: http:\/\/www.polizeipresse.de\/p_story.htx?firmaid=43800  R\u00fcckfragen bitte an:  Landespolizeiamt Schleswig-Holstein Abt. 4 Wasserschutzpolizei Schleswig-Holstein Wasserschutzpolizeirevier Brunsb\u00fcttel Norbert Vallentin  Telefon: 04852\/900-21<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/43800\/3000750\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brunsb\u00fcttel (ots) &#8211; Schwere Gesichtsverletzungen hatte sich ein 44j\u00e4hriger philippinischer Seemann des MS &#8222;ABIS CUXHAVEN&#8220; beim Anlegeman\u00f6ver in der Gro\u00dfen<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-190702","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/190702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=190702"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/190702\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=190702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=190702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=190702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}