{"id":191737,"date":"2014-02-20T11:08:20","date_gmt":"2014-02-20T11:08:20","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/pol-sh-afb-polizisten-auf-der-hubertushoehe-werden-potentielle-lebensretter-1978\/"},"modified":"2014-02-20T11:08:20","modified_gmt":"2014-02-20T11:08:20","slug":"pol-sh-afb-polizisten-auf-der-hubertushoehe-werden-potentielle-lebensretter-1978","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-polizisten-auf-der-hubertushoehe-werden-potentielle-lebensretter-1978\/","title":{"rendered":"POL-SH-AFB: Polizisten auf der Hubertush\u00f6he werden potentielle Lebensretter"},"content":{"rendered":"<p>Eutin (ots) &#8211; Polizisten auf der Hubertush\u00f6he in Eutin werden  potentielle Lebensretter     Anfang Februar kam es polizeiintern zu einem Aufruf, sich als  Knochenmarkspender typisieren zu lassen. Hintergrund war die  Leuk\u00e4mieerkrankung eines Kollegen im Raum Schleswig, was unseren  Innenminister, Herrn Breitner, spontan veranlasste, die  Schirmherrschaft dieser Aktion zu \u00fcbernehmen.<!--more--> Die PD AFB, unterst\u00fctzt durch Kollegen einiger benachbarter Dienststellen, nahm dies zum  Anlass, eine Typisierungsaktion innerhalb der Polizei auf der  Hubertush\u00f6he durchzuf\u00fchren. 408! Kollegen folgten dem Aufruf eine  Speichelprobe abzugeben und sich bei der Deutschen  Knochenmarkspenderdatei (DKMS) als potenzielle Spender registrieren  zu lassen. Bei \u00dcbereinstimmung der Gewebemerkmale zwischen Spender  und Patient kann das Knochenmark f\u00fcr eine \u00dcbertragung von Stammzellen herangezogen werden, um das Leben von Blutkrebspatienten zu retten.  Durch die Registrierung bei der DKMS besteht neue Hoffnung f\u00fcr den  erkrankten Kollegen aber auch viele andere Erkrankte. Vielleicht  animiert diese Aktion auch andere Teile der Bev\u00f6lkerung, sich als  m\u00f6gliche Lebensretter typisieren zu lassen.     R\u00fcckfragen bitte an:  Polizeidirektion f\u00fcr Aus- und Fortbildung und f\u00fcr die  Bereitschaftspolizei Schleswig-Holstein Burkhard Buchholz Telefon: 04521 81 218 E-Mail: burkhard.buchholz@polizei.landsh.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/43685\/2669244\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; Polizisten auf der Hubertush\u00f6he in Eutin werden potentielle Lebensretter Anfang Februar kam es polizeiintern zu einem Aufruf,<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-191737","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/191737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=191737"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/191737\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=191737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=191737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=191737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}