{"id":193791,"date":"2015-07-03T07:07:00","date_gmt":"2015-07-03T07:07:00","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-bundespolizei-see-leistet-schnelle-hilfe-379\/"},"modified":"2015-07-03T07:07:00","modified_gmt":"2015-07-03T07:07:00","slug":"bpoli-see-bundespolizei-see-leistet-schnelle-hilfe-379","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-bundespolizei-see-leistet-schnelle-hilfe-379\/","title":{"rendered":"BPOLI-See: Bundespolizei See leistet schnelle Hilfe"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Die Einsatzkr\u00e4fte bei der \u00dcberfahrt zur F\u00e4hre\" src=\"http:\/\/www.presseportal.de\/bild\/329074-preview-pressemitteilung-dscf2045.jpg\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Am 02.07.15 um 17:45 Uhr wurde von dem im Seestreifendienst  befindlichen Einsatzschiff der Bundespolizeiinspektion See Neustadt  in Holstein &#8220; Bad D\u00fcben&#8220; ein Seefunkgespr\u00e4ch zwischen dem  schwedischen RoRo &#8211; F\u00e4hrschiff &#8222;Huckleberry Finn&#8220; und der  Seenotleistelle der Deutschen Gesellschaft zur Rettung  Schiffbr\u00fcchiger (DGzRS) &#8222;MRCC Bremen&#8220; mitgeh\u00f6rt: -1- verletzte Person <!--more-->(schwedisches Crewmitglied) an Bord ben\u00f6tige dringendst \u00e4rztliche  Hilfe. Die verletzte Person m\u00fcsste schnellst m\u00f6glich evakuiert  werden. Weitere Informationen zum Gesundheitszustand lagen zu diesem  Zeitpunkt nicht vor.     Die &#8222;Bad D\u00fcben&#8220; befand sich in unmittelbarer N\u00e4he zur Huckleberry  Finn (0,4 sm Abstand). \u00dcber Seefunkkanal 16 wurde mit &#8222;MRCC Bremen&#8220;  und der &#8222;Huckleberry Finn&#8220; Verbindung aufgenommen und sofortige Hilfe angeboten.     Um 18:15 Uhr wurden zwei Beamte mit Notarztkoffer und weiterer  medizinischer Ausstattung f\u00fcr die Erstversorgung mittels Kontrollboot auf die &#8222;Huckleberry Finn&#8220; zur Hilfeleistung \u00fcbergesetzt.     Gl\u00fcck auch f\u00fcr den Verunfallten, dass sich unter den Passagieren  eine \u00c4rztin befand, die den Patienten mittlerweile mit einer  Ringerlaktatl\u00f6sung stabilisieren konnte. Bei dem Patienten handelte  es sich um ein m\u00e4nnliches Besatzungsmitglied im Alter von 61 Jahren,  der  vor vier Wochen in Schweden am Magen operiert wurde. Die Person  wurde liegend versorgt. Krankheitssymptome: Patient ansprechbar,  spukt Blut, hat innere Blutungen.     Die eingesetzten Beamten unterst\u00fctzten die \u00c4rztin bei der  Stabilisierung \/ Betreuung des Patienten. Nach R\u00fccksprache des  Kapit\u00e4ns der &#8222;Huckleberry Finn&#8220; mit MRCC Bremen wurde der Hafen  Warnem\u00fcnde angelaufen. Die eingesetzten Beamten und die \u00c4rztin  \u00fcbergaben an der Passagierpier \/ Pier 7 in Warnem\u00fcnde den Patienten  um 19:30 Uhr an den bereits im Vorwege alarmierten RTW und Notarzt,  der den Patienten unverz\u00fcglich ins Krankenhaus verbrachte.     Einsatzende: 19:50 Uhr Nach Einsatzende bedankte sich der Kapit\u00e4n  der &#8222;Huckleberry Finn&#8220; \u00fcber UKW Seefunk bei der Besatzung der &#8222;Bad  D\u00fcben&#8220; f\u00fcr die sofortige, schnelle, kompetente und professionelle  Hilfe.     R\u00fcckfragen bitte an:  Bundespolizeiinspektion See Neustadt \/ Holstein Pressestelle Sascha Herz Telefon: 04561 \/ 40715 &#8211; 14 Fax: 04561 \/ 40715 &#8211; 10 E-Mail: sascha.herz@polizei.bund.de www.bundespolizei.de  Die Bundespolizeidirektion Bad Bramstedt nimmt als Bundesbeh\u00f6rde ihre Aufgaben in Schleswig-Holstein, Mecklenburg-Vorpommern sowie in Nord- und Ostsee und anlassbezogen dar\u00fcber hinaus wahr.    Dazu sind ihr als operative Dienststellen die  Bundespolizeiinspektionen in Flensburg, Kiel, Rostock, Stralsund und  Pasewalk sowie die Bundespolizeiinspektion Kriminalit\u00e4tsbek\u00e4mpfung  Rostock und eine Mobile Kontroll- und \u00dcberwachungseinheit  unterstellt. Mit den Bundespolizeiinspektionen See in Neustadt in  Holstein, Warnem\u00fcnde und Cuxhaven verf\u00fcgt sie als einzige  Bundespolizeidirektion \u00fcber eine maritime Einsatzkomponente  &#8222;Bundespolizei See&#8220;, um die Seegrenze in der Nord- und Ostsee  (Schengen-Au\u00dfengrenze) zu \u00fcberwachen.   Die Bundespolizeidirektion Bad Bramstedt besch\u00e4ftigt insgesamt ca.  2600 Mitarbeiterinnen und Mitarbeiter, darunter Polizeibeamte,  Verwaltungsbeamte und Tarifbesch\u00e4ftigte. Auf Grundlage des Bundespolizeigesetzes und anderer Gesetze nimmt sie umfangreiche und vielf\u00e4ltige Aufgaben wahr.   Dazu geh\u00f6ren insbesondere: &#8211;  der grenzpolizeiliche Schutz des Bundesgebietes, &#8211; die bahnpolizeilichen Aufgaben &#8211; die grenzpolizeilichen, schifffahrtspolizeilichen und  umweltpolizeilichen Aufgaben in Nord- und Ostsee.   Weitere Informationen zur Bundespolizei und zur  Bundespolizeidirektion Bad Bramstedt erhalten Sie unter  www.bundespolizei.de.<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/3062559\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Am 02.07.15 um 17:45 Uhr wurde von dem im Seestreifendienst befindlichen Einsatzschiff der Bundespolizeiinspektion See Neustadt in<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-193791","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/193791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=193791"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/193791\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=193791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=193791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=193791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}