{"id":193857,"date":"2014-08-02T22:57:16","date_gmt":"2014-08-02T22:57:16","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-bundespolizeischiff-rettet-gekenterte-sportbootfahrer-aus-der-ostsee-2045\/"},"modified":"2014-08-02T22:57:16","modified_gmt":"2014-08-02T22:57:16","slug":"bpoli-see-bundespolizeischiff-rettet-gekenterte-sportbootfahrer-aus-der-ostsee-2045","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-bundespolizeischiff-rettet-gekenterte-sportbootfahrer-aus-der-ostsee-2045\/","title":{"rendered":"BPOLI-See: Bundespolizeischiff rettet gekenterte Sportbootfahrer aus der Ostsee"},"content":{"rendered":"<p>Neustadt (ots) &#8211; Am Samstag den 2. August  war das  Bundespolizeischiff BP23 &#8222;BAD D\u00dcBEN&#8220; der Bundespolizeiinspektion See  Neustadt in Holstein bei starken \u00f6stlichen Winden gleich an drei  Seenoteins\u00e4tzen beteiligt.     Gegen Mittag kenterte vor Olpenitz ein Ruderboot mit 5 Personen an Bord.<!--more--> Vier Personen wurden vom Seenotrettungskreuzer &#8222;NIS RANDERS&#8220;  und einem Sportboot aufgenommen und eine Person wurde vom Tochterboot der &#8222;BAD D\u00dcBEN&#8220; gerettet. Alle Personen konnten unverletzt in  Olpenitz an Land gebracht werden.     Am sp\u00e4ten Nachmittag kenterte dann direkt neben der &#8222;BAD D\u00dcBEN&#8220;  ein mit einer Person besetztes Motorboot in der Flensburger F\u00f6rde bei Langballigau. Der d\u00e4nische Staatsb\u00fcrger konnte unverletzt gerettet,  das Boot sicher geborgen und nach Langballigau verbracht werden.     In den Abendstunden wiederum beteiligte sich das  Bundespolizeischiff BP 23 dann zusammen mit dem Seenotrettungsboot  &#8222;WERNER KUNZE&#8220; an der Suche nach vermisst gemeldeten Personen,  nachdem ein herrenloses Schlauchboot in der Flensburger Au\u00dfenf\u00f6rde  angetrieben wurde. Die Suche wurde wenig sp\u00e4ter eingestellt, da die  Vermisstenmeldung aufgehoben wurde.     R\u00fcckfragen bitte an:  Bundespolizeiinspektion See Neustadt in Holstein \u00d6ffentlichkeitsarbeit Bianca Diekert Telefon: 04561 \/ 4071 &#8211; 514 Fax: 04561 \/ 4071 &#8211; 510 E-Mail: bianca.diekert@polizei.bund.de www.bundespolizei.de  Die Bundespolizeidirektion Bad Bramstedt nimmt als Bundesbeh\u00f6rde ihre Aufgaben in Schleswig-Holstein, Mecklenburg-Vorpommern sowie in Nord- und Ostsee und anlassbezogen dar\u00fcber hinaus wahr.    Dazu sind ihr als operative Dienststellen die  Bundespolizeiinspektionen in Flensburg, Kiel, Rostock, Stralsund und  Pasewalk sowie die Bundespolizeiinspektion Kriminalit\u00e4tsbek\u00e4mpfung  Rostock und eine Mobile Kontroll- und \u00dcberwachungseinheit  unterstellt. Mit den Bundespolizeiinspektionen See in Neustadt in  Holstein, Warnem\u00fcnde und Cuxhaven verf\u00fcgt sie als einzige  Bundespolizeidirektion \u00fcber eine maritime Einsatzkomponente  &#8222;Bundespolizei See&#8220;, um die Seegrenze in der Nord- und Ostsee  (Schengen-Au\u00dfengrenze) zu \u00fcberwachen.   Die Bundespolizeidirektion Bad Bramstedt besch\u00e4ftigt insgesamt ca.  2600 Mitarbeiterinnen und Mitarbeiter, darunter Polizeibeamte,  Verwaltungsbeamte und Tarifbesch\u00e4ftigte. Auf Grundlage des Bundespolizeigesetzes und anderer Gesetze nimmt sie umfangreiche und vielf\u00e4ltige Aufgaben wahr.   Dazu geh\u00f6ren insbesondere: &#8211;  der grenzpolizeiliche Schutz des Bundesgebietes, &#8211; die bahnpolizeilichen Aufgaben &#8211; die grenzpolizeilichen, schifffahrtspolizeilichen und  umweltpolizeilichen Aufgaben in Nord- und Ostsee.   Weitere Informationen zur Bundespolizei und zur  Bundespolizeidirektion Bad Bramstedt erhalten Sie unter  www.bundespolizei.de.<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/2798672\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Am Samstag den 2. August war das Bundespolizeischiff BP23 &#8222;BAD D\u00dcBEN&#8220; der Bundespolizeiinspektion See Neustadt in Holstein<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-193857","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/193857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=193857"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/193857\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=193857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=193857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=193857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}