{"id":203858,"date":"2015-08-07T17:19:42","date_gmt":"2015-08-07T17:19:42","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/wsp-sh-brennende-segelyacht-im-binnenhafen-brunsbuettel-519\/"},"modified":"2015-08-07T17:19:42","modified_gmt":"2015-08-07T17:19:42","slug":"wsp-sh-brennende-segelyacht-im-binnenhafen-brunsbuettel-519","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/wsp-sh-brennende-segelyacht-im-binnenhafen-brunsbuettel-519\/","title":{"rendered":"WSP-SH: Brennende Segelyacht im Binnenhafen Brunsb\u00fcttel"},"content":{"rendered":"<p>Brunsb\u00fcttel (ots) &#8211; Am Nachmittag des 07.08.2015 brach an Bord  einer Segelyacht ein Feuer aus. Der Skipper befand sich mit seiner  Ehefrau an Bord und sie warteten im Binnenhafen Brunsb\u00fcttel auf die  Schleusung, als es pl\u00f6tzlich zur Rauchentwicklung im Inneren der  Yacht kam. Die Rauchentwicklung wurde schnell intensiver und kurz  darauf stand das Boot in Flammen.<!--more--> Die Segler konnten sich durch einen Sprung ins Wasser retten und wurden von der Besatzung einer anderen  Yacht geborgen. Bei der Frau besteht der Verdacht einer leichten  Rauchgasvergiftung, w\u00e4hrend ihr Ehemann unverletzt ist. Beide wurden  vorsorglich ins WKK Brunsb\u00fcttel eingeliefert. Das Feuer wurde durch  die Feuerwehr Brunsb\u00fcttel gel\u00f6scht und die v\u00f6llig ausgebrannte Yacht  in den Binnenhafen geschleppt. Nach Aussage des Ehepaares sei das  Feuer im Maschinenraum entstanden. Nach ersten Ermittlungen ist ein  technischer Defekt urs\u00e4chlich f\u00fcr den Brand. Die Feuerwehr war mit 33 Einsatzkr\u00e4ften im Einsatz, auch unter Zuhilfenahme eines Schleppers.   ots Originaltext: Landespolizeiamt Schleswig-Holstein &#8211; Abt. 4 &#8211; Wasserschutzpolizei  Digitale Pressemappe: http:\/\/www.polizeipresse.de\/p_story.htx?firmaid=43800  <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/43800\/3091981\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brunsb\u00fcttel (ots) &#8211; Am Nachmittag des 07.08.2015 brach an Bord einer Segelyacht ein Feuer aus. Der Skipper befand sich mit<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-203858","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/203858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=203858"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/203858\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=203858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=203858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=203858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}