{"id":205394,"date":"2015-09-02T13:47:28","date_gmt":"2015-09-02T13:47:28","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-oh-neuer-werbeuftritt-der-feuerwehren-der-gemeinde-scharbeutz-522\/"},"modified":"2015-09-02T13:47:28","modified_gmt":"2015-09-02T13:47:28","slug":"fw-oh-neuer-werbeuftritt-der-feuerwehren-der-gemeinde-scharbeutz-522","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-neuer-werbeuftritt-der-feuerwehren-der-gemeinde-scharbeutz-522\/","title":{"rendered":"FW-OH: Neuer Werbeuftritt der Feuerwehren der Gemeinde Scharbeutz"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"B\u00fcrgermeister und Gemeindewehrf\u00fchrung pr\u00e4sentieren den neuen Werbeauftritt\" src=\"http:\/\/cache.pressmailing.net\/thumbnail\/story_big\/070cb12b-ba3a-443b-b176-183f4547fb68\/image\" \/><\/p>\n<p>Lensahn (ots) &#8211;     GEMEINDE SCHARBEUTZ DER B\u00dcRGERMEISTER Pressemitteilung der  Gemeindeverwaltung Scharbeutz, Am B\u00fcrgerhaus 2, 23683 Scharbeutz Frau Nicole Schaub, Ordnungsamt, nicole.schaub@gemeinde-scharbeutz.de,  Tel. 04503\/7709-84, Fax. 04503\/7709-1184, www.Gemeinde-Scharbeutz.<!--more-->de     Pressemitteilung vom 02.09.2015     &#8211;\tStarker gemeinsamer neuer Internetauftritt der Feuerwehren &#8211;\t Feuer-Wehrner wirbt brandheiss f\u00fcr neue Mitglieder &#8211;\tWir bleiben  cool, auch wenn es heiss wird     Starker gemeinsamer neuer Internetauftritt der Feuerwehren     Ab dem 02.09.2015 gehen die acht freiwilligen Feuerwehren sowie  die zwei Jugendfeuerwehren der Gemeinde Scharbeutz gemeinsam mit  einem neuen Internetauftritt ins Netz.     &#8222;In Kooperation mit der Gemeindeverwaltung, der Wehrf\u00fchrung und  den einzelnen Wehren ist unter www.Feuerwehren-Gemeinde-Scharbeutz.de jetzt ein gemeinsamer starker Internetauftritt aller 8 Wehren und der zwei Jugendwehren geschaffen worden&#8220;, erl\u00e4utert B\u00fcrgermeister Volker  Owerien. Er hebt hierbei insbesondere das erhebliche Engagement der  Kameraden der Feuerwehr hervor, die ma\u00dfgeblich die Seite mit Leben  gef\u00fcllt haben.     &#8222;Ein moderner strukturierter einheitlicher Auftritt, der dennoch  den jeweiligen Wehren eine weitere individuelle inhaltliche  Gestaltungsm\u00f6glichkeit er\u00f6ffnet&#8220;, freuen sich Gemeindewehrf\u00fchrer  Reinhold Mang und B\u00fcrgermeister unisono.     Zu den Hintergr\u00fcnden des neuen Auftritts f\u00fchrt B\u00fcrgermeister  Volker Owerien aus: &#8222;Wir brauchen mehr Kameraden, die sich in unseren Ortsfeuerwehren engagieren&#8220;. Die aufstrebende Gemeinde Scharbeutz mit Ihren 10 Ortschaften ist mit ihren 8 Wehren f\u00fcr den Notfall gut  ger\u00fcstet. Doch der Augenmerk darf sich nicht nur auf Fahrzeuge und  Einsatzmittel beschr\u00e4nken.  &#8222;Sowohl im Jugend- als auch im  Erwachsenenbereich wird es immer schwieriger, neue Freiwillige zur  \u00dcbernahme eines Ehrenamtes in der Feuerwehr zu finden&#8220;, so  B\u00fcrgermeister Owerien weiter. Der neue Internetauftritt ist  nur ein  Schritt, um die Kameraden zu unterst\u00fctzen und \u00fcber ihre Arbeit zu  informieren. Die T\u00e4tigkeit der Aktiven soll transparenter werden,  aber auch die Kommunikationswege innerhalb der Wehr unterst\u00fctzen.  &#8222;Wir haben in unserer Gemeinde eine Wehr aus freiwilligen Helfern,  d.h. dies sind Ehrenamtler, die, wie du und ich, einem Job nachgehen  und in Ihrer Freizeit f\u00fcr die Allgemeinheit Dienst tun. Dies muss  auch zuk\u00fcnftig weiter gef\u00f6rdert und ausgebaut werden. Ohne  Freiwillige kann im Notfall nicht geholfen werden&#8220;, erkl\u00e4rt  Ordnungsamtsleiter Heiko Laskowski.     Gemeindewehrf\u00fchrer Reinhold Mang und sein Stellvertreter freuen  sich, dass die Arbeit und Leistungen der Kameradinnen und Kameraden  innerhalb der gemeindlichen Gremien und der Gemeindeverwaltung  gesch\u00e4tzt wird und Anerkennung findet.     Erfreut zeigen sich die beiden, dass die Gemeinde Scharbeutz seit  2 Jahren ein umfangreiches Programm zur Mitgliedergewinnung und  -bindung umgesetzt. Es sei keine Selbstverst\u00e4ndlichkeit, dass die  pers\u00f6nlichen Leistungen honoriert und Anreize f\u00fcr den Feuerwehrdienst gegeben werden, so Mang weiter. Jubil\u00e4umsgratifikationen, Zusch\u00fcsse  bei Jugendlichen zum Erwerb von F\u00fchrerscheinen und  kostenlose  Parkausweise seinen nur einige Punkte. Besonders Stolz sind wir auf  unseren &#8222;F\u00fc\u00fcrwehr-Pott&#8220;, f\u00fchrt sein Stellvertreter Markus Rabe aus,  der mit 25.000 EUR von der Gemeinde j\u00e4hrlich zur Verf\u00fcgung gestellt  wird. Aus dem F\u00fc\u00fcrwehr-Pott werden die pers\u00f6nlichen Leistungen mit  Tank- und Essensgutscheinen, Jahreskarten und andere &#8222;Schmankerl  honoriert. Mit dem Budget soll nicht nur den Feuerwehrmitgliedern  selbst, sondern auch deren Angeh\u00f6rige und Familien ein &#8222;Dankesch\u00f6n&#8220;  zukommen, da der Feuerwehrdienst in der heutigen Zeit stark zu Lasten des Familienlebens geht, so B\u00fcrgermeister Volker Owerien  abschlie\u00dfend.     Feuer-Wehrner wirbt brandheiss f\u00fcr neue Mitglieder     Zuk\u00fcnftig wird Feuer-Wehrner als neue Werbefigur brandheiss f\u00fcr  neue Mitglieder werben. Hierf\u00fcr ist eine Marketingseite zur  Erstansprache unter www.feuer-wehrner.de entstanden. Diese soll in  erster Linie Jugendliche und Kinder f\u00fcr eine Mitarbeit bei der  Feuerwehr begeistern.     Wir bleiben cool, auch wenn es heiss wird     Unter diesem Motto veranstalten die Jugendfeuerwehren der Gemeinde Scharbeutz einen Aktionstag, zu dem alle Kinder und Jugendlichen ab 9 Jahren in der Gemeinde Scharbeutz eine pers\u00f6nliche Einladung von  B\u00fcrgermeister Volker Owerien erhalten haben. Sie bekommen am Samstag, den 12. September in der Zeit von 15:00 bis 18:00 Uhr auf dem  Sportplatz in Gleschendorf die M\u00f6glichkeit, alles rund um das Thema  Feuerwehr kennenzulernen &#8222;Teamwork mit Spass, Technik, Action &amp;   Meer&#8220; stehen im Vordergrund, versprechen Gemeindewehrf\u00fchrer Reinhold  Mang und sein Stellvertreter Markus Rabe. An vielen Stationen  bekommen die Kinder und Jugendlichen einen Einblick in die Aufgaben  der Jugendfeuerwehr und k\u00f6nnen selbst ausprobieren, was zu tun ist,  wenn&#8217;s brennt. An Spielstationen haben sie die M\u00f6glichkeit ihr  Geschick selbst zu testen oder die Fahrzeuge und Technik der  Feuerwehren anschauen. Zudem werden die Jugendfeuerwehren eine  Brandbek\u00e4mpfungs\u00fcbung zeigen. Getreu dem Motto &#8222;Wir bleiben cool,  auch wenn&#8217;s hei\u00df wird&#8220; wird dann der Grill angeheizt. Eltern,  Geschwister und Freunde sind uns herzlich willkommen, f\u00fchrt  B\u00fcrgermeister Owerien abschlie\u00dfend erg\u00e4nzend aus.     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/3112200\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; GEMEINDE SCHARBEUTZ DER B\u00dcRGERMEISTER Pressemitteilung der Gemeindeverwaltung Scharbeutz, Am B\u00fcrgerhaus 2, 23683 Scharbeutz Frau Nicole Schaub, Ordnungsamt,<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-205394","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/205394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=205394"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/205394\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=205394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=205394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=205394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}