{"id":207803,"date":"2016-06-20T19:58:24","date_gmt":"2016-06-20T19:58:24","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-se-fettbrand-loest-grossalarm-der-rettungskraefte-aus-84\/"},"modified":"2016-06-20T19:58:24","modified_gmt":"2016-06-20T19:58:24","slug":"fw-se-fettbrand-loest-grossalarm-der-rettungskraefte-aus-84","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-se-fettbrand-loest-grossalarm-der-rettungskraefte-aus-84\/","title":{"rendered":"FW-SE: Fettbrand l\u00f6st Gro\u00dfalarm der Rettungskr\u00e4fte aus"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Das betroffene Geb\u00e4ude\" src=\"http:\/\/cache.pressmailing.net\/thumbnail\/story_big\/a7e166c9-4e79-4115-a9b2-7cd10fa7f2a5\/image\" \/><\/p>\n<p>Pronstorf \/ OT Wulfsfelde (ots) &#8211;     Ein ausgedehnter K\u00fcchenbrand hat am Montagmittag gut 75  Einsatzkr\u00e4fte in Wulfsfelde, Gemeinde Pronstorf in Atem gehalten.  Brennendes Fett setzte die komplette K\u00fcche in Brand. Verletzt wurde  niemand.     Um 12:02 Uhr heulten im Bereich 4 der Amtswehr Trave-Land,  Cashagen und Tankenrade ( Kreis Ostholstein) die Sirenen.<!--more--> In  Wulfsfelde in der Dorfstra\u00dfe wurde \u00fcber Notruf 112 ein Gro\u00dffeuer  gemeldet. In einem Mehrfamilienhaus kam es in einer K\u00fcche zu einem  Fettbrand, der sich schnell in der gesamten K\u00fcche ausbreitete. Durch  die dort verbaute Holzdecke bekam das Feuer viel Nahrung und griff  rasch in die Zwischendecke \u00fcber. Dichter, schwarzer Rauch drang aus  der Wohnung. Die Bewohner konnten sich selbst ins Freie retten, die  drei Hunde der Bewohner wurden von der Feuerwehr unter Atemschutz  gerettet und den Besitzern \u00fcbergeben. Ein weiterer Hund aus der  Nachbarwohnung wurde durch Nachbarn gerettet. Einsatzeiter Heiko  Bergfelder lie\u00df sofort einen Innenangriff durchf\u00fchren um die Flammen  schnell einzud\u00e4mmen. Unter schwerem Atemschutz wurde die K\u00fcche  abgel\u00f6scht. Der Angriff erfolgte durch mehrere Trupps von zwei  Geb\u00e4udeseiten mit insgesamt 3 W\u00e4rmebildkameras des Amtes und der FF  Westerrade. Nachdem das Feuer und alle Glutnester gefunden und  gel\u00f6scht waren, wurde damit begonnen das Geb\u00e4ude, welches komplett  verraucht war, mit 2 Hochdruckl\u00fcftern zu bel\u00fcften. Die  Gefahrguterkundung Amt-Trave-Land f\u00fchrte Messungen durch, um  gef\u00e4hrliche Brandgase zu lokalisieren. Die ersten Wehren konnten nach gut 1,5 Stunden aus dem Einsatz entlassen werden. F\u00fcr die Ortswehr  Wulfsfelde-Reinsbek war der Einsatz um ca. 14:30 Uhr beendet. &#8222;Zum  Gl\u00fcck war zu dem Zeitpunkt niemand in den Wohnungen.&#8220; so Heiko  Bergfelder, denn das alte Haus ist sehr verwinkelt und  un\u00fcbersichtlich.     Im Einsatz waren 75 Einsatzkr\u00e4fte aus den Feuerwehren:  Wulfsfelde-Reinsbek, Strenglin-Pronstrof, Eilsdorf, Goldenbek,  Strukdorf,  Cashagen, Tankenrade, Geschendorf und Westerrade. Polizei mit 3 Einsatzkr\u00e4ften, DRK Segeberg mit einem Rettungswagen und dem  Org.Leiter.     S\u00f6nke M\u00f6ller Pressesprecher Kreisfeuerwehrverband Segeberg Telefon: 0173\/6141091<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/68034\/3358053\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pronstorf \/ OT Wulfsfelde (ots) &#8211; Ein ausgedehnter K\u00fcchenbrand hat am Montagmittag gut 75 Einsatzkr\u00e4fte in Wulfsfelde, Gemeinde Pronstorf in<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-207803","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/207803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=207803"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/207803\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=207803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=207803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=207803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}