{"id":208047,"date":"2015-06-28T10:12:02","date_gmt":"2015-06-28T10:12:02","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/wsp-sh-gewaesserverunreinigunggefahrgutunfall-auf-der-schleuse-holtenau-883\/"},"modified":"2015-06-28T10:12:02","modified_gmt":"2015-06-28T10:12:02","slug":"wsp-sh-gewaesserverunreinigunggefahrgutunfall-auf-der-schleuse-holtenau-883","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/wsp-sh-gewaesserverunreinigunggefahrgutunfall-auf-der-schleuse-holtenau-883\/","title":{"rendered":"WSP-SH: Gew\u00e4sserverunreinigung\/Gefahrgutunfall auf der Schleuse Holtenau"},"content":{"rendered":"<p>Kiel (ots) &#8211; Am 28.06.2015, gegen 05:30 Uhr, kam es auf der  Schleuse Holtenau zu einer Gew\u00e4sserverunreinigung durch Farbe. 48  Gebinde Lackfarbe, von 2,5 &#8211; 20 Liter Inhalt, sollten mit einem  Elektrokarren an ein Schiff in der neuen S\u00fcd-Schleuse geliefert  werden. Beim Rangieren auf der Mittelmauer geriet der Elektrokarren  mit einem Rad \u00fcber die Kaikante.<!--more--> Ein Teil der Ladung rutschte von der Ladefl\u00e4che und fiel in die Schleusenkammer. Acht Farbeimer st\u00fcrzten  auf ein Reibholz und platzten dabei auf. Durch die ausgelaufene Farbe wurde eine Wasserfl\u00e4che von ca. 300m x 5 m verunreinigt. Die  alarmierte Feuerwehr r\u00fcckte mit dem Gefahrgutzug an und nahm einen  Teil der Farbe auf. F\u00fcr die Reinigungsarbeiten musste die neue  S\u00fcd-Schleuse mehrere Stunden gesperrt werden. Personen kamen bei dem  Unfall nicht zu Schaden. Die Ermittlungen durch die  Wasserschutzpolizei Kiel dauern noch an.   ots Originaltext: Landespolizeiamt Schleswig-Holstein &#8211; Abt. 4 &#8211; Wasserschutzpolizei  Digitale Pressemappe: http:\/\/www.polizeipresse.de\/p_story.htx?firmaid=43800  <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/43800\/3057887\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kiel (ots) &#8211; Am 28.06.2015, gegen 05:30 Uhr, kam es auf der Schleuse Holtenau zu einer Gew\u00e4sserverunreinigung durch Farbe. 48<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-208047","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/208047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=208047"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/208047\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=208047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=208047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=208047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}