{"id":212726,"date":"2014-05-29T17:03:34","date_gmt":"2014-05-29T17:03:34","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot-3132\/"},"modified":"2014-05-29T17:03:34","modified_gmt":"2014-05-29T17:03:34","slug":"bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot-3132","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-bundespolizei-see-rettet-angler-vor-pelzerhaken-aus-seenot-3132\/","title":{"rendered":"BPOLI-See: Bundespolizei See rettet Angler vor Pelzerhaken aus Seenot"},"content":{"rendered":"<p>Neustadt (ots) &#8211; Am Morgen des 29. Mai 2014 sichtete die Besatzung des Einsatzschiffes BP 22 &#8222;Neustrelitz&#8220; der Bundespolizeiinspektion  See aus Neustadt w\u00e4hrend der Streifenfahrt ein gekentertes Angelboot  vor Pelzerhaken. Die Crew bestand aus drei m\u00e4nnlichen Personen, die  neben dem Boot im Wasser trieben.<!--more--> Das sofort zu Wasser gelassene  Bereitschaftsboot von BP 22 konnte die Angler nach kurzer Zeit an  Bord nehmen, keiner von ihnen trug eine Rettungsweste. Nach einer  Verbindungsaufnahme mit der DGzRS wurde das SRB &#8222;Crempe&#8220; gebeten, das in der Zwischenzeit gesunkene Angelboot zu bergen. Das Boot lag am  Grund im Flachwasser vor Pelzerhaken, wo an diesem Wochenende das  Surf Festival veranstaltet wird, somit stellte es eine Gefahr f\u00fcr die dort startenden Surfer und Kiter dar. Auf dem Einsatzschiff BP 22  wurden unterdessen die geretteten Angler im Rahmen der Ersten Hilfe  versorgt. Da zwei Personen an Unterk\u00fchlung litten, wurde ihnen  trockene Kleidung von der Besatzung zur Verf\u00fcgung gestellt. Nach dem  Einlaufen im Neust\u00e4dter Hafen konnten die drei Personen von einem  durch das Gemeinsame Lagezentrum bereits alarmierten Rettungswagen  \u00fcbernommen und weiter versorgt werden.     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/2749298\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Am Morgen des 29. Mai 2014 sichtete die Besatzung des Einsatzschiffes BP 22 &#8222;Neustrelitz&#8220; der Bundespolizeiinspektion See<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-212726","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/212726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=212726"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/212726\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=212726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=212726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=212726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}