{"id":214325,"date":"2016-09-18T22:47:50","date_gmt":"2016-09-18T22:47:50","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-od-siek-meilsdorf-gewinnt-8-kreisfussballturnier-der-stormarner-jugendfeuerwehren-108\/"},"modified":"2016-09-18T22:47:50","modified_gmt":"2016-09-18T22:47:50","slug":"fw-od-siek-meilsdorf-gewinnt-8-kreisfussballturnier-der-stormarner-jugendfeuerwehren-108","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-od-siek-meilsdorf-gewinnt-8-kreisfussballturnier-der-stormarner-jugendfeuerwehren-108\/","title":{"rendered":"FW-OD: Siek-Meilsdorf gewinnt 8. Kreisfu\u00dfballturnier der Stormarner Jugendfeuerwehren"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Nach einem packenden Finale konnte sich das Team aus Siek-Meilsdorf mit 0:0 (3:0 n.E) gegen Tremsb\u00fcttel durchsetzen.\" src=\"http:\/\/cache.pressmailing.net\/thumbnail\/story_big\/e87af4c0-422c-420e-800d-c4d2748788ad\/image\" \/><\/p>\n<p>Travenbr\u00fcck (ots) &#8211;     In einem packenden Finale standen sich am Samstag, den 17.09.16  die Jugendfeuerwehren aus Siek-Meilsdorf und Tremsb\u00fcttel gegen\u00fcber.  Nach der regul\u00e4ren Spielzeit stand es in dem ausgeglichenen Spiel  noch 0:0, so dass die Entscheidung im 9-Meter Schie\u00dfen fallen musste.<!--more--> Dort konnte sich das Team aus Siek-Meilsdorf mit einem deutlichen 3:0 durchsetzen und gewann schlussendlich das diesj\u00e4hrige Turnier. Alle  zwei Jahre veranstalten die Stormarner Jugendfeuerwehren das  Kreisfu\u00dfballturnier. Ausrichter und Gewinner des letzten Turniers war am Samstag, den 17.09.2016 war die Jugendfeuerwehr aus Delingsdorf.  Elf Mannschaften hatten sich in diesem Jahr angemeldet und neben der  Schule und den normalen Jugendfeuerwehr-Diensten verbissen trainiert. In zwei Gruppen wurden die Teilnehmer f\u00fcr das Halbfinale ausgespielt. Gespielt wurde f\u00fcr jeweils 10 Minuten auf zwei Kleinfeldern. Im  Halbfinale traten dann Siek-Meilsdorf gegen B\u00fcnningstedt (2:0) und  Hoisb\u00fcttel gegen Tremsb\u00fcttel an. In einem recht ausgeglichenen  Gemeindederby k\u00e4mpften die Teams von B\u00fcnningstedt gegen Hoisb\u00fcttel um das Siegtor. Hier konnte Hoisb\u00fcttel dank eines Foul-9-Meters das  Match knapp f\u00fcr sich entscheiden und erreichte den dritten Platz.  Spannender ging es im Finale zwischen Tremsb\u00fcttel und Siek-Meilsdorf  zu. Der Torwart der Siek-Meilsdorfer war im Verlauf der Turniers eine Bank und hielt seinen Kasten sauber. Mit 17:0 Toren wurde das Team  souver\u00e4n Gruppensieger. Aber auch die Tremsb\u00fctteler sind mit 11:0  Toren ohne Gegentor ins Finale gezogen, wo sich der torlose Trend  beider Mannschaften fortsetzen sollte. Beide Teams k\u00e4mpften verbissen um das entscheidende Tor, doch so viele Chancen sich die Beiden auch  erarbeiteten: Das Runde wollte einfach nicht ins Eckige. Nach 10  Minuten der regul\u00e4ren Spielzeit kam es nach einem Remis, wie es sich  f\u00fcr ein richtiges Turnier geh\u00f6rt, zum spannungsgeladenen 9-Meter  Schie\u00dfen. Doch hier hatte Tremsb\u00fcttel die Nase nicht mehr vorn. Der  Torwart der Siek-Meilsdorfer konnte einen Ball halten, ein weiterer  Ging am Tor vorbei. Auch die Sch\u00fctzen von Siek-Meilsdorf hatten mehr  Gl\u00fcck und verwandelten alle Sch\u00fcsse souver\u00e4n. Am Ende gewannen sie  das Turnier somit mit 0:0 (3:0 n.E.). Fair wurde mit den Gegnern aus  Tremsb\u00fcttel abgeschlagen. Ein weiteres Zeichen daf\u00fcr, wie fair es in  diesem Jahr bei den Spielen zuging. Keine groben Fouls, keine  nennenswerten Verletzungen. Einfach ein spannendes, von einigen  Zuschauern begleitetes, Fu\u00dfballturnier der Stormarner  Jugendfeuerwehren. 2018 wird das Turnier dann von Siek-Meilsdorf  ausgerichtet. Die Platzierungen im Einzelnen (1. Siek-Meilsdorf, 2.  Tremsb\u00fcttel, 3. Hoisb\u00fcttel, 4. B\u00fcnningstedt, 5. Travenbr\u00fcck, 6.  Barsb\u00fcttel, 7. Ahrensfelde, 8. Feldhorst, 9. Barnitz, 10. Gr\u00f6nwohld,  11. Brunsbek)     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/68032\/3433202\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Travenbr\u00fcck (ots) &#8211; In einem packenden Finale standen sich am Samstag, den 17.09.16 die Jugendfeuerwehren aus Siek-Meilsdorf und Tremsb\u00fcttel gegen\u00fcber.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-214325","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/214325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=214325"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/214325\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=214325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=214325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=214325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}