{"id":223761,"date":"2016-08-20T15:47:50","date_gmt":"2016-08-20T15:47:50","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-oh-sereetz-keis-ostholsten-feuerwehrmann-mit-schweren-brandverletzungen-542\/"},"modified":"2016-08-20T15:47:50","modified_gmt":"2016-08-20T15:47:50","slug":"fw-oh-sereetz-keis-ostholsten-feuerwehrmann-mit-schweren-brandverletzungen-542","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-sereetz-keis-ostholsten-feuerwehrmann-mit-schweren-brandverletzungen-542\/","title":{"rendered":"FW-OH: Sereetz Keis Ostholsten: Feuerwehrmann mit schweren Brandverletzungen"},"content":{"rendered":"<p>Lensahn (ots) &#8211; Am Freitagabend (19.08.2016) kam es in Sereetz  (Gemeinde Ratekau, Kreis Ostholstein) zu einem Brand in einem  leerstehenden, ehemaligen Verbrauchermarkt. Dabei wurde ein zuf\u00e4llig  auf die Einsatzstelle zukommender Feuerwehrmann erheblich verletzt.<!--more-->  Gegen 21.05 Uhr kam der Feuerwehrmann auf dem R\u00fcckweg vom  Feuerwehraus an der sp\u00e4teren Schadenstelle vorbei und bemerkte eine  offene Eingangst\u00fcr.  Da die Feuerwehr Sereetz \u00fcber einen Schl\u00fcssel  f\u00fcr das im Besitz der Gemeinde befindliche, leerstehende Geb\u00e4ude  verf\u00fcgt, fuhr er zur\u00fcck zum Feuerwehrhaus, um den Schl\u00fcssel zu holen. Als er dann die T\u00fcr verschlie\u00dfen wollte, kam es im Inneren des  Geb\u00e4udes zu einer Durchz\u00fcndung, bei der er sich erhebliche  Brandverletzungen zugezogen hat. Er konnte sich noch selbst auf die  andere Stra\u00dfenseite in Sicherheit bringen, wo er von Anwohnern  erstversorgt wurde. Der Feuerwehrmann wurde mit schweren  Verbrennungen in die Uniklinik L\u00fcbeck eingeliefert. Lebensgefahr  besteht nicht. Wie es zu dem Brand kam, der vermutlich im  Versorgungsraum des Geb\u00e4udes ausgebrochen ist, ist bislang unklar.     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/3408528\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Am Freitagabend (19.08.2016) kam es in Sereetz (Gemeinde Ratekau, Kreis Ostholstein) zu einem Brand in einem leerstehenden,<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-223761","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/223761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=223761"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/223761\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=223761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=223761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=223761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}