{"id":223872,"date":"2016-09-09T09:00:00","date_gmt":"2016-09-09T09:00:00","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-od-einladung-an-die-medien-8-kreisfussballturnier-der-stormarner-jugendfeuerwehren-490\/"},"modified":"2016-09-09T09:00:00","modified_gmt":"2016-09-09T09:00:00","slug":"fw-od-einladung-an-die-medien-8-kreisfussballturnier-der-stormarner-jugendfeuerwehren-490","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-od-einladung-an-die-medien-8-kreisfussballturnier-der-stormarner-jugendfeuerwehren-490\/","title":{"rendered":"FW-OD: Einladung an die Medien: \n8. Kreisfu\u00dfballturnier der Stormarner Jugendfeuerwehren"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"8. Kreisfu\u00dfballturniert der Stormarner Jugendfeuerwehren in Delingsdorf\" src=\"http:\/\/cache.pressmailing.net\/thumbnail\/story_big\/e3dab4c8-c9ad-40c0-9613-d4a3678082b5\/image\" \/><\/p>\n<p>Travenbr\u00fcck (ots) &#8211;     Die Stormarner Jugendfeuerwehren richten ihr 8.  Kreisfu\u00dfballturnier in Delingsdorf aus &#8211; am Samstag, den 17.  September 2016.     Ein weiteres Highlight in der zweiten Jahresh\u00e4lfte ist das  mittlerweile 8. Kreisfu\u00dfballturnier der Stormarner Jugendfeuerwehren  auf dem Sportplatz in Delingsdorf.<!--more--> Ob aus dem Norden, dem S\u00fcden oder  der Mitte von Stormarn: Die Jugendfeuerwehren aus dem Kreis werden um den Einzug ins Finale k\u00e4mpfen um am Ende den Pokal in den Himmel zu  strecken. Gespielt wird nach den Regeln des Deutschen Fu\u00dfball Bundes  (DFB) und mit 7 Spielern pro Mannschaft &#8211; nat\u00fcrlich sind Jungen und  M\u00e4dchen gemischt. Wir freuen uns, Sie am Turniertag in Delingsdorf  begr\u00fc\u00dfen zu d\u00fcrfen um ein Foto der Spiele zu machen!     Wo: Sportplatz Delingsdorf &#8211; Lohe 44 &#8211; 22941 Delingsdorf Wann:  Samstag, 17. September 2016 Beginn: 10:00 Uhr Siegerehrung: nach  Turnierende (ca. 15:00 Uhr)     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/68032\/3425125\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Travenbr\u00fcck (ots) &#8211; Die Stormarner Jugendfeuerwehren richten ihr 8. Kreisfu\u00dfballturnier in Delingsdorf aus &#8211; am Samstag, den 17. September 2016.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-223872","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/223872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=223872"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/223872\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=223872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=223872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=223872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}