{"id":224064,"date":"2016-09-08T11:54:18","date_gmt":"2016-09-08T11:54:18","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-rz-feuerwehr-leistungsfahrt-des-kreisfeuerwehrverbandes-herzogtum-lauenburg-am-03-09-2016-494\/"},"modified":"2016-09-08T11:54:18","modified_gmt":"2016-09-08T11:54:18","slug":"fw-rz-feuerwehr-leistungsfahrt-des-kreisfeuerwehrverbandes-herzogtum-lauenburg-am-03-09-2016-494","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-feuerwehr-leistungsfahrt-des-kreisfeuerwehrverbandes-herzogtum-lauenburg-am-03-09-2016-494\/","title":{"rendered":"FW-RZ: Feuerwehr-Leistungsfahrt des Kreisfeuerwehrverbandes Herzogtum Lauenburg am 03.09.2016"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"03.09.2016 L-Fahrt Jugendfeuerwehr:\nAuch die Jugendfeuerwehr musste Ger\u00e4te praktisch vorf\u00fchren.\" src=\"http:\/\/cache.pressmailing.net\/thumbnail\/story_big\/d8bca038-94c1-4d58-9c47-45ef322dbb97\/image\" \/><\/p>\n<p>Ratzeburg (ots) &#8211;     44 Mannschaften, darunter auch drei Gastmannschaften des THW und  DRK lie\u00dfen sich von dem Nieselregen nicht abhalten und nahmen am 03.  September 2016 an der Feuerwehr-Leistungsfahrt des  Kreisfeuerwehrverbandes Herzogtum Lauenburg auf dem Gel\u00e4nde der  Bundespolizei in B\u00fcchen teil.<!--more--> P\u00fcnktlich um 11.00 Uhr starteten die  Mannschaften in den altbekannten Klassen Klein-, Mittel-, Gro\u00df- und  Sonderfahrzeugen. Die Jugendfeuerwehren unter Leitung der  Jugendwartung oder einer Bereuungsperson nahmen auch in diesem Jahr  wieder mit einer Vielzahl von Mannschaften teil. Nach einer  umfassenden Funktionskontrolle der Fahrzeuge, begann der Parcours mit den unterschiedlichsten Aufgaben. Neben der Geschicklichkeit des  Fahrers war auch Teamarbeit gefragt. Wenn beispielsweise das Fahrzeug mit abgedeckten Au\u00dfenspiegeln eine R\u00fcckw\u00e4rtsgasse passieren musste,  war der Fahrer auf seinen Einweiser angewiesen. Weiterhin mussten  feuerwehrtechnische Fragen beantwortet werden, ein L\u00f6schangriff nach  Dienstvorschrift war abzuarbeiten und die unterschiedlichsten  Ger\u00e4tschaften der Fahrzeuge wurden vorgef\u00fchrt. Da f\u00fcr die  abschlie\u00dfende Gesamtwertung nicht nur das erfolgreiche Absolvieren  des Parcours mit allen Aufgaben entscheidend war, sondern auch die  Zeit gestoppt wurde, boten sich dem Zuschauer die ein oder andere  spannende Szene. Gegen 15.00 Uhr erfolgte die Siegerehrung, bei der  neben der Urkunde f\u00fcr jede teilnehmende Mannschaft auch diverse  Pokale \u00fcbergeben wurden. Nachfolgend eine Aufstellung der Sieger in  den einzelnen Klassen: Kleinfahrzeuge: FF Hammer Mittelfahrzeuge: FF  Sierksrade Gro\u00dffahrzeuge: FF Worth Jugendfeuerwehr: JF G\u00fclzow  Sonderfahrzeuge: DRK B\u00fcchen Zus\u00e4tzlich gab es in diesem Jahr zwei  Sonderpreise. Das Amt B\u00fcchen hatte eine stattliche Mettwurst  gespendet. Der B\u00fcrgermeister der Gemeinde B\u00fcchen, Uwe M\u00f6ller \u00fcbergab  die Mettwurst an die FF Elmenhorst, die an diesem Tag als erste  Mannschaft starten musste. Die B\u00fcrgervorsteherin der Gemeinde B\u00fcchen, Heike Gronau-Schmidt, konnte unter gro\u00dfem Applaus an die Mannschaft  der FF Kollow einen stattlichen Schinken \u00fcbergeben, diese Mannschaft  kam dem Durchschnitt aller &#8222;eingefahrenen&#8220; Punkt am n\u00e4chsten. Bei der Feuerwehr wird bekannterma\u00dfen auch f\u00fcr das leibliche Wohl gesorgt.  Die Kameradinnen und Kameraden der Freiwilligen Feuerwehr B\u00fcchen  haben auch in diesem Jahr zusammen mit ihren Angeh\u00f6rigen wieder f\u00fcr  ein umfangreiches Speisensortiment zu attraktiven Preisen gesorgt.  Leider war -vermutlich wetterbedingt- die Beteiligung der Bev\u00f6lkerung nicht allzu gro\u00df. An dieser Stelle noch einmal den herzlichsten Dank  an die Kameradinnen und Kameraden der FF B\u00fcchen sowie alle  eingeteilten Helfer, die den Kreisfeuerwehrverband bei dieser  Veranstaltung erneut tatkr\u00e4ftig unterst\u00fctzt haben.     Honorarfreie Fotos: 03.09.2016 L-Fahrt Jugendfeuerwehr: Auch die  Jugendfeuerwehr musste Ger\u00e4te praktisch vorf\u00fchren.     03.09.2016 L-Fahrt Schwarzenbek: Die Kameraden der FF Schwarzenbek nahmen mit sechs Mannschaften teil.     03.09.2016 L-Fahrt Grillstand: Die Mitglieder der FF B\u00fcchen  sorgten f\u00fcr das leibliche Wohl.     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/68033\/3424472\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; 44 Mannschaften, darunter auch drei Gastmannschaften des THW und DRK lie\u00dfen sich von dem Nieselregen nicht abhalten<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-224064","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/224064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=224064"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/224064\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=224064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=224064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=224064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}