{"id":224235,"date":"2016-09-04T17:50:48","date_gmt":"2016-09-04T17:50:48","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-od-jugendfeuerwehren-treffen-sich-zur-leistungsspangenabnahme-in-reinfeld-515\/"},"modified":"2016-09-04T17:50:48","modified_gmt":"2016-09-04T17:50:48","slug":"fw-od-jugendfeuerwehren-treffen-sich-zur-leistungsspangenabnahme-in-reinfeld-515","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-od-jugendfeuerwehren-treffen-sich-zur-leistungsspangenabnahme-in-reinfeld-515\/","title":{"rendered":"FW-OD: Jugendfeuerwehren treffen sich zur Leistungsspangenabnahme in Reinfeld"},"content":{"rendered":"<p>Travenbr\u00fcck (ots) &#8211; Am Samstag, den 10.09.2016 ab 10:00 Uhr geht  es spannend zu in Reinfeld.<!--more--> Dann hei\u00dft es f\u00fcr rund 90 Mitglieder der  Schleswig-Holsteinischen Jugendfeuerwehren im Alter von 15 bis 18  Jahren, fit zu sein f\u00fcr insgesamt f\u00fcnf Disziplinen, um die begehrte  Leistungsspange, die h\u00f6chste Auszeichnung, die sie in der  Jugendfeuerwehr erzielen k\u00f6nnen, an die Uniform geheftet zu bekommen. P\u00fcnktlich um 10 Uhr beginnt auf der Sportanlage in Reinfeld  (Bischofsteicher Weg 45a) die Abnahme. Daf\u00fcr trainieren die  Teilnehmer seit dem Ende der Sommerferien mehrmals pro Woche. Zu den  Disziplinen geh\u00f6ren eine Schnelligkeits\u00fcbung, bei der eine  Schlauchleitung von 120 Metern ausgelegt wird, Kugelsto\u00dfen,  Staffellauf und der L\u00f6schangriff. Au\u00dferdem werden in einem  15-min\u00fctigen Gespr\u00e4ch mit jeder Gruppe Fragen zu Fahrzeugtypen und  Ausr\u00fcstung der Feuerwehren aber auch gesellschaftspolitische Themen  er\u00f6rtert. Externe Wertungsrichter nehmen die Leistungen der  Nachwuchskr\u00e4fte kritisch unter die Lupe und verteilen Punkte. Wird  geflucht oder bricht das Chaos aus folgt ein Punkteabzug, denn auch  das kameradschaftliche und disziplinierte Gesamtverhalten der Gruppe  wird bewertet. Die Jugendfeuerwehren w\u00fcrden sich \u00fcber viele Zuschauer freuen. Antreten und Begr\u00fc\u00dfung um 10:00 Uhr, Beginn der Abnahme um  10:15 Uhr, Verleihung der Spangen gegen 15:00 Uhr.     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/68032\/3420676\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Travenbr\u00fcck (ots) &#8211; Am Samstag, den 10.09.2016 ab 10:00 Uhr geht es spannend zu in Reinfeld.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-224235","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/224235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=224235"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/224235\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=224235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=224235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=224235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}