{"id":226497,"date":"2016-09-18T16:05:52","date_gmt":"2016-09-18T16:05:52","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/pol-sh-afb-angehende-polizisten-feierlich-vereidigt-519\/"},"modified":"2016-09-18T16:05:52","modified_gmt":"2016-09-18T16:05:52","slug":"pol-sh-afb-angehende-polizisten-feierlich-vereidigt-519","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-angehende-polizisten-feierlich-vereidigt-519\/","title":{"rendered":"POL-SH-AFB: Angehende Polizisten feierlich vereidigt"},"content":{"rendered":"<p>Eutin (ots) &#8211; In Anwesenheit von Innenminister Stefan Studt und  Landespolizeidirektor Ralf H\u00f6hs haben heute auf der Hubertush\u00f6he in  Eutin  445 angehende Polizisten ihren Eid abgelegt. Es ist die  h\u00f6chste Zahl an Dienstanf\u00e4ngern seit Bestehen der Landespolizei  Schleswig-Holstein.<!--more-->     F\u00fcr den besonderen Tag waren rund 3000 Angeh\u00f6rige, Freunde und  Kollegen der angehenden Polizisten nach Eutin  gekommen.  Die  Vereidigung bei der Polizeidirektion f\u00fcr Aus- und Fortbildung und f\u00fcr die Bereitschaftspolizei (PD AFB) ist f\u00fcr die jungen Anw\u00e4rter der  feierliche Beginn ihrer Polizeilaufbahn.     Bereits am 01.02.2016 begannen 46 Anw\u00e4rterinnen und Anw\u00e4rter ihre  Ausbildung. Auf die 399  M\u00e4nner und Frauen, die am 1. August ihre  Ausbildung in der Landespolizei Schleswig-Holstein begonnen haben,  folgt jetzt die weitere Ausbildung. F\u00fcr die Anw\u00e4rter im gehobenen  Dienst findet das 3-j\u00e4hrige Studium mit Ausnahme des Grund- und  Hauptpraktikums an der Fachhochschule f\u00fcr Verwaltung und  Dienstleistung (FHVD) in Altenholz bei Kiel statt. Die Anw\u00e4rter des  mittleren Dienstes absolvieren ihre  Ausbildung mit Ausnahme des  Berufspraktikums bei der Polizeidirektion f\u00fcr Aus- und Fortbildung  und f\u00fcr die Bereitschaftspolizei in Eutin. Sie dauert zweieinhalb  Jahre.     Bereits am Morgen war ein gemeinsamer Gottesdienst der Auftakt.  Der Festakt selbst bekam eine w\u00fcrdevolle musikalische Begleitung  durch das Marinemusikkorps der Bundeswehr aus Kiel. Ein  beeindruckendes Bild entstand, als die 445 angehenden Polizisten zu  Beginn der Veranstaltung auf die Veranstaltungsfl\u00e4che  einmarschierten. Nach der Begr\u00fc\u00dfung durch den neuen Leiter der PD AFB Leitender Polizeidirektor (LPD) Michael Wilksen folgte das Gru\u00dfwort  von Landespolizeidirektor Ralf H\u00f6hs. Hier stellte der  Landespolizeidirektor fest: &#8222;Ich will \u00fcber das sprechen, was die  Grundlage ist f\u00fcr unsere Landespolizei, deren F\u00fchrungskr\u00e4fte und alle Mitarbeiterinnen und Mitarbeiter sowie die notwendigen  Ver\u00e4nderungsprozesse. Ich rede von Vertrauen und Verantwortung! Wo  Vertrauen fehlt, regiert Unsicherheit und Angst. Angst vor der  Zukunft ist der sicherste Weg, Vertrauen zu verlieren. Sie l\u00e4hmt die  Handlungsf\u00e4higkeit und f\u00fchrt mitunter zu irrationalen Entscheidungen. Nicht umsonst hei\u00dft es: &#8222;Angst ist ein schlechter Ratgeber!&#8220; Wir alle wissen: Vertrauen kann man nicht anordnen, nicht befehlen! Vertrauen  kann man auch nicht beschlie\u00dfen. Vertrauen muss wachsen. Vertrauen  w\u00e4chst zwischen einzelnen Menschen, aber auch in Gemeinschaften wie  unserer Landespolizei&#8220;.     In seiner Vereidigungsansprache wandte sich Innenminister Stefan  Studt direkt an die zu Vereidigenden: &#8222;Sie haben sich f\u00fcr die  Landespolizeipolizei Schleswig-Holstein beworben und sich im  Auswahlverfahren unter zahlreichen anderen Mitbewerberinnen und  Mitbewerbern durchgesetzt. Dazu begl\u00fcckw\u00fcnsche ich Sie ganz herzlich. In den kommenden Jahren werden Sie eine sehr gute Ausbildung  erhalten! Wir geben Sie in die Obhut sehr erfahrener und motivierter  Ausbilderinnen und Ausbilder. Unsere Polizei ist ein Garant der  inneren Sicherheit und der b\u00fcrgerlichen Freiheit in  Schleswig-Holstein. Sie steht seit Jahrzehnten f\u00fcr hohe  Einsatzbereitschaft und Professionalit\u00e4t. Mit Ihrer heutigen  Vereidigung werden Sie ein Teil dieser gro\u00dfen und immer vielf\u00e4ltiger  werdenden Organisation.&#8220; Anschlie\u00dfend sprachen eine Anw\u00e4rterin und  ein Anw\u00e4rter den Prolog zur Vereidigung.     Es folgte dann die eigentliche Vereidigung, bei der Innenminister  als oberster Dienstherr den Diensteid abnahm. Es war ein imposanter  Eindruck, als aus 445 Kehlen der Diensteid abgelegt wurde.     Im Anschluss l\u00f6sten sich die strengen Formationen auf und die  Angeh\u00f6rigen und Freunde st\u00fcrmten zu den frisch Vereidigten. In einem  bunten Happening genossen die angehenden Polizisten den Empfang mit  ihren Lieben, bevor am Montag dann die neue Ausbildungswoche starten  wird.     Die Zeit nach der Vereidigung nutzten viele Besucher, um die  Liegenschaft Hubertush\u00f6he kennenzulernen, die Unterk\u00fcnfte zu  inspizieren und sich auch einen \u00dcberblick \u00fcber einen Querschnitt aus  der Ausbildung bei praktischen Vorf\u00fchrungen zu verschaffen.     Weitere Informationen:     328 Dienstanf\u00e4nger sind in Landeskinder und stammen aus  Schleswig-Holstein. Bei den Anw\u00e4rtern mit Migrationshintergrund  stammen 6 aus der T\u00fcrkei, 2 aus Polen und jeweils einer oder eine aus D\u00e4nemark, Schweden, Russland, Algerien und dem Kamerun.     Insgesamt werden neben dem Jahrgang 2016 derzeit folgende   Anw\u00e4rterinnen und Anw\u00e4rter ausgebildet:     Eutin: 234 \tIn der Fach- und Abschlussausbildung LG 1, 2. EA  Berufspraktikum:\t47 \tLG 1, 2.EA FHVD: 220 \tStudierende Ein- du  Aufsteiger in verschiedenen Semestern, LG 2, 1. EA     Gesamt 946 (incl. der heute zu Vereidigenden)     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/43685\/3433106\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; In Anwesenheit von Innenminister Stefan Studt und Landespolizeidirektor Ralf H\u00f6hs haben heute auf der Hubertush\u00f6he in Eutin<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-226497","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/226497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=226497"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/226497\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=226497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=226497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=226497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}