{"id":238555,"date":"2016-12-31T12:45:42","date_gmt":"2016-12-31T12:45:42","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-oh-feuer-im-pflegeheim-schnell-unter-kontrolle-481\/"},"modified":"2016-12-31T12:45:42","modified_gmt":"2016-12-31T12:45:42","slug":"fw-oh-feuer-im-pflegeheim-schnell-unter-kontrolle-481","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-feuer-im-pflegeheim-schnell-unter-kontrolle-481\/","title":{"rendered":"FW-OH: Feuer im Pflegeheim schnell unter Kontrolle"},"content":{"rendered":"<p>Lensahn (ots) &#8211; Am Morgen des 31. Dezember wurde die Feuerwehr  Lensahn gegen 4 Uhr wegen einer Ausl\u00f6sung der Brandmeldeanlage im AWO Haus am M\u00fchlenteich in Lensahn alarmiert. Bei der ersten Erkundung  stellten die Einsatzkr\u00e4fte Brandgeruch auf dem Flur einer  Pflegestation fest.<!--more--> Da die Brandursache zun\u00e4chst nicht zu erkennen  war wurde in Absprache mit dem Rettungsdienst die Evakuierung der  betroffenen Station vorgesehen. Noch w\u00e4hrend die nachalarmierten  Feuerwehr- und Rettungsdienstkr\u00e4fte auf der Anfahrt waren, stellte  sich heraus, dass die Brandursache vermutlich ein defektes  LED-Teelicht war, dessen schwelendes Kunststoffgeh\u00e4use eine kr\u00e4ftige  Rauchentwicklung verursacht hatte. Das LED-Licht stand ordnungsgem\u00e4\u00df  in einer hohen Glasvase, so dass das Feuer sich nicht ausbreiten  konnte. Einsatzleiter Hartmut Junge und der Leitende Notarzt  Christian Schultz zeigten sich erleichtert, dass keine Evakuierung  der Bewohner erforderlich war. Die Feuerwehr bel\u00fcftete den  betroffenen Geb\u00e4udeteil. Alle Bewohner konnten in ihren Zimmern  bleiben. Die nachalarmierten Feuerwehren aus Lensahnerhof, Sipsdorf  und Wahrendorf sowie die Schnelleinsatzgruppen des Rettungsdienstes  brauchten nicht mehr t\u00e4tig werden.     <\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/3524245\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Am Morgen des 31. Dezember wurde die Feuerwehr Lensahn gegen 4 Uhr wegen einer Ausl\u00f6sung der Brandmeldeanlage<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-238555","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/238555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=238555"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/238555\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=238555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=238555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=238555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}