{"id":248921,"date":"2017-09-17T17:57:15","date_gmt":"2017-09-17T17:57:15","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/pol-sh-afb-oh-eutin-anzeige-bei-vereidigungsfeier-138\/"},"modified":"2017-09-17T17:57:15","modified_gmt":"2017-09-17T17:57:15","slug":"pol-sh-afb-oh-eutin-anzeige-bei-vereidigungsfeier-138","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-oh-eutin-anzeige-bei-vereidigungsfeier-138\/","title":{"rendered":"POL-SH-AFB: OH &#8211; Eutin \/ Anzeige bei Vereidigungsfeier"},"content":{"rendered":"<p>Eutin (ots) &#8211; Am Sonntag, 17.09.2017, fand in Eutin (Ostholstein)  die Vereidigung von den Polizeianw\u00e4rterinnen und Polizeianw\u00e4rtern  statt. Im Rahmen der Veranstaltung wurden zwei M\u00e4nner festgestellt,  die w\u00e4hrend des Abspielens der deutschen Nationalhymne den  sogenannten Hitlergru\u00df  gezeigt haben sollen.<!--more--> Durch die Polizei wurde eine Strafanzeige gem\u00e4\u00df \u00a7 86a StGB (Verwenden von Kennzeichen  verfassungswidriger Organisationen) gefertigt. Nach der  Identit\u00e4tsfeststellung erhielten die beiden M\u00e4nner einen  Platzverweis. Die weiteren Ermittlungen werden durch die  Bezirkskriminalinspektion in L\u00fcbeck, Bereich Staatsschutz, gef\u00fchrt     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43685\/3737552\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; Am Sonntag, 17.09.2017, fand in Eutin (Ostholstein) die Vereidigung von den Polizeianw\u00e4rterinnen und Polizeianw\u00e4rtern statt. Im Rahmen<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-248921","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/248921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=248921"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/248921\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=248921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=248921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=248921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}