{"id":251972,"date":"2017-12-07T13:08:57","date_gmt":"2017-12-07T13:08:57","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-charity-projekt-2017-der-bundespolizeiinspektion-see-neustadt-in-holstein-abgeschlossenspende-uebergeben-96\/"},"modified":"2017-12-07T13:08:57","modified_gmt":"2017-12-07T13:08:57","slug":"bpoli-see-charity-projekt-2017-der-bundespolizeiinspektion-see-neustadt-in-holstein-abgeschlossenspende-uebergeben-96","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-charity-projekt-2017-der-bundespolizeiinspektion-see-neustadt-in-holstein-abgeschlossenspende-uebergeben-96\/","title":{"rendered":"BPOLI-See: Charity- Projekt 2017 der Bundespolizeiinspektion See Neustadt in Holstein abgeschlossen\nSpende \u00fcbergeben"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Spenden\u00fcbergabe im Kinderzentrum Pelzerhaken\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/53a4643c-9a4e-4c01-a1a8-83b1cf9a7136\/image\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Wie zu Jahresbeginn 2017 vereinbart und im Rahmen einer Vielzahl  von Veranstaltungen und Besuchen der Neust\u00e4dter Dienststelle der  Bundespolizei See umgesetzt, sollte in diesem Jahr der Erl\u00f6s aus der  Spendenbox an das Kinderzentrum Pelzerhaken \u00fcbergeben werden. Unter  dem Motto &#8222;Wir helfen Helfen&#8230;<!--more-->&#8220; wird auch das Veranstaltungsjahr  2018 von einer derartigen Aktion begleitet werden&#8220;, so der  Inspektionsleiter bei der Scheck\u00fcbergabe. Das Kinderzentrum  Pelzerhaken ist eine Einrichtung zur sozialp\u00e4diatrischen Behandlung  von Kindern mit Entwicklungsst\u00f6rungen und neurologischen  Erkrankungen. Um W\u00fcnsche wahrwerden zu lassen, soll mit dem Erl\u00f6s aus der Vielzahl von Veranstaltungen nun ein in die Jahre gekommenes  Laufband ersetzt werden. Kein Laufband wie eines aus dem  Fitnessstudio: hier sind technische Ausstattungen erforderlich, die  auf die therapeutischen Bed\u00fcrfnisse der teilweise noch sehr kleinen  Patienten abgestimmt werden m\u00fcssen, so dass bei man bei den  Anschaffungskosten von einer f\u00fcnfstelligen Summe ausgehen muss. Am  05. Dezember 2017 konnte dem \u00e4rztlichen Leiter der Einrichtung, Dr.  Broxtermann, die stattliche Summe von  3.500,00  EUR \u00fcbergeben  werden. &#8222;F\u00fcr Ihre Einrichtung kommt der Nikolaus in diesem Jahr einen Tag fr\u00fcher&#8230;&#8220; so die einleitenden Worte des Inspektionsleiters EPHK  Antler im Rahmen der Check\u00fcbergabe. Bereits zum Jahresbeginn war  klar, wohin der Erl\u00f6se bzw. die Zuwendungen aus einer Vielzahl von  Veranstaltung flie\u00dfen sollten, an denen die Mitarbeiterinnen und  Mitarbeiter der Neust\u00e4dter Inspektion mit oder auch ohne  Einsatzschiff teilnehmen; ob w\u00e4hrend der vielen Veranstaltungen an  unserer K\u00fcste, im Binnenland oder insbesondere zum &#8222;Tag der  K\u00dcSTENWACHE&#8220;: die als Spendenbox umfunktionierte Positionslaterne mit dem entsprechenden Hinweis auf den zuk\u00fcnftigen Verwendungszweck  war  immer pr\u00e4sent. Auch wenn unsere Spende nur ein kleiner Beitrag zum  Erreichen der Gesamtsumme darstellt &#8211; der erste Schritt ist  vollbracht und das erwirtschaftete Geld ist gut angelegt, davon  konnten wir uns \u00fcberzeugen.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/3809324\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Wie zu Jahresbeginn 2017 vereinbart und im Rahmen einer Vielzahl von Veranstaltungen und Besuchen der Neust\u00e4dter Dienststelle<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-251972","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/251972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=251972"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/251972\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=251972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=251972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=251972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}