{"id":255152,"date":"2017-12-05T14:19:43","date_gmt":"2017-12-05T14:19:43","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-oh-feuerwehrfahrzeug-im-kreis-ostholstein-verunglueckt-180\/"},"modified":"2017-12-05T14:19:43","modified_gmt":"2017-12-05T14:19:43","slug":"fw-oh-feuerwehrfahrzeug-im-kreis-ostholstein-verunglueckt-180","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-feuerwehrfahrzeug-im-kreis-ostholstein-verunglueckt-180\/","title":{"rendered":"FW-OH: Feuerwehrfahrzeug im Kreis Ostholstein verungl\u00fcckt"},"content":{"rendered":"<p>Lensahn (ots) &#8211; Am 05.12.2017 gegen 07.45 Uhr verunfallte ein  Einsatzfahrzeug der Freiwilligen Feuerwehr S\u00fcderort (Stadt Fehmarn)  auf der B 202 in H\u00f6he der Kreisgrenze zwischen den Kreisen  Ostholstein und Pl\u00f6n. Der Unfall ereignete sich auf der Fahrt nach  Preetz, zu einem Inspektionstermin in einer Fachwerkstatt. Das  Feuerwehrfahrzeug war mit einer Person besetzt.<!--more--> Es kam nach rechts  auf die weiche Bankette, brach aus und prallte gegen einen Baum. Am  Fahrzeug entstand erheblicher Sachschaden und es ist nicht mehr  einsatzbereit. Der Unfallfahrer wurde leicht verletzt. Nach  ambulanter Behandlung im Krankenhaus wurde er wieder entlassen und  befindet sich mittlerweile wieder zuhause. Die Feuerwehren  Kak\u00f6hl-Blekendorf, Sechendorf und Nessendorf aus dem Kreis Pl\u00f6n waren mit Aufr\u00e4umarbeiten besch\u00e4ftigt und unterst\u00fctzten die Polizei bei der Absicherung der Unfallstelle.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/3807195\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Am 05.12.2017 gegen 07.45 Uhr verunfallte ein Einsatzfahrzeug der Freiwilligen Feuerwehr S\u00fcderort (Stadt Fehmarn) auf der B<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-255152","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/255152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=255152"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/255152\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=255152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=255152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=255152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}