{"id":255717,"date":"2017-05-22T11:17:02","date_gmt":"2017-05-22T11:17:02","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-seenotretter-und-bundespolizisten-gemeinsam-im-einsatz-fuer-seglerin-mit-herzinfarkt-565\/"},"modified":"2017-05-22T11:17:02","modified_gmt":"2017-05-22T11:17:02","slug":"bpoli-see-seenotretter-und-bundespolizisten-gemeinsam-im-einsatz-fuer-seglerin-mit-herzinfarkt-565","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-seenotretter-und-bundespolizisten-gemeinsam-im-einsatz-fuer-seglerin-mit-herzinfarkt-565\/","title":{"rendered":"BPOLI-See: Seenotretter und Bundespolizisten gemeinsam im Einsatz f\u00fcr Seglerin mit Herzinfarkt"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/83ca899d-c1fd-45f4-94c5-0edfd0fb80d1\/image\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Der Ostsee-T\u00f6rn eines Segler-Ehepaars aus den Niederlanden ist f\u00fcr die 69-j\u00e4hrige Frau an Bord des Seenotrettungsbootes HEILIGENHAFEN zu Ende gegangen. Die Freiwilligen-Besatzung der Deutschen Gesellschaft  zur Rettung Schiffbr\u00fcchiger (DGzRS) brachte die Seglerin nach einem  Herzinfarkt am gestrigen Sonntag, 21. Mai 2017, sicher an Land.<!--more-->  Unterst\u00fctzt wurden die Seenotretter bei diesem Einsatz von der  Bundespolizei. Gegen 15.10 Uhr erfuhren die Seenotretter von dem  medizinischen Notfall. Allerdings war die telefonisch \u00fcbermittelte  Positionsangabe der etwa zw\u00f6lf Meter langen Segelyacht nahe Fehmarn  unvollst\u00e4ndig. Zudem war das Boot zun\u00e4chst nicht mehr zu erreichen.  Deutlich geworden war jedoch, dass es sich um ein Fahrzeug mit blauem Rumpf handelte. \u00dcber den internationalen Sprechfunk-Notrufkanal 16  bat die SEENOTLEITUNG BREMEN der DGzRS deshalb die gesamte  Schifffahrt im Revier um Mithilfe. Eine Segelyacht meldete daraufhin  eine blaue Segelyacht etwa 1,5 Seemeilen westlich des Fl\u00fcgger  Leuchtturms. Die Seenotretter sandten die &#8222;Bayreuth&#8220; zu der  angegebenen Position. Das Einsatzschiff der Bundespolizei hatte seine Unterst\u00fctzung angeboten. Es konnte am schnellsten vor Ort sein. Der  Rettungshubschrauber &#8222;Christoph 12&#8220; des Bundesinnenministeriums  brachte einen Notarzt zum Liegeplatz der Seenotretter nach  Heiligenhafen. Die Freiwilligen-Besatzung des Seenotrettungsbootes  HEILIGENHAFEN nahm ihn an Bord und brachte ihn hinaus auf See.  Unterdessen hatte ein Sanit\u00e4tsteam der &#8222;Bayreuth&#8220; auf die Segelyacht  \u00fcbergesetzt,  die Patientin bei Bewusstsein vorgefunden und mit  Sauerstoff versorgt. Ebenfalls vor Ort war der Seenotrettungskreuzer  BREMEN der DGzRS. Die Seenotretter \u00fcbergaben den Notarzt auf die  Segelyacht. Er entschied, dass die HEILIGENAFEN die Frau an Land  bringen sollte. In Heiligenhafen \u00fcbergaben die Seenotretter die  69-J\u00e4hrige in die Obhut der Besatzung des Rettungshubschraubers, der  sie nach Neustadt i. H. flog.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/3641613\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Der Ostsee-T\u00f6rn eines Segler-Ehepaars aus den Niederlanden ist f\u00fcr die 69-j\u00e4hrige Frau an Bord des Seenotrettungsbootes HEILIGENHAFEN<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-255717","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/255717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=255717"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/255717\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=255717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=255717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=255717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}