{"id":256199,"date":"2017-10-18T13:07:38","date_gmt":"2017-10-18T13:07:38","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-oh-tesdorf-gemeinde-wangels-kreis-ostholstein-brand-einer-landwirtschaftlichen-lagerhalle-296\/"},"modified":"2017-10-18T13:07:38","modified_gmt":"2017-10-18T13:07:38","slug":"fw-oh-tesdorf-gemeinde-wangels-kreis-ostholstein-brand-einer-landwirtschaftlichen-lagerhalle-296","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-tesdorf-gemeinde-wangels-kreis-ostholstein-brand-einer-landwirtschaftlichen-lagerhalle-296\/","title":{"rendered":"FW-OH: Tesdorf, Gemeinde Wangels, Kreis Ostholstein: Brand einer landwirtschaftlichen Lagerhalle"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Foto: Hartmut Junge\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/ff0d5d46-37f0-4c45-adaa-7120d356d2d3\/image\" \/><\/p>\n<p>Lensahn (ots) &#8211;     Am gestrigen Dienstagabend (17.10.) wurde der Integrierten  Rettungsleitstelle S\u00fcd ein brennender Traktor in einer Lagerhalle  eines landwirtschaftlichen Betriebes \u00fcber Notruf gemeldet. Als die  Feuerwehr vor Ort eintraf brannte das Geb\u00e4ude bereits in voller  Ausdehnung.  In der Scheune waren \u00fcberwiegend Gro\u00dfmaschinen, Heu und  Stroh unterbracht waren.<!--more--> Die L\u00f6scharbeiten gestalteten sich zun\u00e4chst  schwierig, weil Wasser aus einer ca. 500m entfernten Wasserstelle  geholt werden musste. Deshalb wurden auch mehrere Tankl\u00f6schfahrzeuge  aus umliegenden Wehren zur Einsatzstelle alarmiert. ca. 125 Kr\u00e4fte  der Feuerwehren der Gemeinden Wangels, Sch\u00f6nwalde und Lensahn, sowie  aus Neustadt- und Oldenburg in Holstein und die Feuerwehtechnische  Zentrale des Kreises Ostholstein waren im Einsatz. Ebenfalls waren  eine Drehleiter im Einsatz. Die Einsatzkr\u00e4fte wurden von der  DRK-Bereitschaft G\u00f6hl mit Essen und Getr\u00e4nken versorgt.  Kreiswehrf\u00fchrer Thorsten Plath machte ebenfalls vor Ort ein Bild von  der Lage.     Nachdem das Feuer unter Kontrolle war, wurde das brennende Stroh  mit einem Bagger aus der Scheune geholt und aussen abgel\u00f6scht. Dazu  waren viele Atemschutzger\u00e4tetr\u00e4ger n\u00f6tig, die bis in den Vormittag  hinein nach und nach von umliegenden Feuerwehren aus den \u00c4mtern  Lensahn und Oldenburg Land nachalarmiert wurden.     Noch in der Nacht nahm die Kriminalpolizei ihre Arbeit an der  Einsatzstelle auf. Nachfragen zur Brandursache oder Schadensh\u00f6he sind zu richten an die Pressestelle der Polizeidirektion L\u00fcbeck.     Bilder honorarfrei unter Nennung der Quelle. Fotos: Hartmut Junge     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/3764478\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Am gestrigen Dienstagabend (17.10.) wurde der Integrierten Rettungsleitstelle S\u00fcd ein brennender Traktor in einer Lagerhalle eines landwirtschaftlichen<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-256199","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/256199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=256199"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/256199\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=256199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=256199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=256199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}