{"id":262932,"date":"2018-08-10T14:44:11","date_gmt":"2018-08-10T14:44:11","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/politik-wirtschaft\/brinkhaus-schrittweises-vorgehen-bei-kindergeldzahlungen-an-eu-auslaender-2\/"},"modified":"2018-08-10T14:44:11","modified_gmt":"2018-08-10T14:44:11","slug":"brinkhaus-schrittweises-vorgehen-bei-kindergeldzahlungen-an-eu-auslaender-2","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/brinkhaus-schrittweises-vorgehen-bei-kindergeldzahlungen-an-eu-auslaender-2\/","title":{"rendered":"Brinkhaus: Schrittweises Vorgehen bei Kindergeldzahlungen an EU-Ausl\u00e4nder"},"content":{"rendered":"<p>Berlin (ots) &#8211; Kurzfristig wichtig, Missbrauch weiter zu bek\u00e4mpfen     Die Kindergeldzahlungen an EU-Ausl\u00e4nder haben zugenommen. Dazu  erkl\u00e4rt der Stellvertretende Vorsitzende der CDU\/CSU-Fraktion im  Deutschen Bundestag Ralph Brinkhaus:     &#8222;Die Zahlung von Kindergeld ins EU-Ausland ist grunds\u00e4tzlich nicht zu beanstanden. Was aber zu Recht kritisiert wird, sind die  Missbrauchsf\u00e4lle.<!--more--> Hier m\u00fcssen wir konsequent und z\u00fcgig handeln.     Erste Ma\u00dfnahmen sind wir bereits in der letzten Legislaturperiode  angegangen: Wir haben die r\u00fcckwirkende Zahlung von Kindergeld  eingeschr\u00e4nkt &#8211; von vier Jahren auf sechs Monate. Au\u00dferdem haben wir  daf\u00fcr gesorgt, dass das Bundeszentralamt f\u00fcr Steuern k\u00fcnftig  schneller seine Erkenntnisse an die Familienkassen weiterreicht.  Dabei geht es um B\u00fcrger, die aus dem Melderegister abgemeldet wurden.     Trotzdem m\u00fcssen wir bei der Missbrauchsbek\u00e4mpfung noch effektiver  werden und nachlegen. Vor allem geh\u00f6rt die Zusammenarbeit der  Beh\u00f6rden auf allen Ebenen weiter verbessert. Hieran werden wir  arbeiten.     Ein weiterer Punkt, der auch von uns sehr kritisch gesehen wird:  Die H\u00f6he der deutschen Kindergeldzahlungen gerade f\u00fcr Kinder, die in  Ost- und S\u00fcdosteuropa leben, steht in keinem Verh\u00e4ltnis zu den  Lebenshaltungskosten in diesen Staaten. Deswegen m\u00fcssen wir die  Kindergeldzahlungen ins EU-Ausland dringend an die dortigen  Verh\u00e4ltnisse anpassen. Hierf\u00fcr sind \u00c4nderungen im europ\u00e4ischen Recht  n\u00f6tig. Bislang war es schwierig, daf\u00fcr eine Mehrheit in Br\u00fcssel zu  bekommen. Das ist f\u00fcr uns so nicht akzeptabel. Wir werden daher  weiter daran arbeiten, die erforderliche Unterst\u00fctzung f\u00fcr dieses  Projekt zu bekommen.&#8220;    Pressekontakt: CDU\/CSU &#8211; Bundestagsfraktion Pressestelle Telefon:  (030) 227-52360 Fax:      (030) 227-56660 Internet: http:\/\/www.cducsu.de Email: pressestelle@cducsu.de  Original-Content von: CDU\/CSU &#8211; Bundestagsfraktion, \u00fcbermittelt durch news aktuell<\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/pm\/7846\/4031665\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin (ots) &#8211; Kurzfristig wichtig, Missbrauch weiter zu bek\u00e4mpfen Die Kindergeldzahlungen an EU-Ausl\u00e4nder haben zugenommen. Dazu erkl\u00e4rt der Stellvertretende Vorsitzende<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[5],"tags":[],"class_list":["post-262932","post","type-post","status-publish","format-standard","hentry","category-politik-wirtschaft"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/262932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=262932"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/262932\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=262932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=262932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=262932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}