{"id":262959,"date":"2018-08-11T06:46:58","date_gmt":"2018-08-11T06:46:58","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/politik-wirtschaft\/parsons-bringt-schutzloesung-fuer-kritische-infrastruktur-auf-den-markt\/"},"modified":"2018-08-11T06:46:58","modified_gmt":"2018-08-11T06:46:58","slug":"parsons-bringt-schutzloesung-fuer-kritische-infrastruktur-auf-den-markt","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/parsons-bringt-schutzloesung-fuer-kritische-infrastruktur-auf-den-markt\/","title":{"rendered":"Parsons bringt Schutzl\u00f6sung f\u00fcr kritische Infrastruktur auf den Markt"},"content":{"rendered":"<p>Domain6 (TM)  integriert bew\u00e4hrte Technologien f\u00fcr Cybersecurity  und physischen Schutz     Pasadena, Kalifornien (ots\/PRNewswire) &#8211; Parsons hat heute ein  integriertes Portfolio von Technologien und Dienstleistungen auf den  Markt gebracht, das kritische Infrastruktur widerstandsf\u00e4hig macht  und vor sowohl Cyber- als auch physischen Bedrohungen sch\u00fctzt.<!--more-->  Domain6(TM) ist die weltweit erste vollst\u00e4ndig konvergente L\u00f6sung, um Angriffe auf Betriebstechnik (Operational Technology, OT) und  Informationstechnologie (IT) abzuwehren. Die im Domain6(TM) Portfolio vereinten Technologien bew\u00e4hren sich bereits im operativen Alltag der Parsons-Kunden, darunter staatliche Nachrichtendienste und  Verteidigungsbeh\u00f6rden der USA sowie gewerbliche Kundeneinrichtungen.     &#8222;Die technologiegest\u00fctzte Kapazit\u00e4t von Domain6(TM) beruht auf  drei strategischen Eckpfeilern &#8211; n\u00e4mlich die jahrzehntelange  Erfahrung von Parsons im Design und Aufbau von OT-Umgebungen, unsere  Investitionen in F&amp;E, und die Akquisition von einigen der weltweit  f\u00fchrenden Unternehmen f\u00fcr Cybersecurity und physischen Schutz&#8220;, sagt  Carey Smith, President des Gesch\u00e4ftsbereich Federal bei Parsons. &#8222;Der Kernwert von Domain6(TM) geht weit \u00fcber das gef\u00e4hrlich enge Modell  der IT-zentrierten aufgesetzten Software hinaus. Die Kunden von  Parsons in Nachrichtendiensten und Milit\u00e4r haben schon seit langem  eine konvergierte OT-IT-Infrastruktursicherheitsl\u00f6sung gefordert, mit Fokus auf die eskalierende Bedrohung von industriellen  Steuerungssystemen (Industrial Control Systems, ICS). Dies war mit  der wichtigste Ansporn f\u00fcr die Entwicklung von Domain6(TM)&#8220;.     Parsons verf\u00fcgt \u00fcber mehr als ein halbes Jahrhundert an Erfahrung  bei Konzeption, Entwicklung und Schutz kritischer Infrastrukturen f\u00fcr Kunden in den Bereichen Transport, Energie, Produktion, Wasser,  Chemie und weiteren Branchen sowie US-Milit\u00e4r und Nachrichtendienste. 2014 wurde das Unternehmen vom Maryland Procurement Office (MPO)  ausgew\u00e4hlt, um umfassende Beratungsleistungen zum cyber-physischen  Infrastrukturschutz an den Standorten des Kunden zu erbringen, an  denen die Kontinuit\u00e4t des Betriebs entscheidend ist. Im Jahr 2017  wurde das Modernisierungsprogramm MPO Industrial Controls System  (ICS) vom Office of the Director of National Intelligence (ODNI) mit  dem Preis f\u00fcr das beste Programm des Jahres f\u00fcr die Intelligence  Community ausgezeichnet. Die Dienstleistungen von Parsons f\u00fcr den  Schutz der Infrastruktur gegen sowohl Cyber- als auch physische  Bedrohungen waren wesentlicher Bestandteil der Konzeption und  Umsetzung des Programms.     Das Domain6(TM) Portfolio wurde mit einer eng an das vom National  Institute of Standards and Technologies herausgegebene  NIST-Cybersecurity-Framework angelehnten Grundlage &#8211; Identifizieren,  Sch\u00fctzen, Erkennen, Reagieren, Wiederherstellen &#8211; mit zahlreichen  propriet\u00e4ren Parsons-Technologien entwickelt, die in den Rahmen  eingebettet sind. Die Camelot-Technologie beispielsweise ist ein  einzigartiges Toolkit f\u00fcr defensive Cyber-Operationen, das die  Grundlage f\u00fcr die Priorisierung von Bedrohungen auf Basis einer  erweiterten Datenanalyse bildet. Camelot ist eine Parsons-Innovation, die sich aus als geheim eingestuften Cybersecurity-Operationen f\u00fcr  milit\u00e4rische Kunden herleitet.     Parsons hatte im Juni 2018 eine Umfrage  (https:\/\/www.parsons.com\/cipsurvey\/) unter Ingenieuren f\u00fcr  industrielle Steuerungssysteme in 15 kritischen  Infrastrukturbereichen ver\u00f6ffentlicht. Die Befragung ergab unter  anderem, dass fast 80% der ICS-Ingenieure, die f\u00fcr die Integration  von vernetzten IIoT-Ger\u00e4ten f\u00fcr das Industrial Internet of Things  verantwortlich sind, nicht besonders stark in die Planung und  Implementierung von Cyberschutzma\u00dfnahmen eingebunden werden.     &#8222;Domain6(TM) ist eine Technologieplattform, von der Parsons  glaubt, dass sie die Art und Weise, wie Eigent\u00fcmer und Betreiber  kritischer Infrastrukturen sowohl Cyber- als auch physischen  Bedrohungen begegnen und Risiken managen, revolutionieren wird&#8220;,  erkl\u00e4rt Carey Smith. &#8222;Unsere Botschaft an den Cybersecurity-Markt ist simpel: Parsons hat mehr Erfahrung bei Konzeption, Aufbau und Schutz  von Infrastrukturen als jedes andere Unternehmen der Welt. Die  OT-Umgebung, wo in den n\u00e4chsten Jahren buchst\u00e4blich Milliarden von  angeschlossenen, hackbaren Ger\u00e4ten im Industrial Internet of Things  hinzukommen werden, braucht genau diese Erfahrung&#8220;.     Parsons hat im Markt f\u00fcr CIP (Critical Infrastructure Protection)  im letzten Jahrzehnt strategisch zahlreiche f\u00fchrende Unternehmen f\u00fcr  Cybersecurity und physischen Schutz akquiriert, darunter:  &#8211; Polaris Alpha (Mai 2018) &#8211; K\u00fcnstliche Intelligenz und maschinelles    Lernen f\u00fcr die Cybersicherheit von kritischen Infrastrukturen.  &#8211; Williams Electric Company (Oktober 2017) &#8211; ICS und Integration f\u00fcr    kritische OT-Infrastrukturumgebungen.  &#8211; Secure Mission Solutions (April 2014) &#8211; Cybersecurity-, Netzwerk-    und Security Operations Center Management und    Informationssicherung.  &#8211; SPARTA, Inc. (November 2011) \u00ad- cybermissionskritische Technologien   und Dienstleistungen f\u00fcr industrielle, nationale und    nachrichtendienstliche Organisationen.      Weiterf\u00fchrende Information zu den CIP-Technologien von Parsons und zu Domain6(TM) finden Sie auf parsons.com\/domain6\/  (http:\/\/www.parsons.com\/domain6\/). Sie k\u00f6nnen sich auch gerne direkt  per E-Mail an uns wenden: domain6@parsons.com  (https:\/\/prnnj3-irisxe10.prnewswire.local\/ewebeditor\/).     Parsons ist ein Anbieter von digitalen L\u00f6sungen f\u00fcr die Bereiche  Verteidigung, Sicherheit und Infrastruktur. Mit rund 75 Jahren  Erfahrung ist Parsons einzigartig qualifiziert, um Cybersicherheit  und physischen Schutz, fortschrittliche Technologiel\u00f6sungen und  andere innovative Dienstleistungen f\u00fcr Bundes-, Regional- und  Kommunalbeh\u00f6rden und private Industriekunden weltweit zu  bereitzustellen. Weitere Informationen zu Parsons finden Sie unter   parsons.com (http:\/\/www.parsons.com\/). Folgen Sie uns auch auf   Facebook (https:\/\/www.facebook.com\/parsonscorporation),  Twitter  (https:\/\/twitter.com\/parsonscorp),  LinkedIn  (https:\/\/www.linkedin.com\/company\/parsons) und  YouTube  (https:\/\/www.youtube.com\/user\/ParsonsCorp).    Pressekontakt: Amber Thompson-Nadler +1 626.440.4590 amber.thompson-nadler@parsons.com  Original-Content von: Parsons, \u00fcbermittelt durch news aktuell<\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/pm\/130744\/4031870\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domain6 (TM) integriert bew\u00e4hrte Technologien f\u00fcr Cybersecurity und physischen Schutz Pasadena, Kalifornien (ots\/PRNewswire) &#8211; Parsons hat heute ein integriertes Portfolio<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[5],"tags":[],"class_list":["post-262959","post","type-post","status-publish","format-standard","hentry","category-politik-wirtschaft"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/262959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=262959"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/262959\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=262959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=262959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=262959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}