{"id":263000,"date":"2018-08-12T11:04:43","date_gmt":"2018-08-12T11:04:43","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/politik-wirtschaft\/motschmann-der-13-august-1961-darf-nie-vergessen-werden-anstrengungen-zur-erinnerungskultur-weiter-verstaerken\/"},"modified":"2018-08-12T11:04:43","modified_gmt":"2018-08-12T11:04:43","slug":"motschmann-der-13-august-1961-darf-nie-vergessen-werden-anstrengungen-zur-erinnerungskultur-weiter-verstaerken","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/motschmann-der-13-august-1961-darf-nie-vergessen-werden-anstrengungen-zur-erinnerungskultur-weiter-verstaerken\/","title":{"rendered":"Motschmann: Der 13. August 1961 darf nie vergessen werden &#8211; Anstrengungen zur Erinnerungskultur weiter verst\u00e4rken"},"content":{"rendered":"<p>Berlin (ots) &#8211; Am Montag j\u00e4hrt sich der Tag des Baus der Berliner  Mauer zum 57. Mal. Dazu erkl\u00e4rt die kultur- und medienpolitische  Sprecherin der CDU\/CSU-Bundestagsfraktion, Elisabeth Motschmann:      &#8222;Der Bau der Berliner Mauer war der sichtbarste Ausdruck des  SED-Unrechtsregimes.<!--more--> Daher bleibt der 13. August f\u00fcr die  CDU\/CSU-Bundestagsfraktion eine immerw\u00e4hrende Mahnung, an die  Einsperrung der ostdeutschen B\u00fcrger und die Repressionen durch den  Unterdr\u00fcckungsapparat der DDR zu erinnern. Wir gedenken der Opfer  dieser m\u00f6rderischen Grenze: Mindestens 327 Menschen sind an der  innerdeutschen Grenze get\u00f6tet worden; vier von f\u00fcnf Toten waren  j\u00fcnger als 35 Jahre.      Die Mauer ist heute schon l\u00e4nger Geschichte als sie brutale  Wirklichkeit gewesen ist. Umso wichtiger ist es, das  Geschichtsbewusstsein gerade der jungen Menschen zu st\u00e4rken. Daher  hat sich die Koalition auf Betreiben der CDU\/CSU-Fraktion im  Koalitionsvertrag das Programm &#8218;Jugend erinnert&#8216; vorgenommen. Es soll u. a. Gedenkst\u00e4ttenbesuche junger Menschen f\u00f6rdern und zur  Demokratiebildung beitragen. Wir begr\u00fc\u00dfen, dass Staatsministerin  Monika Gr\u00fctters daf\u00fcr in ihrem Haushalt f\u00fcr 2019 bereits 2 Millionen  Euro bereitgestellt hat. Wir werden uns f\u00fcr weitere Steigerungen  einsetzen.      Daneben ist es wichtig, sich an die gl\u00fccklichen Momente der  j\u00fcngsten deutschen Geschichte zu erinnern. In dieser Wahlperiode  werden wir die 30. Jahrestage der friedlichen Revolution 1989 und des Vollzugs der Deutschen Einheit in einem friedlichen Europa in  herausgehobener Weise w\u00fcrdigen. Dazu z\u00e4hlt auch das Freiheits- und  Einheitsdenkmal: Wir m\u00fcssen die &#8222;Waage&#8220; nun endlich bauen und keine  neuen fruchtlosen Standortdiskussionen vom Zaun brechen. Leider gibt  es noch kein Mahnmal zur Erinnerung an die Opfer kommunistischer  Gewaltherrschaft. Auch daf\u00fcr wird sich die Unionsfraktion mit  Nachdruck einsetzen.&#8220;    Pressekontakt: CDU\/CSU &#8211; Bundestagsfraktion Pressestelle Telefon:  (030) 227-52360 Fax:      (030) 227-56660 Internet: http:\/\/www.cducsu.de Email: pressestelle@cducsu.de  Original-Content von: CDU\/CSU &#8211; Bundestagsfraktion, \u00fcbermittelt durch news aktuell<\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/pm\/7846\/4032339\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin (ots) &#8211; Am Montag j\u00e4hrt sich der Tag des Baus der Berliner Mauer zum 57. Mal. Dazu erkl\u00e4rt die<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[5],"tags":[],"class_list":["post-263000","post","type-post","status-publish","format-standard","hentry","category-politik-wirtschaft"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/263000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=263000"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/263000\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=263000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=263000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=263000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}