{"id":264689,"date":"2018-04-26T16:34:07","date_gmt":"2018-04-26T16:34:07","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-bundespolizeischiff-bp-25-bayreuth-von-jungen-damen-geentert-180\/"},"modified":"2018-04-26T16:34:07","modified_gmt":"2018-04-26T16:34:07","slug":"bpoli-see-bundespolizeischiff-bp-25-bayreuth-von-jungen-damen-geentert-180","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-bundespolizeischiff-bp-25-bayreuth-von-jungen-damen-geentert-180\/","title":{"rendered":"BPOLI-See: Bundespolizeischiff BP 25 &#8222;Bayreuth&#8220; von jungen Damen geentert"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Wir gehen an Bord\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/8cd6bc26-73e1-4ba2-87de-beb2a08b9fef\/image\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Der letzte Donnerstag im April ist immer ein besonderer Tag, es  ist &#8222;Girls Day&#8220;! Insgesamt 13 M\u00e4dchen hatten sich \u00fcber die  Internetplattform, &#8222;Girls Day, M\u00e4dchen-Zukunftstag&#8220; bei der  Bundespolizeiinspektion See Neustadt in Holstein angemeldet. Der  abwechslungsreiche Beruf als &#8222;Bundespolizeibeamtin zur See&#8220; wurde  durch verschiedene Aktionen dargestellt.<!--more--> Auf dem Tagesprogramm stand  die Besichtigung eines Bundespolizeihubschraubers im Rahmen einer  Ostseeflugstreife, Einsatztraining und Knotenkunde. Anschlie\u00dfend  gingen die M\u00e4dchen an Bord des Bundespolizeischiffes BP 25 &#8222;Bayreuth&#8220; und konnten sich bei einer Fahrt auf der Ostsee einen Einblick in das Bordleben verschaffen. Der &#8222;Smut&#8220; zauberte f\u00fcr alle ein reichhaltiges Mittagessen! Das Ausschiffen erfolgte mit dem Kontrollboot in Form  einer rasanten Fahrt zur\u00fcck nach Neustadt. Der Einblick in das  Berufsfeld &#8222;Bundespolizeibeamtin&#8220; hat bei allen spannende Eindr\u00fccke  hinterlassen. Die Bundespolizei bietet eine fundierte Ausbildung und  gute Berufsperspektiven, mit stetig neuen Herausforderungen in  nationalen und internationalen Bereichen.     Seelig,POK`in     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/3928323\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Der letzte Donnerstag im April ist immer ein besonderer Tag, es ist &#8222;Girls Day&#8220;! Insgesamt 13 M\u00e4dchen<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-264689","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/264689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=264689"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/264689\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=264689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=264689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=264689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}