{"id":267451,"date":"2017-03-06T11:32:22","date_gmt":"2017-03-06T11:32:22","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-od-einladung-an-die-medien-kreisjugendfeuerwehrversammlung-der-stormarner-jugendfeuerwehren-1261\/"},"modified":"2017-03-06T11:32:22","modified_gmt":"2017-03-06T11:32:22","slug":"fw-od-einladung-an-die-medien-kreisjugendfeuerwehrversammlung-der-stormarner-jugendfeuerwehren-1261","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-od-einladung-an-die-medien-kreisjugendfeuerwehrversammlung-der-stormarner-jugendfeuerwehren-1261\/","title":{"rendered":"FW-OD: Einladung an die Medien: \nKreisjugendfeuerwehrversammlung der Stormarner Jugendfeuerwehren"},"content":{"rendered":"<p>Travenbr\u00fcck (ots) &#8211; Die Delegierten der 39 Stormarner  Jugendfeuerwehren kommen am Sonnabend, den 11.03.2017 um 10:30 Uhr im Sch\u00fctzen- und Gemeinschaftshaus Klein Wesenberg zusammen, um ihre  Delegiertenversammlung abzuhalten.<!--more-->     Viel Spannung versprechen die anstehenden Wahlen des\/der  Kreisjugendfeuerwehrwart_in, des\/der Fachbereichsleiter_in  Wettbewerbe, Ausbildung, Presse- und \u00d6ffentlichkeitsarbeit sowie  des\/der Kreisjugendgruppenleiter_in. Traditionell werden auch wieder  Kameraden f\u00fcr ihre herausragenden Leistungen im Bereich der  Jugendfeuerwehr geehrt.     Als G\u00e4ste werden neben dem Kreiswehrf\u00fchrer Gerd Riemann unter  anderem auch Kreispr\u00e4sident Hans-Werner Harmuth erwartet.     Traditionell wird die neue Ausgabe vom Funkenflug &#8211; dem  Jahresmagazin der Stormarner Jugendfeuerwehren &#8211; ausgegeben.     Zu dieser Veranstaltung sind Vertreter der Medien herzlich  eingeladen.  Wo:     Sch\u00fctzen- und Gemeinschaftshaus Klein Wesenberg, Reeker Weg \/ Am Kirchberg, 23860 Klein Wesenberg Wann: \tSonnabend, 11.03.2017 um 10:30 Uhr     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68032\/3577212\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Travenbr\u00fcck (ots) &#8211; Die Delegierten der 39 Stormarner Jugendfeuerwehren kommen am Sonnabend, den 11.03.2017 um 10:30 Uhr im Sch\u00fctzen- und<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-267451","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/267451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=267451"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/267451\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=267451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=267451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=267451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}