{"id":273746,"date":"2018-08-08T20:00:00","date_gmt":"2018-08-08T20:00:00","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-rz-feuerwehr-leistungsfahrt-des-kreisfeuerwehrverbandes-herzogtum-lauenburg-am-01-09-2018-321\/"},"modified":"2018-08-08T20:00:00","modified_gmt":"2018-08-08T20:00:00","slug":"fw-rz-feuerwehr-leistungsfahrt-des-kreisfeuerwehrverbandes-herzogtum-lauenburg-am-01-09-2018-321","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-feuerwehr-leistungsfahrt-des-kreisfeuerwehrverbandes-herzogtum-lauenburg-am-01-09-2018-321\/","title":{"rendered":"FW-RZ: Feuerwehr-Leistungsfahrt des Kreisfeuerwehrverbandes Herzogtum Lauenburg am 01.09.2018"},"content":{"rendered":"<p>Ratzeburg (ots) &#8211; Am 01. September 2018 findet auf dem  \u00dcbungsgel\u00e4nde der Bundespolizei in B\u00fcchen erneut die j\u00e4hrliche  Feuerwehr-Leistungsfahrt des Kreisfeuerwehrverbandes Herzogtum  Lauenburg statt.<!--more--> Der Gemeindewehrf\u00fchrer J\u00fcrgen Lempges sowie die  Kameradinnen und Kameraden der Freiwilligen Feuerwehr B\u00fcchen  unterst\u00fctzen den Kreisfeuerwehrverband durch den  Auf- und Abbau des  gesamten Parcours.     Ab 11.30 Uhr starteten die Mannschaften -unter Ihnen auch  Mannschaften der befreundeten Organisationen in sechs Klassen. Neben  den altbekannten Klassen Klein-, Mittel-, Gro\u00df- und Sonderfahrzeugen  k\u00f6nnen auch die Jugendfeuerwehren unter Leitung der Jugendwartung  oder einer Bereuungsperson teilnehmen. Diese Gruppe wird  erfreulicherweise zunehmend gr\u00f6\u00dfer.     Nach einer umfassenden Funktionskontrolle der Fahrzeuge, beginnt  der Parcours mit den unterschiedlichsten Aufgaben. Neben der  Geschicklichkeit des Fahrers ist auch Teamarbeit gefragt. Wenn  beispielsweise das Fahrzeug mit abgedeckten Au\u00dfenspiegeln eine  R\u00fcckw\u00e4rtsgasse passieren muss, ist der Fahrer auf seinen Einweiser  angewiesen. Weiterhin m\u00fcssen feuerwehrtechnische Fragen beantwortet  werden, ein L\u00f6schangriff nach Dienstvorschrift ist abzuarbeiten und  die unterschiedlichsten Ger\u00e4tschaften der Fahrzeuge werden  vorgef\u00fchrt.     Da f\u00fcr die abschlie\u00dfende Gesamtwertung nicht nur das erfolgreiche  Absolvieren des Parcours mit allen Aufgaben entscheiden ist, sondern  auch die Zeit gestoppt wird, bietet sich den Zuschauern auch in  diesem Jahr sicher wieder die ein oder andere spannende Szene. Die  abschlie\u00dfende Siegerehrung erfolgt gegen 15.00 Uhr.     Die Kameradinnen und Kameraden der Freiwilligen Feuerwehr B\u00fcchen  sorgen zusammen mit ihren Angeh\u00f6rigen wieder f\u00fcr ein umfangreiches  Speisensortiment zu sehr attraktiven Preisen, so gibt es neben kalten Getr\u00e4nken, Grillwurst und -fleisch auch Kaffee und selbstgebackene  Kuchen und Torten.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68033\/4029865\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Am 01. September 2018 findet auf dem \u00dcbungsgel\u00e4nde der Bundespolizei in B\u00fcchen erneut die j\u00e4hrliche Feuerwehr-Leistungsfahrt des<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-273746","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/273746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=273746"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/273746\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=273746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=273746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=273746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}