{"id":274262,"date":"2018-08-27T11:13:24","date_gmt":"2018-08-27T11:13:24","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-rz-absage-feuerwehr-leistungsfahrt-in-buechen-am-01-09-2018-323\/"},"modified":"2018-08-27T11:13:24","modified_gmt":"2018-08-27T11:13:24","slug":"fw-rz-absage-feuerwehr-leistungsfahrt-in-buechen-am-01-09-2018-323","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-absage-feuerwehr-leistungsfahrt-in-buechen-am-01-09-2018-323\/","title":{"rendered":"FW-RZ: Absage Feuerwehr-Leistungsfahrt in B\u00fcchen am 01.09.2018 !"},"content":{"rendered":"<p>Ratzeburg (ots) &#8211; Der Kreisfeuerwehrverband Herzogtum Lauenburg  und die Ortswehrf\u00fchrung B\u00fcchen sehen sich leider gezwungen aufgrund  einer zu geringen Anzahl an Anmeldungen die Feuerwehr-Leistungsfahrt  am 01. September 2018 abzusagen.<!--more--> Der &#8211; insbesondere durch die  Kameradinnen und Kameraden der Freiwilligen Feuerwehr B\u00fcchen &#8211; zu  betreibende Aufwand steht in keiner Relation zu den eingegangenen  Anmeldungen.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68033\/4044708\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Der Kreisfeuerwehrverband Herzogtum Lauenburg und die Ortswehrf\u00fchrung B\u00fcchen sehen sich leider gezwungen aufgrund einer zu geringen Anzahl<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-274262","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/274262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=274262"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/274262\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=274262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=274262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=274262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}