{"id":275698,"date":"2018-08-27T16:57:30","date_gmt":"2018-08-27T16:57:30","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-rz-gefahrstoffaustritt-in-lauenburg-472\/"},"modified":"2018-08-27T16:57:30","modified_gmt":"2018-08-27T16:57:30","slug":"fw-rz-gefahrstoffaustritt-in-lauenburg-472","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-gefahrstoffaustritt-in-lauenburg-472\/","title":{"rendered":"FW-RZ: Gefahrstoffaustritt in Lauenburg"},"content":{"rendered":"<p>Ratzeburg (ots) &#8211; Gegen 15 Uhr wurde in einem chemieverarbeitenden Betrieb in Lauenburg ein Austritt von Thermal\u00f6l festgestellt. Die  alarmierten Einsatzkr\u00e4fte bestehend aus diversen Feuerwehren, dem  L\u00f6schzug-Gefahrgut, der Technischen Einsatzleitung sowie dem  Rettungsdienst des Kreises Herzogtum Lauenburg sind zur Zeit mit  einem Gro\u00dfaufgebot an Kr\u00e4ften vor Ort.<!--more--> Es gibt keine Verletzten, die  Lage ist unter Kontrolle. F\u00fcr die Bev\u00f6lkerung besteht keine Gefahr.  Durch die Einsatzkr\u00e4fte wurde die Leckage bereits abgedichtet.  Weitere Ma\u00dfnahmen an der Einsatzstelle werden zurzeit mit der  Einsatzleitung vor Ort besprochen.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68033\/4045399\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Gegen 15 Uhr wurde in einem chemieverarbeitenden Betrieb in Lauenburg ein Austritt von Thermal\u00f6l festgestellt. Die alarmierten<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-275698","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/275698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=275698"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/275698\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=275698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=275698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=275698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}