{"id":277772,"date":"2018-10-31T09:00:05","date_gmt":"2018-10-31T09:00:05","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-sl-tag-der-offenen-tuer-und-informationsveranstaltung-zur-gruendung-einer-jugendfeuerwehr-292\/"},"modified":"2018-10-31T09:00:05","modified_gmt":"2018-10-31T09:00:05","slug":"fw-sl-tag-der-offenen-tuer-und-informationsveranstaltung-zur-gruendung-einer-jugendfeuerwehr-292","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-sl-tag-der-offenen-tuer-und-informationsveranstaltung-zur-gruendung-einer-jugendfeuerwehr-292\/","title":{"rendered":"FW-SL: Tag der offenen T\u00fcr und Informationsveranstaltung zur Gr\u00fcndung einer Jugendfeuerwehr"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Werbeplakat zum Tag der offenen T\u00fcr der FF Hollingstedt\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/c83dd6e0-48c3-4595-ac3a-cafe9462d10e\/IMG_2861.jpg\" \/><\/p>\n<p>Schleswig (ots) &#8211;     Die Feuerwehr Hollingstedt veranstaltet am 10.11.2018 einen Tag  der offenen T\u00fcr. Neben dem gro\u00dfen Augenmerk Mitgliederwerbung f\u00fcr  Mitglieder der Einsatzabteilung, m\u00f6chten die Kameradinnen und  Kameraden Werbung f\u00fcr die Jugendfeuerwehr machen.<!--more-->     Im Jahr 2019 m\u00f6chten sie in Hollingstedt die 36. Jugendfeuerwehr  im Kreisgebiet gr\u00fcnden und suchen daf\u00fcr nat\u00fcrlich auch nach  Jugendlichen ab 10 Jahren, die bereit sind sich in der  Jugendfeuerwehr zu engagieren.     Die Jugendfeuerwehr J\u00fcbek ist ebenfalls vor Ort und zeigt den  Kindern und Jugendlichen was sie in der Jugendfeuerwehr erwartet.  Mehrmals am Tag gibt es Vorf\u00fchrungen der jungen Kameradinnen und  Kameraden.     F\u00fcr Fragen steht Wehrf\u00fchrer Michael Grindt unter 04627 \/ 18 98 35  oder fernsehgirndt@t-online.de gerne zur Verf\u00fcgung.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68035\/4102603\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schleswig (ots) &#8211; Die Feuerwehr Hollingstedt veranstaltet am 10.11.2018 einen Tag der offenen T\u00fcr. Neben dem gro\u00dfen Augenmerk Mitgliederwerbung f\u00fcr<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-277772","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/277772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=277772"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/277772\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=277772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=277772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=277772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}