{"id":280850,"date":"2019-02-20T14:09:12","date_gmt":"2019-02-20T14:09:12","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bka-russian-laundromatstaatsanwaltschaft-muenchen-i-und-bundeskriminalamtbeschlagnahmen-50-mio-euro-wegen-geldwaesche-62\/"},"modified":"2019-02-20T14:09:12","modified_gmt":"2019-02-20T14:09:12","slug":"bka-russian-laundromatstaatsanwaltschaft-muenchen-i-und-bundeskriminalamtbeschlagnahmen-50-mio-euro-wegen-geldwaesche-62","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bka-russian-laundromatstaatsanwaltschaft-muenchen-i-und-bundeskriminalamtbeschlagnahmen-50-mio-euro-wegen-geldwaesche-62\/","title":{"rendered":"BKA: &#8222;Russian Laundromat&#8220;:\nStaatsanwaltschaft M\u00fcnchen I und Bundeskriminalamt\nbeschlagnahmen 50 Mio. Euro wegen Geldw\u00e4sche"},"content":{"rendered":"<p>Wiesbaden (ots) &#8211; Seit drei Jahren ermittelt das Bundeskriminalamt im Auftrag der Staatsanwaltschaft M\u00fcnchen I wegen des Verdachts der  Geldw\u00e4sche gegen insgesamt drei Beschuldigte. Ab 18.02.2019 erfolgte  die gleichzeitige Beschlagnahme von vier Immobilien in Schwalbach am  Taunus, N\u00fcrnberg, Regensburg und M\u00fchldorf am Inn im Gesamtwert von  rund 40 Millionen Euro.<!--more--> Daneben wurde ein Konto bei einer Bank in  Lettland mit einem erwarteten Guthaben in H\u00f6he von ca. 1,2 Millionen  Euro beschlagnahmt, welches aus der Ver\u00e4u\u00dferung einer weiteren  Immobilie in Chemnitz herr\u00fchrt. Zus\u00e4tzlich wurde die vorl\u00e4ufige  Sicherung von Kontoguthaben bei diversen Banken in Deutschland auf  der Grundlage von Verm\u00f6gensarresten in H\u00f6he von ca. 6,7 Millionen  Euro bei zwei beteiligten Immobiliengesellschaften in Deutschland  veranlasst.     Die Staatsanwaltschaft M\u00fcnchen I geht nach ihren bisherigen  Ermittlungen davon aus, dass die in hochwertige Immobilien  investierten Verm\u00f6genswerte aus Ertr\u00e4gen von Geldw\u00e4schehandlungen im  Zusammenhang mit dem sogenannten Russian Laundromat stammen. Dabei  handelt es sich um eine kriminelle Gruppierung um einen ehemaligen  leitenden Angestellten der im Jahr 2016 von der Bankenaufsicht in  Lettland abgewickelten AS Trasta Komercbanka, sowie aus dessen  zahlreichen f\u00fcr die Taten verwendeten Briefkastengesellschaften und  eigens daf\u00fcr eingerichteten Bankkonten.     F\u00fcr das als &#8222;non-resident banking&#8220; bezeichnete Gesch\u00e4ft wurden  tausende Briefkastengesellschaften vorgehalten und hunderte  Bankkonten in Lettland im Rahmen der Tathandlungen verwendet. In den  Jahren 2011 bis 2014 erwirtschaftete die Gruppierung nach derzeitigen Erkenntnissen mit den Geldw\u00e4schehandlungen \u00fcber 100 Millionen  US-Dollar sogenannte Schattengeb\u00fchren, die im Rahmen von unz\u00e4hligen  Tathandlungen meist von russischen Auftraggebern erhoben wurden.  Insgesamt wurden Gelder im Wert von \u00fcber 22 Milliarden US-Dollar von  ca. 20 russischen Banken \u00fcber Banken in Moldau und Lettland  transferiert.     Die Ermittlungsgruppe des Bundeskriminalamtes Wiesbaden  kooperierte drei Jahre lang im Auftrag der Staatsanwaltschaft M\u00fcnchen I eng mit Fahndern des Zollfahndungsamts Berlin-Brandenburg,  Dienstsitz Frankfurt (Oder), und spezialisierten Ermittlern der  Abteilung Wirtschaftskriminalit\u00e4t bei der Staatspolizei in Riga.     Presseausk\u00fcnfte erteilt die Staatsanwaltschaft M\u00fcnchen I Tel.: 089\/5597-4792 Fax: 089\/5597-5536 PRESSESTELLE@sta-m1.bayern.de  Original-Content von: Bundeskriminalamt, \u00fcbermittelt durch news aktuell<\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/7\/4198575\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wiesbaden (ots) &#8211; Seit drei Jahren ermittelt das Bundeskriminalamt im Auftrag der Staatsanwaltschaft M\u00fcnchen I wegen des Verdachts der Geldw\u00e4sche<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-280850","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/280850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=280850"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/280850\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=280850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=280850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=280850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}