{"id":280872,"date":"2019-01-10T05:33:28","date_gmt":"2019-01-10T05:33:28","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-rz-grossfeuer-in-einem-kombinierten-wohn-und-wirtschaftsgebaeude-in-muehlenrade-124\/"},"modified":"2019-01-10T05:33:28","modified_gmt":"2019-01-10T05:33:28","slug":"fw-rz-grossfeuer-in-einem-kombinierten-wohn-und-wirtschaftsgebaeude-in-muehlenrade-124","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-rz-grossfeuer-in-einem-kombinierten-wohn-und-wirtschaftsgebaeude-in-muehlenrade-124\/","title":{"rendered":"FW-RZ: Gro\u00dffeuer in einem kombinierten Wohn- und Wirtschaftsgeb\u00e4ude, in M\u00fchlenrade"},"content":{"rendered":"<p>Ratzeburg (ots) &#8211; Kreis Herzogtum Lauenburg \/ Donnerstag \/  10.01.2019     Am 10.01.2019 wurde gegen 0:45 Uhr ein Feuer in einem  landwirtschaftlichen Wohn- und Wirtschaftsgeb\u00e4ude, in M\u00fchlenrade  gemeldet. Auf Grund der Gr\u00f6\u00dfe des etwa 100 Jahre alten Geb\u00e4udes wurde rasch bis zum Alarmstichwort &#8222;Feuer 5&#8220; erh\u00f6ht.<!--more--> Die Bewohner konnten  sich zu Anfang rechtzeitig und unverletzt in Sicherheit bringen,  jedoch kamen zahlreiche Rinder bei dem Brand ums Leben. Letzten  Zahlen zur Folge handelte es sich zuletzt um ca. 30 Rinder. Etwa die  H\u00e4lfte wurde noch w\u00e4hrend des Einsatzes geborgen und man muss davon  ausgehe, dass die \u00fcbrigen Tiere ebenfalls nicht \u00fcberlebt haben.  Weitere rund 30 Tiere konnten rechtzeitig gerettet werden und wurden  auf umliegende Weidefl\u00e4chen in Sicherheit gebracht. Rund 150  Einsatzkr\u00e4fte aus Feuerwehr, Rettungsdienst und Polizei waren bis in  die fr\u00fchen Morgenstunden im Einsatz, um den Brand unter Kontrolle zu  bringen. W\u00e4hrend des gesamten Einsatzes war die Ortsdurhfahrt  M\u00fchlenrade voll gesperrt.Die H\u00f6he des entstandenen Sachschadens und  die Brandursache stehen zur Stunde noch nicht fest. Die Polizei hat  die Ermittlungen aufgenommen.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68033\/4161983\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (ots) &#8211; Kreis Herzogtum Lauenburg \/ Donnerstag \/ 10.01.2019 Am 10.01.2019 wurde gegen 0:45 Uhr ein Feuer in einem<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-280872","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/280872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=280872"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/280872\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=280872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=280872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=280872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}