{"id":281338,"date":"2019-02-27T13:24:24","date_gmt":"2019-02-27T13:24:24","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/lka-sh-wir-bringen-wieder-licht-ins-dunkel-lka-startet-dritte-befragung-zu-sicherheit-und-kriminalitaet-51\/"},"modified":"2019-02-27T13:24:24","modified_gmt":"2019-02-27T13:24:24","slug":"lka-sh-wir-bringen-wieder-licht-ins-dunkel-lka-startet-dritte-befragung-zu-sicherheit-und-kriminalitaet-51","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/lka-sh-wir-bringen-wieder-licht-ins-dunkel-lka-startet-dritte-befragung-zu-sicherheit-und-kriminalitaet-51\/","title":{"rendered":"LKA-SH: Wir bringen wieder Licht ins Dunkel: LKA startet dritte Befragung zu Sicherheit und Kriminalit\u00e4t"},"content":{"rendered":"<p>Kiel (ots) &#8211; Das Landeskriminalamt Schleswig-Holstein (LKA)  startet Anfang M\u00e4rz mit der dritten &#8222;Befragung zu Sicherheit und  Kriminalit\u00e4t in Schleswig-Holstein&#8220;.<!--more-->  Die Beh\u00f6rde f\u00fchrt damit die  repr\u00e4sentative Dunkelfeldstudie aus den Jahren 2015 und 2017 fort,  f\u00fcr die B\u00fcrgerinnen und B\u00fcrger aus Schleswig-Holstein anonym zu  Bereichen wie Opfererfahrung, Anzeigeverhalten, Kriminalit\u00e4tsfurcht,  Wahrnehmung und Bewertung der Polizeiarbeit befragt worden sind. Ziel der Umfrage ist es, Erkenntnisse aus dem Dunkelfeld zu gewinnen und  diese f\u00fcr eine noch gezieltere Kriminalit\u00e4tsbek\u00e4mpfung zu nutzen.     Dazu hat das LKA in den vergangenen Tagen Ank\u00fcndigungsschreiben an 25 000 Menschen ab 16 Jahren, die nach dem Zufallsprinzip aus den  Melderegistern der schleswig-holsteinischen Gemeinden ausgew\u00e4hlt  worden sind. Das Schreiben informiert \u00fcber die bevorstehende Umfrage  und ihren Hintergrund. Ihm folgt Anfang  M\u00e4rz ein 20-seitiger  Fragebogen mit 59 Fragen zu verschiedenen Komplexen wie  &#8222;Kriminalit\u00e4tsfurcht&#8220; oder &#8222;Kriminalit\u00e4tsbelastung&#8220;. Die Teilnehmer  haben vier Wochen Zeit, um die Fragen zu beantworten. Die Teilnahme  ist freiwillig.     &#8222;Durch die Ergebnisse der Dunkelfeldstudien 2015 und 2017 hat die  Polizei viele Erkenntnisse \u00fcber das Sicherheitsgef\u00fchl und die  Wahrnehmung der polizeilichen Arbeit durch die B\u00fcrgerinnen und B\u00fcrger Schleswig-Holsteins erhalten,&#8220; sagt Stephan Nietz, der St\u00e4ndige  Vertreter der Amtsleitung des Landeskriminalamtes und  Projektverantwortliche. &#8222;Diese dritte Studie erlaubt uns,  Ver\u00e4nderungen \u00fcber einen  langen Zeitraum zu bewerten und das  polizeiliche Handeln daran zu orientieren.&#8220;     Auch Dr. Lars Riesner, Diplompsychologe und Kriminologe im LKA,  verweist auf die gro\u00dfe Bedeutung der Fortschreibung: &#8222;Entsprechende  Untersuchungen sind die einzige M\u00f6glichkeit, um festzustellen, wie  viele welcher Straftaten tats\u00e4chlich geschehen. Und auch die Furcht  vor Kriminalit\u00e4t in der Bev\u00f6lkerung ist eine wichtige Gr\u00f6\u00dfe, die  zeitlichen Ver\u00e4nderungen unterliegen kann.&#8220;     Der R\u00fccklauf der zweiten Dunkelfeldstudie war 2017 mit 11614  ausgef\u00fcllten Frageb\u00f6gen sehr hoch. Die Ergebnisse zeigten, dass die  Furcht vor Kriminalit\u00e4t bei den Schleswig-Holsteinern im Zeitraum der vergangenen zwei Jahre leicht bis moderat angestiegen ist, sie sich  aber nach wie vor sicher f\u00fchlen.     Die Bewertung der Polizei im Allgemeinen fiel insgesamt positiv  aus und hat sich in nahezu allen untersuchten Aspekten von 2015 auf  2017 verbessert. Schleswig-Holsteiner, die Kontakt zu Polizei hatten, haben diese zunehmend als \u00fcberlastet wahrgenommen. Insgesamt  bewerteten die B\u00fcrgerinnen und B\u00fcrger die erlebten Polizeikontakte  weiterhin \u00fcberwiegend als positiv.     Zus\u00e4tzlich zu den Kernfragen hat das LKA in 2017 vertiefend nach  vorurteilsmotivierter Kriminalit\u00e4t gefragt. Hierbei geht es um  Straftaten, die gezielt gegen Personen aufgrund ihrer sozialen  Gruppenzugeh\u00f6rigkeit gerichtet sind. Dies k\u00f6nnen beispielsweise  Hautfarbe, religi\u00f6ser Glaube oder sexuelle Orientierung sein. Die  Ergebnisse zu diesem Sondermodul werden in K\u00fcrze vorgestellt.  Aufgrund der hohen gesellschaftlichen Relevanz beleuchtet das LKA in  der nun startenden Dunkelfeldstudie f\u00fcr 2019 das Thema erneut.     F\u00fcr R\u00fcckfragen und weitere Informationen ist ab sofort bis zum 05. April ein B\u00fcrgertelefon eingerichtet, das montags bis freitags von  9:30 Uhr bis 18 Uhr unter  0431\/160-4949 zu erreichen ist.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/2256\/4204776\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kiel (ots) &#8211; Das Landeskriminalamt Schleswig-Holstein (LKA) startet Anfang M\u00e4rz mit der dritten &#8222;Befragung zu Sicherheit und Kriminalit\u00e4t in Schleswig-Holstein&#8220;.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-281338","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/281338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=281338"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/281338\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=281338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=281338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=281338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}