{"id":284224,"date":"2018-10-25T16:18:23","date_gmt":"2018-10-25T16:18:23","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/fw-oh-presseeinladung-zur-grossuebung-feuerwehr-polizei-rettungsdienst-hilfsorganisationen-in-neustadt-in-holstein-keine-veroeffentlichung-285\/"},"modified":"2018-10-25T16:18:23","modified_gmt":"2018-10-25T16:18:23","slug":"fw-oh-presseeinladung-zur-grossuebung-feuerwehr-polizei-rettungsdienst-hilfsorganisationen-in-neustadt-in-holstein-keine-veroeffentlichung-285","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-presseeinladung-zur-grossuebung-feuerwehr-polizei-rettungsdienst-hilfsorganisationen-in-neustadt-in-holstein-keine-veroeffentlichung-285\/","title":{"rendered":"FW-OH: Presseeinladung zur Gro\u00df\u00fcbung Feuerwehr\/Polizei\/Rettungsdienst\/Hilfsorganisationen in Neustadt in Holstein -KEINE VER\u00d6FFENTLICHUNG!-"},"content":{"rendered":"<p>Lensahn (ots) &#8211; Presseeinladung NICHT ZUR VER\u00d6FFENTLICHUNG!!!     Am Freitag, 26.10.2018 findet in der Innenstadt von Neustadt in  Holstein eine Gro\u00df\u00fcbung der Feuerwehr, des Rettungsdienstes, der  Polizei und weiterer Hilfsorganisationen statt. Es wird das Szenario  eines Massenanfalls von Verletzten\/Betroffenen ge\u00fcbt.<!--more--> Dazu wird der  Neust\u00e4dter Innenstadtbereich am Freitagabend weitr\u00e4umig gesperrt.     Um den interessierten Journalisten die M\u00f6glichkeit einer Teilnahme und &#8222;hautnaher&#8220; Berichterstattung zu erm\u00f6glichen, steht ein  Presseteam des Kreisfeuerwehrverbandes Ostholstein und der  Polizeidirektion L\u00fcbeck f\u00fcr Sie bereit.     Treffpunkt f\u00fcr Pressevertreter ist um 18.00 Uhr an der  Rathaustreppe auf dem Neust\u00e4dter Marktplatz. Also genau in dem  Bereich, wo auch sp\u00e4ter das eigentliche \u00dcbungsszenario abl\u00e4uft.  Ansprechpartner sind dort Hartmut Junge vom Kreisfeuerwehrverband  Ostholstein sowie Stefan Muhtz von der Polizeidirektion L\u00fcbeck, die  vor- und w\u00e4hrend der \u00dcbung f\u00fcr Fragen rund um das Einsatzgeschehen  zur Verf\u00fcgung stehen. W\u00e4hrend der \u00dcbung selbst haben Sie auch die  M\u00f6glichkeit, die von der &#8222;Einsatzleitung&#8220; eingesetzten Pressesprecher zu interviewen und auch dort ggf. O-T\u00f6ne aufzunehmen.     Bitte machen Sie sich an der \u00dcbungsstelle als Pressevertreter  kenntlich, z.B. &#8222;gr\u00fcne Weste&#8220;, Presseausweis usw.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/56143\/4098288\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Presseeinladung NICHT ZUR VER\u00d6FFENTLICHUNG!!! Am Freitag, 26.10.2018 findet in der Innenstadt von Neustadt in Holstein eine Gro\u00df\u00fcbung<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-284224","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/284224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=284224"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/284224\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=284224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=284224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=284224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}