{"id":286133,"date":"2018-12-04T12:22:22","date_gmt":"2018-12-04T12:22:22","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bpoli-see-abschluss-charity-projekt-2018scheckuebergabe-an-das-kinderzentrum-pelzerhaken-353\/"},"modified":"2018-12-04T12:22:22","modified_gmt":"2018-12-04T12:22:22","slug":"bpoli-see-abschluss-charity-projekt-2018scheckuebergabe-an-das-kinderzentrum-pelzerhaken-353","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-abschluss-charity-projekt-2018scheckuebergabe-an-das-kinderzentrum-pelzerhaken-353\/","title":{"rendered":"BPOLI-See: Abschluss Charity- Projekt 2018\n\nScheck\u00fcbergabe an das Kinderzentrum Pelzerhaken"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Hier ist das Spendengeld gut aufgehoben...\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/207588f1-833a-45ac-ae8a-a5dd619706af\/DSC_3874.JPG\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Mit der Scheck\u00fcbergabe am Montag endete f\u00fcr die  Bundespolizeiinspektion See Neustadt in Holstein das Charity- Projekt 2018. Im Rahmen einer Vielzahl von Veranstaltungen wurde &#8222;f\u00fcr einen  guten Zweck&#8220; gesammelt.<!--more--> Gr\u00f6\u00dfte Einnahmequelle war auch in diesem Jahr der &#8222;9.Tag der K\u00dcSTENWACHE&#8220;; hier nochmals einen Dank an alle Aktiven aus dem Standort Neustadt sowie unseren Partnern, die zum Gelingen  der Veranstaltung beigetragen haben. Insgesamt konnte ein Betrag von  4.639,05 EUR an das Kinderzentrum Pelzerhaken \u00fcbergeben werden. Dass  das Geld hier gut angelegt ist, davon konnten wir uns bereits im  vergangenen Jahr \u00fcberzeugen. Die Anschaffung eines therapeutischen  Laufbandes ist damit in greifbare N\u00e4he ger\u00fcckt.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/4133907\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Mit der Scheck\u00fcbergabe am Montag endete f\u00fcr die Bundespolizeiinspektion See Neustadt in Holstein das Charity- Projekt 2018.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-286133","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/286133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=286133"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/286133\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=286133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=286133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=286133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}